{"id":628406,"date":"2018-01-28T12:23:00","date_gmt":"2018-01-28T10:23:00","guid":{"rendered":"http:\/\/devrri.freshlemon.ro\/aktuell\/ao-finale-halep-unterliegt-wozniacki-id628406.html"},"modified":"2018-01-28T12:23:00","modified_gmt":"2018-01-28T10:23:00","slug":"ao-finale-halep-unterliegt-wozniacki","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html","title":{"rendered":"AO-Finale: Halep unterliegt Wozniacki"},"content":{"rendered":"<p align=justify>Ich habe geweint, aber jetzt kann ich l\u00e4cheln! &#8211; So fasste die Tennisspielerin Simona Halep ihre Emotionen bei der Pressekonferenz nach dem Spiel in Melbourne zusammen. Im Finale der Australian Open 2018 angekommen, unterlag die Rum\u00e4nin Caroline Wozniacki mit 6:7, 6:3 und 4:6. Damit verpasst die 26-J\u00e4hrige zum bereits dritten Mal die Chance auf ihren ersten Grand-Slam-Titel. Zuvor war sie zweimal bei den French Open gescheitert, 2014 gegen Maria Scharapowa und 2017 gegen Jelena Ostapenko.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p align=justify>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p align=justify>Doch auch f\u00fcr ihre Gegnerin war enorm viel auf dem Spiel: Caroline ist seit Samstag nach zwei ihrerseits verlorenen Endspielen im Besitz der ersten Grand-Slam-Troph\u00e4e. Dar\u00fcber hinaus l\u00f6st die D\u00e4nin ab Montag Halep an der Weltranglistenspitze ab. Die Spielerin aus Constan\u021ba hatte 16 Wochen lang die Rankings angef\u00fchrt &#8211; ein Rekord f\u00fcr Rum\u00e4niens Tennisspielerinnen.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p align=justify>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p align=justify>Unterdessen scheinen sich Tennis-Experten weltweit einig zu sein: Wozniacki ist zwar nach sechs Jahren wieder zur\u00fcck auf die Weltranglisten-Position Nummer 1. geklettert, doch Halep wird ihr dies nur vor\u00fcbergehend genehmigt haben. Trotz der Finalniederlage in Melbourne sei die K\u00e4mpferin in jeder Hinsicht bereit, wieder an die Spitze zur\u00fcckzukehren. Denn nach dem dramatischen Dreisatz-Match gleiche Halep zum ersten Mal nicht einer bezwungenen Spielerin: Sie ist physisch und psychisch besser vorbereitet als je zuvor, schreiben Tennis-Journalisten.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p align=justify>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p align=justify>In diesem Fall h\u00e4tten sich die langen Matches vor dem Endspiel auf die Physis der im Vergleich kleinen Spielerin ausgewirkt. Halep verletzte sich bereits w\u00e4hrend ihrer Erstrunden-Partie am Kn\u00f6chel und musste die n\u00e4chsten Runden mit Schmerzen \u00fcberstehen. Sie selbst sagte nach dem verlorenen Finale, dass ihre Beine nicht frisch genug gewesen und dass die Muskeln m\u00fcde gewesen seien. Heute hat mein K\u00f6rper Nein! gesagt. Ich konnte mich nicht so bewegen, wie ich es gern gemacht h\u00e4tte, es waren zu viele harte Matches- erkl\u00e4rte eine sichtlich entt\u00e4uschte Simona.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p align=justify>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p align=justify>Zus\u00e4tzlich musste die Rum\u00e4nin nach dem Endspiel wegen Dehydratations-Symptomen kurz ins Krankenhauseingeliefert werden. Dort erhielt sie eine Infusionsl\u00f6sung mit Magnesium, um sich von den Folgen des intensiven Schlagabtausches bei 38 Grad Celsius zu befreien. Die Bilder mit der Tennisspielerin im Krankenbett nach dem Finale gingen rund um die Welt.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p align=justify>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p align=justify>Zahlreiche Landsleute hatten Halep zuvor in der Rod Laver-Arena angefeuert, auch vor den Bildschirmen zu Hause wurden heftig die Daumen gedr\u00fcckt. Und, auch wenn die Fans am Ende der Partie nicht ausgelassen feiern konnten, war die Stimmung in den sozialen Netzwerken am Ende positiv. Simona hat einen unglaublichen Kampf geliefert und hat sich unseren ganzen Respekt verdient; Bravo, Simona! Ich glaube, dass der Moment des Grand Slam-Erfolgs f\u00fcr dich kommen wird &#8211; lautete der allgemeine Tenor bei den Anh\u00e4ngern der Spielerin.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p align=justify>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p align=justify>Auf der offiziellen Homepage des Turniers, ausopen.com, war zu lesen, dass das Finale zwischen Simona Halep und Caroline Wozniacki eines der besten der Geschichte war &#8211; voller Spannung, Talent, Sportlichkeit und Beharrlichkeit. Was f\u00fcr ein Finale! 2 Stunden, 50 Minuten\u2026 Episch. &#8211; jubelte auch die <em>BBC.com<\/em>. Und die spanische <em>Mundo Deportivo<\/em> betonte, dass das Endspiel von Melbourne Tennis auf h\u00f6chstem Niveau geboten habe, aber auch gleichzeitig spannungsgeladen war und Agonie-Phasen enthielt. Es habe all die Zutaten eines gro\u00dfen Tennis-Spiels gehabt. <\/p>\n<p>&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es hat auch beim dritten Anlauf nicht geklappt: Tennis-Profi Simona Halep verlor am Samstag zum dritten Mal ein Grand-Slam-Finale. Diesmal das Finale gegen die D\u00e4nin Caroline Wozniacki bei den Australian Open.<\/p>\n","protected":false},"author":109,"featured_media":76266,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[116752],"tags":[41472,161475,39187,117741,172986,148354,31456,33028,102465,99589,143783,144540],"coauthors":[],"class_list":["post-628406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport-de","tag-angelique-kerber","tag-australian-open-de","tag-caroline-wozniacki","tag-dehydratation","tag-finale-de","tag-french-open-de","tag-grand-slam","tag-melbourne","tag-niederlage","tag-rumaenien","tag-simona-halep-de","tag-tennis-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AO-Finale: Halep unterliegt Wozniacki - Radio Rum\u00e4nien International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AO-Finale: Halep unterliegt Wozniacki - Radio Rum\u00e4nien International\" \/>\n<meta property=\"og:description\" content=\"Es hat auch beim dritten Anlauf nicht geklappt: Tennis-Profi Simona Halep verlor am Samstag zum dritten Mal ein Grand-Slam-Finale. Diesmal das Finale gegen die D\u00e4nin Caroline Wozniacki bei den Australian Open.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Rum\u00e4nien International\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-28T10:23:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/simona-halep-wozniacki-trofeu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roxana Vasile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roxana Vasile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Roxana Vasile\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\\\/ao-finale-halep-unterliegt-wozniacki-id628406.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\\\/ao-finale-halep-unterliegt-wozniacki-id628406.html\"},\"author\":{\"name\":\"Roxana Vasile\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/0745b519f2d1287783422f162c4112af\"},\"headline\":\"AO-Finale: Halep unterliegt Wozniacki\",\"datePublished\":\"2018-01-28T10:23:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\\\/ao-finale-halep-unterliegt-wozniacki-id628406.html\"},\"wordCount\":529,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\\\/ao-finale-halep-unterliegt-wozniacki-id628406.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/simona-halep-wozniacki-trofeu.jpg\",\"keywords\":[\"Angelique Kerber\",\"Australian Open\",\"Caroline Wozniacki\",\"Dehydratation\",\"finale\",\"French Open\",\"Grand Slam\",\"Melbourne\",\"Niederlage\",\"Rum\u00e4nien\",\"Simona Halep\",\"tennis\"],\"articleSection\":[\"Sport\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\\\/ao-finale-halep-unterliegt-wozniacki-id628406.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\\\/ao-finale-halep-unterliegt-wozniacki-id628406.html\",\"name\":\"AO-Finale: Halep unterliegt Wozniacki - Radio Rum\u00e4nien International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\\\/ao-finale-halep-unterliegt-wozniacki-id628406.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\\\/ao-finale-halep-unterliegt-wozniacki-id628406.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/simona-halep-wozniacki-trofeu.jpg\",\"datePublished\":\"2018-01-28T10:23:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/0745b519f2d1287783422f162c4112af\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\\\/ao-finale-halep-unterliegt-wozniacki-id628406.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\\\/ao-finale-halep-unterliegt-wozniacki-id628406.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\\\/ao-finale-halep-unterliegt-wozniacki-id628406.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/simona-halep-wozniacki-trofeu.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/simona-halep-wozniacki-trofeu.jpg\",\"width\":640,\"height\":421},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\\\/ao-finale-halep-unterliegt-wozniacki-id628406.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktuell\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sport\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/sport-de\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"AO-Finale: Halep unterliegt Wozniacki\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Rum\u00e4nien International\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/0745b519f2d1287783422f162c4112af\",\"name\":\"Roxana Vasile\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/author\\\/roxana-vasile\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AO-Finale: Halep unterliegt Wozniacki - Radio Rum\u00e4nien International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html","og_locale":"de_DE","og_type":"article","og_title":"AO-Finale: Halep unterliegt Wozniacki - Radio Rum\u00e4nien International","og_description":"Es hat auch beim dritten Anlauf nicht geklappt: Tennis-Profi Simona Halep verlor am Samstag zum dritten Mal ein Grand-Slam-Finale. Diesmal das Finale gegen die D\u00e4nin Caroline Wozniacki bei den Australian Open.","og_url":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html","og_site_name":"Radio Rum\u00e4nien International","article_published_time":"2018-01-28T10:23:00+00:00","og_image":[{"width":640,"height":421,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/simona-halep-wozniacki-trofeu.jpg","type":"image\/jpeg"}],"author":"Roxana Vasile","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Roxana Vasile","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten","Written by":"Roxana Vasile"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html"},"author":{"name":"Roxana Vasile","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/0745b519f2d1287783422f162c4112af"},"headline":"AO-Finale: Halep unterliegt Wozniacki","datePublished":"2018-01-28T10:23:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html"},"wordCount":529,"image":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/simona-halep-wozniacki-trofeu.jpg","keywords":["Angelique Kerber","Australian Open","Caroline Wozniacki","Dehydratation","finale","French Open","Grand Slam","Melbourne","Niederlage","Rum\u00e4nien","Simona Halep","tennis"],"articleSection":["Sport"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html","url":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html","name":"AO-Finale: Halep unterliegt Wozniacki - Radio Rum\u00e4nien International","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/simona-halep-wozniacki-trofeu.jpg","datePublished":"2018-01-28T10:23:00+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/0745b519f2d1287783422f162c4112af"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/simona-halep-wozniacki-trofeu.jpg","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/simona-halep-wozniacki-trofeu.jpg","width":640,"height":421},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de\/ao-finale-halep-unterliegt-wozniacki-id628406.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.rri.ro\/de"},{"@type":"ListItem","position":2,"name":"Aktuell","item":"https:\/\/www.rri.ro\/de\/aktuell"},{"@type":"ListItem","position":3,"name":"Sport","item":"https:\/\/www.rri.ro\/de\/aktuell\/sport-de"},{"@type":"ListItem","position":4,"name":"AO-Finale: Halep unterliegt Wozniacki"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Rum\u00e4nien International","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/0745b519f2d1287783422f162c4112af","name":"Roxana Vasile","url":"https:\/\/www.rri.ro\/de\/author\/roxana-vasile"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/posts\/628406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/users\/109"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/comments?post=628406"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/posts\/628406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/media\/76266"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/media?parent=628406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/categories?post=628406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/tags?post=628406"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/coauthors?post=628406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}