{"id":629371,"date":"2020-04-08T17:30:00","date_gmt":"2020-04-08T14:30:00","guid":{"rendered":"http:\/\/devrri.freshlemon.ro\/aktuell\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html"},"modified":"2020-04-08T17:30:00","modified_gmt":"2020-04-08T14:30:00","slug":"sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html","title":{"rendered":"Sexuelle Ausbeutung von Minderj\u00e4hrigen: Menschenhandel und Gewalt gegen Kinder"},"content":{"rendered":"<p>Frauen und M\u00e4dchen machen erwartungsgem\u00e4\u200e\u00df mehr als zwei Drittel der insgesamt registrierten Opfer aus. Der Anteil w\u00fcrde bei 77%, also mehr als drei Viertel liegen, wenn wir die statistischen Daten aus dem gerade aus der EU ausgetreten Vereinigten K\u00f6nigreich ausklammern w\u00fcrden. Die ersten f\u00fcnf europ\u00e4ischen Herkunftsl\u00e4nder der Opfer waren Rum\u00e4nien, Ungarn, die Niederlande, Polen und Bulgarien.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Die Situation scheint sich aktuell nicht wesentlich ge\u00e4ndert zu haben, da Rum\u00e4nien laut der Nationalen Agentur gegen Menschenhandel im Jahr 2018 immer noch eines der gro\u200e\u00dfen Herkunftsl\u00e4nder des Menschenhandels war und die H\u00e4lfte der Gesamtopfer minderj\u00e4hrig waren. Einige der jungen Frauen, die es irgendwie geschafft haben, aus dieser Art der heutigen Sklaverei auszubrechen, werden von der Aktivistin Iana Matei unterst\u00fctzt, die vor 20 Jahren ein Heim f\u00fcr den Schutz und die soziale Eingliederung der Opfer von Menschenhandel gr\u00fcndete. Laut Iana Matei hat die oben genannte NGO mit dem Titel Reaching Out Romania\u201c seit ihrer Gr\u00fcndung \u00fcber 600 Opfern von Sexploitation, wie die sexuelle Ausbeutung noch hei\u200e\u00dft, Hilfe angeboten:<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><em>Wir haben mit einer Wohnung begonnen, die wir damals gemietet haben, danach stieg die Zahl der M\u00e4dchen, und ich glaube, im Jahr 2000 haben wir die gr\u00f6\u200e\u00dfte Zahl von M\u00e4dchen registriert. Die meisten von ihnen wurden in den L\u00e4ndern des ehemaligen Jugoslawiens Opfer von Menschenhandel. Sp\u00e4ter mussten wir eine Unterkunft f\u00fcr sie bauen und f\u00fcgten eine weitere hinzu, da ihre Zahl weiterhin zunahm. Die beiden Zentren, die wir derzeit haben, k\u00f6nnen 18 M\u00e4dchen aufnehmen, und derzeit leben 12 M\u00e4dchen hier. Wir haben noch eine weitere Unterbringungsm\u00f6glichkeit in einer Lavendelfarm in Craiova, weil wir eine Alternative f\u00fcr die M\u00e4dchen schaffen wollten, die nicht weiter zur Schule gehen wollen. Die meisten von ihnen kommen vom Land, und auf unserer Lavendelfarm bringen wir ihnen bei, wie sie ihr eigenes Gesch\u00e4ft und ihren eigenen Beruf entwickeln k\u00f6nnen. Die M\u00e4dchen in unseren Zentren sind zwischen 12 und 14 Jahre alt, und aus meiner Sicht sollten wir hier \u00fcber P\u00e4dophilie sprechen, nicht \u00fcber Menschenhandel. Das ist Gewalt nicht gegen Frauen, sondern gegen Kinder.\u201c<\/em><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Auf der Lavendelfarm wird diesen M\u00e4dchen die M\u00f6glichkeit geboten, die f\u00fcr einen Beruf notwendigen F\u00e4higkeiten zu erlernen, damit sie nicht wieder in die Prostitution gehen, aber in dem von Iana Matei gegr\u00fcndeten Heim wird ihnen auch psychologische Betreuung angeboten. Die Ausbeutung verursacht spezifische Traumata, die nur schwer zu \u00fcberwinden sind; die Opfer leiden an einem geringen Selbstwertgef\u00fchl, da ihnen schon in sehr jungen Jahren Zuneigung vorenthalten wurde. Diese Probleme werden in der Regel von Menschenh\u00e4ndlern ausgenutzt, die oft auf die sogenannte Loverboy\u201c-Methode zur\u00fcckgreifen, um junge M\u00e4dchen zur Prostitution zu verf\u00fchren, f\u00fchrt die Aktivistin weiter aus:<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><em>Die Loverboy-Methode erm\u00f6glicht es dem Menschenh\u00e4ndler, die Identit\u00e4t des jungen M\u00e4dchens zu vernichten. Wir sprechen hier von jungen M\u00e4dchen, die eigentlich nicht wissen, was Liebe ist, und das macht sie zu einer leichten Beute f\u00fcr diese Raubtiere. Leider werden diese jungen M\u00e4dchen mit der Zeit sexs\u00fcchtig. Wenn sie ihr Sexualleben mit etwa 11 oder 12 Jahren beginnen und etwa 10&#8211;15 Freier am Tag haben, entsteht eine gewisse Art von Abh\u00e4ngigkeit; aber dieses Thema ist tabu, da niemand dar\u00fcber sprechen will. Dar\u00fcber hinaus m\u00fcssen diese jungen M\u00e4dchen oft mit vielen Schuldzuweisungen umgehen, da die Menschen sehr voreingenommen sind und gerne mit dem Finger zeigen. Die ersten drei Monate sind die schwierigsten, weil sie vor allem wieder in ihren Beruf, in ihre Sucht, zur\u00fcckkehren wollen. Staatliche Institutionen sind in dieser Hinsicht nicht sehr hilfreich. Nach dem Gesetz muss zum Beispiel jedes Kind zur Schule gehen, aber diese M\u00e4dchen, die Opfer von sexueller Ausbeutung sind, haben eine besondere Situation und k\u00f6nnen nicht sehr bald wieder zur Schule gehen.\u201c<\/em><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Iana Matei zufolge erfordert die Bek\u00e4mpfung des Menschenhandels einen integrierten Ansatz, also gemeinsame Handlungen der Ressorts Bildung, Gesundheit und Inneres sowie verschiedene Methoden der Bek\u00e4mpfung des organisierten Verbrechens. Die Beh\u00f6rden sollten mit den Vereinen zusammenarbeiten, die die Situation aus erster Hand kennen. Dar\u00fcber hinaus muss sich die kollektive Optik in den l\u00e4ndlichen Gemeinden \u00e4ndern, aus denen diese M\u00e4dchen stammen &#8212; dort werde die Ausbeutung missverstanden und die Schuld den Opfern gegeben. Das findet auch h\u00e4ufig bei dem Umgang mit h\u00e4uslicher Gewalt statt, sagt Elena Samoil\u0103, Programmkoordinatorin des FILIA-Zentrums, einer Vereinigung, die sich f\u00fcr die Rechte der Frauen einsetzt.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><em>Dass die Schuld bei den Opfern gesucht wird, ist heutzutage ein weit verbreitetes Muster in der Gesellschaft. Oft werden die Opfer f\u00fcr ihre Entscheidung beschuldigt, an einer Beziehung festzuhalten, in der sie missbraucht werden. Oder sie werden zum S\u00fcndenbock f\u00fcr das Verhalten der T\u00e4ter gemacht. Die Leute sagen oft: \u201aNun, jede Geschichte hat zwei Seiten, die Frau muss doch etwas getan haben.\u2018 Um es kurz zu machen: Wir leben in einer Gesellschaft, in der Frauen f\u00fcr das Ausl\u00f6sen der Gewalt ihres Partners verantwortlich gemacht werden, und sie sollen Gewalt durch ihre Partner ertragen und die Dinge einfach stoisch aushalten. M\u00e4nner, die meistens die T\u00e4ter in einer Beziehung sind, kommen in der Regel damit durch.\u201c<\/em><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Experten warnen davor, dass unter den gegenw\u00e4rtigen Umst\u00e4nden der Pandemie die Zahl der F\u00e4lle h\u00e4uslicher Gewalt weltweit zunimmt, da viele Frauen in der Isolation mit aggressiven Partnern gefangen sind.<\/p>\n<p>&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laut der Europ\u00e4ischen Kommission verfolgte zwischen 2015 und 2016 der Menschenhandel in der EU in 56% aller F\u00e4lle \u2013 mehr als der H\u00e4lfte also \u2013 den Zweck der sexuellen Ausbeutung. Das ist nach wie vor die h\u00e4ufigste Form der Ausbeutung durch Menschenhandel.<\/p>\n","protected":false},"author":136,"featured_media":143499,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[116756],"tags":[146623,119779,68210,134270,43609,104734,120338,120337,68209,120340,119730,103578,119904,100759,104183,68208,86955,99589,120335,120339,120336],"coauthors":[],"class_list":["post-629371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sozialreport-der-rumaenische-alltag","tag-craiova-de","tag-eingliederung","tag-elena-samoila","tag-eu-de","tag-filia","tag-frauen","tag-heime","tag-herkunftslaender","tag-iana-matei","tag-lavendelfarm","tag-maedchen","tag-menschenhandel","tag-minderjaehrige","tag-opfer","tag-paedophilie","tag-reaching-out-romania","tag-reintegration","tag-rumaenien","tag-sexuelle-ausbeutung","tag-unterkuenfte","tag-zwangsprostitution"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sexuelle Ausbeutung von Minderj\u00e4hrigen: Menschenhandel und Gewalt gegen Kinder - Radio Rum\u00e4nien International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sexuelle Ausbeutung von Minderj\u00e4hrigen: Menschenhandel und Gewalt gegen Kinder - Radio Rum\u00e4nien International\" \/>\n<meta property=\"og:description\" content=\"Laut der Europ\u00e4ischen Kommission verfolgte zwischen 2015 und 2016 der Menschenhandel in der EU in 56% aller F\u00e4lle \u2013 mehr als der H\u00e4lfte also \u2013 den Zweck der sexuellen Ausbeutung. Das ist nach wie vor die h\u00e4ufigste Form der Ausbeutung durch Menschenhandel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Rum\u00e4nien International\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-08T14:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/violenta-femei-pixabay-ok.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Christine Le\u0219cu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christine Le\u0219cu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Christine Le\u0219cu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\\\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\\\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html\"},\"author\":{\"name\":\"Christine Le\u0219cu\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/90282b710df17e2fe4e8831187ac186f\"},\"headline\":\"Sexuelle Ausbeutung von Minderj\u00e4hrigen: Menschenhandel und Gewalt gegen Kinder\",\"datePublished\":\"2020-04-08T14:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\\\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html\"},\"wordCount\":916,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\\\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/violenta-femei-pixabay-ok.png\",\"keywords\":[\"Craiova\",\"Eingliederung\",\"Elena Samoila\",\"EU\",\"FILIA\",\"Frauen\",\"Heime\",\"Herkunftsl\u00e4nder\",\"Iana Matei\",\"Lavendelfarm\",\"M\u00e4dchen\",\"Menschenhandel\",\"Minderj\u00e4hrige\",\"Opfer\",\"P\u00e4dophilie\",\"Reaching Out Romania\",\"r\u00e9int\u00e9gration\",\"Rum\u00e4nien\",\"sexuelle Ausbeutung\",\"Unterk\u00fcnfte\",\"Zwangsprostitution\"],\"articleSection\":[\"Sozialreport \u2013 der rum\u00e4nische Alltag\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\\\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\\\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html\",\"name\":\"Sexuelle Ausbeutung von Minderj\u00e4hrigen: Menschenhandel und Gewalt gegen Kinder - Radio Rum\u00e4nien International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\\\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\\\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/violenta-femei-pixabay-ok.png\",\"datePublished\":\"2020-04-08T14:30:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/90282b710df17e2fe4e8831187ac186f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\\\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\\\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\\\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/violenta-femei-pixabay-ok.png\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/violenta-femei-pixabay-ok.png\",\"width\":640,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\\\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feature &amp; Reportage\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sozialreport \u2013 der rum\u00e4nische Alltag\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/feature-reportage\\\/sozialreport-der-rumaenische-alltag\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Sexuelle Ausbeutung von Minderj\u00e4hrigen: Menschenhandel und Gewalt gegen Kinder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Rum\u00e4nien International\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/90282b710df17e2fe4e8831187ac186f\",\"name\":\"Christine Le\u0219cu\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/author\\\/christine-lescu\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sexuelle Ausbeutung von Minderj\u00e4hrigen: Menschenhandel und Gewalt gegen Kinder - Radio Rum\u00e4nien International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html","og_locale":"de_DE","og_type":"article","og_title":"Sexuelle Ausbeutung von Minderj\u00e4hrigen: Menschenhandel und Gewalt gegen Kinder - Radio Rum\u00e4nien International","og_description":"Laut der Europ\u00e4ischen Kommission verfolgte zwischen 2015 und 2016 der Menschenhandel in der EU in 56% aller F\u00e4lle \u2013 mehr als der H\u00e4lfte also \u2013 den Zweck der sexuellen Ausbeutung. Das ist nach wie vor die h\u00e4ufigste Form der Ausbeutung durch Menschenhandel.","og_url":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html","og_site_name":"Radio Rum\u00e4nien International","article_published_time":"2020-04-08T14:30:00+00:00","og_image":[{"width":640,"height":960,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/violenta-femei-pixabay-ok.png","type":"image\/png"}],"author":"Christine Le\u0219cu","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christine Le\u0219cu","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten","Written by":"Christine Le\u0219cu"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html"},"author":{"name":"Christine Le\u0219cu","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/90282b710df17e2fe4e8831187ac186f"},"headline":"Sexuelle Ausbeutung von Minderj\u00e4hrigen: Menschenhandel und Gewalt gegen Kinder","datePublished":"2020-04-08T14:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html"},"wordCount":916,"image":{"@id":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/violenta-femei-pixabay-ok.png","keywords":["Craiova","Eingliederung","Elena Samoila","EU","FILIA","Frauen","Heime","Herkunftsl\u00e4nder","Iana Matei","Lavendelfarm","M\u00e4dchen","Menschenhandel","Minderj\u00e4hrige","Opfer","P\u00e4dophilie","Reaching Out Romania","r\u00e9int\u00e9gration","Rum\u00e4nien","sexuelle Ausbeutung","Unterk\u00fcnfte","Zwangsprostitution"],"articleSection":["Sozialreport \u2013 der rum\u00e4nische Alltag"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html","url":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html","name":"Sexuelle Ausbeutung von Minderj\u00e4hrigen: Menschenhandel und Gewalt gegen Kinder - Radio Rum\u00e4nien International","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/violenta-femei-pixabay-ok.png","datePublished":"2020-04-08T14:30:00+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/90282b710df17e2fe4e8831187ac186f"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/violenta-femei-pixabay-ok.png","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/violenta-femei-pixabay-ok.png","width":640,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag\/sexuelle-ausbeutung-von-minderjaehrigen-menschenhandel-und-gewalt-gegen-kinder-id629371.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.rri.ro\/de"},{"@type":"ListItem","position":2,"name":"Feature &amp; Reportage","item":"https:\/\/www.rri.ro\/de\/feature-reportage"},{"@type":"ListItem","position":3,"name":"Sozialreport \u2013 der rum\u00e4nische Alltag","item":"https:\/\/www.rri.ro\/de\/feature-reportage\/sozialreport-der-rumaenische-alltag"},{"@type":"ListItem","position":4,"name":"Sexuelle Ausbeutung von Minderj\u00e4hrigen: Menschenhandel und Gewalt gegen Kinder"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Rum\u00e4nien International","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/90282b710df17e2fe4e8831187ac186f","name":"Christine Le\u0219cu","url":"https:\/\/www.rri.ro\/de\/author\/christine-lescu"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/posts\/629371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/users\/136"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/comments?post=629371"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/posts\/629371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/media\/143499"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/media?parent=629371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/categories?post=629371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/tags?post=629371"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/coauthors?post=629371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}