{"id":632158,"date":"2016-08-12T20:06:00","date_gmt":"2016-08-12T17:06:00","guid":{"rendered":"http:\/\/devrri.freshlemon.ro\/aktuell\/nachrichten-12-08-2016-id632158.html"},"modified":"2016-08-12T20:06:00","modified_gmt":"2016-08-12T17:06:00","slug":"nachrichten-12-08-2016","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html","title":{"rendered":"Nachrichten 12.08.2016"},"content":{"rendered":"<p><strong>BUKAREST<\/strong>: Zahlreiche Mitglieder der k\u00f6niglichen Familien Europas werden der Bestattungszeremonie der K\u00f6nigin Anna, der verstorbenen Ehegattin des letzten K\u00f6nigs von Rum\u00e4nien, Michael I.,  beiwohnen. Bislang haben Mitglieder der kaiserlichen Familien von Russland, \u00d6sterreich und Deutschland, und der k\u00f6niglichen Familien aus den Niederlanden, Belgien und Luxemburg ihre Teilnahme best\u00e4tigt. Tausende Menschen erwiesen inzwischen am Donnerstag und Freitag der im Thronsaal des K\u00f6nigspalastes in Bukarest aufgebahrten K\u00f6nigin die letzte Ehre. Die Bestattungszeremonie wird am Samstag im s\u00fcdrum\u00e4nischen Curtea de Arge\u015f stattfinden. K\u00f6nig Michael I. von Rum\u00e4nien, mit dem Anna von Bourbon-Parma seit 1948 verheiratet war, wird der Bestattungszeremonie aus gesundheitlichen Gr\u00fcnden fernbleiben m\u00fcssen. In Rum\u00e4nien und der Republik Moldau wurde zum Anlass Staatstrauer angeordnet. <\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>BUKAREST<\/strong>: Der fr\u00fchere stellvertretende Notenbankchef Bogdan Olteanu ist nach einem Beschluss des Obersten Gerichtshofs f\u00fcr 16 Tage in Untersuchungshaft genommen worden. In dem Verfahren, in dem er der Vorteilsannahme beschuldigt wird, war er zun\u00e4chst unter Hausarrest gestellt worden. Laut Ermittlern soll er 2008 als Vorsitzender der Abgeordnetenkammer und Mitglied der National-Liberalen Partei eine Million Euro von einem Gesch\u00e4ftsmann gefordert und auch erhalten haben. Als Gegenleistung sollte Olteanu seinen Einfluss geltend machen, damit eine bestimmte Person aus dem Umkreis des Gesch\u00e4ftsmannes zum Verwalter des Reservats im Donaudelta ernannt wird \u2013 der Betreffende bekam in der Tat den Job.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>BUKAREST<\/strong>: Die Polizei ermittelt gegen die Firma, die das Outfit des rum\u00e4nischen Kaders f\u00fcr die Olympischen Spiele geliefert hat. Darunter sollen sich gef\u00e4lschte Markenartikel befinden. Am Freitag waren die Beamten zu einer Hausdurchsuchung beim Rum\u00e4nischen Olympischen und Sportkommittees aufgebrochen. Dort beschlagnahmten sie Sportkleidung, jedoch war bislang niemand zu Anh\u00f6rungen geladen worden. Laut Presseberichten hatten sich mehrere Mitglieder des olympischen Kaders \u00fcber die Qualit\u00e4t der Kollektion beklagt. Nach nur einigen Tagen w\u00e4ren die Sportanz\u00fcge gerissen und abgef\u00e4rbt. Die Firma Pax Creative, die f\u00fcr die Lieferung f\u00fcr Olympia verantwortlich ist, soll laut Journalisten von dem Ex-Vorsitzenden des Rum\u00e4nischen Olympischen Kommittees, Octavian Morariu, sowie dem amtierenden Generalsekret\u00e4r, Ioan Dobrescu, gegr\u00fcndet worden sein. Morariu ist derzeit Mitglied des Internationalen Olympischen Kommitees.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>BUKAREST<\/strong>: Die rum\u00e4nische Justizministerin Raluca Pruna hat am Freitag die neue nationale Antikorruptionsstrategie vorgelegt. Sie sprach dabei von einem Paradigmenwechsel \u2013 der Schwerpunkt der Strategie werde diesmal auf Pr\u00e4vention und Verantwortung der F\u00fchrungskr\u00e4fte gelegt. Jede Korruptionsstraftat sei ein F\u00fchrungsversagen, f\u00fcr das sich jemand zu verantworten hat, so die Ministerin. Die Strategie beh\u00e4lt anf\u00e4llige Bereiche wie die Justiz und die Politik im Auge, achtet jetzt priorit\u00e4r aber auch auf Bildung und Gesundheit.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>SPORT<\/strong>: Es sieht langsam etwas rosiger aus f\u00fcr den rum\u00e4nischen Olympia-Kader in Rio de Janeiro. Die Degendamen besiegten im Finale ihre chinesischen Gegnerinnen 44 \u2013 38 und holten sich das Gold \u2013 es ist die erste rum\u00e4nische Medaille bei dieser Ausgabe der Sommerspiele.  Und im Tennis besiegten Horia Tec\u0103u und Florin Mergea im Halbfinale des Herrendoppels das amerikanische Team von Jack Sock und Steve Johnson. Jetzt geht es im Finale gegen die spanischen Topstars Rafael Nadal und Marc Lopez. Gegen Spanien treten auch die Handballdamen am Freitagabend an \u2013 nach entt\u00e4uschenden Niederlagen gegen Angola und Brasilien und einem Sieg gegen Montenegro stehen sie allerdings unter hohen Druck: sie brauchen einen Sieg f\u00fcr den Einzug ins Viertelfinale. <\/p>\n<p>&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die wichtigsten Meldungen des Tages im \u00dcberblick<\/p>\n","protected":false},"author":113,"featured_media":459887,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[116753],"tags":[34880,124175,103446,125826,145034,125762,100698,101412,143772,38683,103373,125828,103441,99702,41142,32934,125829,103391,35834,103018,125827,99918,68542,99589,117216,29099,144540,101238],"coauthors":[],"class_list":["post-632158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsflash-de","tag-anna","tag-antikorruptionsstrategie","tag-bestattung","tag-bourbon","tag-curtea-de-arges-de","tag-degendamen","tag-ermittlungen","tag-faelschung","tag-gold-de","tag-hohenzollern","tag-justizministerin","tag-kappa","tag-koenigin","tag-korruption","tag-mergea","tag-michael","tag-nadal","tag-notenbankchef","tag-olteanu","tag-olympia","tag-outfit","tag-polizei","tag-pruna","tag-rumaenien","tag-stellvertreter","tag-tecau","tag-tennis-de","tag-untersuchungshaft"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachrichten 12.08.2016 - Radio Rum\u00e4nien International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachrichten 12.08.2016 - Radio Rum\u00e4nien International\" \/>\n<meta property=\"og:description\" content=\"Die wichtigsten Meldungen des Tages im \u00dcberblick\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Rum\u00e4nien International\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-12T17:06:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-germana-ok2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Newsroom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsroom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Newsroom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-12-08-2016-id632158.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-12-08-2016-id632158.html\"},\"author\":{\"name\":\"Newsroom\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"headline\":\"Nachrichten 12.08.2016\",\"datePublished\":\"2016-08-12T17:06:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-12-08-2016-id632158.html\"},\"wordCount\":553,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-12-08-2016-id632158.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/stiri-germana-ok2.png\",\"keywords\":[\"Anna\",\"Antikorruptionsstrategie\",\"Bestattung\",\"Bourbon\",\"Curtea de Arges\",\"Degendamen\",\"Ermittlungen\",\"F\u00e4lschung\",\"gold\",\"Hohenzollern\",\"Justizministerin\",\"Kappa\",\"K\u00f6nigin\",\"Korruption\",\"mergea\",\"Michael\",\"Nadal\",\"Notenbankchef\",\"Olteanu\",\"Olympia\",\"Outfit\",\"Polizei\",\"pruna\",\"Rum\u00e4nien\",\"Stellvertreter\",\"Tecau\",\"tennis\",\"Untersuchungshaft\"],\"articleSection\":[\"Newsflash\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-12-08-2016-id632158.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-12-08-2016-id632158.html\",\"name\":\"Nachrichten 12.08.2016 - Radio Rum\u00e4nien International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-12-08-2016-id632158.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-12-08-2016-id632158.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/stiri-germana-ok2.png\",\"datePublished\":\"2016-08-12T17:06:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-12-08-2016-id632158.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-12-08-2016-id632158.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-12-08-2016-id632158.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/stiri-germana-ok2.png\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/stiri-germana-ok2.png\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-12-08-2016-id632158.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktuell\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Nachrichten 12.08.2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Rum\u00e4nien International\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\",\"name\":\"Newsroom\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/author\\\/newsroom\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachrichten 12.08.2016 - Radio Rum\u00e4nien International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html","og_locale":"de_DE","og_type":"article","og_title":"Nachrichten 12.08.2016 - Radio Rum\u00e4nien International","og_description":"Die wichtigsten Meldungen des Tages im \u00dcberblick","og_url":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html","og_site_name":"Radio Rum\u00e4nien International","article_published_time":"2016-08-12T17:06:00+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-germana-ok2.png","type":"image\/png"}],"author":"Newsroom","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Newsroom","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten","Written by":"Newsroom"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html"},"author":{"name":"Newsroom","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"headline":"Nachrichten 12.08.2016","datePublished":"2016-08-12T17:06:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html"},"wordCount":553,"image":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-germana-ok2.png","keywords":["Anna","Antikorruptionsstrategie","Bestattung","Bourbon","Curtea de Arges","Degendamen","Ermittlungen","F\u00e4lschung","gold","Hohenzollern","Justizministerin","Kappa","K\u00f6nigin","Korruption","mergea","Michael","Nadal","Notenbankchef","Olteanu","Olympia","Outfit","Polizei","pruna","Rum\u00e4nien","Stellvertreter","Tecau","tennis","Untersuchungshaft"],"articleSection":["Newsflash"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html","url":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html","name":"Nachrichten 12.08.2016 - Radio Rum\u00e4nien International","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-germana-ok2.png","datePublished":"2016-08-12T17:06:00+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-germana-ok2.png","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-germana-ok2.png","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-12-08-2016-id632158.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.rri.ro\/de"},{"@type":"ListItem","position":2,"name":"Aktuell","item":"https:\/\/www.rri.ro\/de\/aktuell"},{"@type":"ListItem","position":3,"name":"Newsflash","item":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de"},{"@type":"ListItem","position":4,"name":"Nachrichten 12.08.2016"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Rum\u00e4nien International","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88","name":"Newsroom","url":"https:\/\/www.rri.ro\/de\/author\/newsroom"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/posts\/632158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/comments?post=632158"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/posts\/632158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/media\/459887"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/media?parent=632158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/categories?post=632158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/tags?post=632158"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/coauthors?post=632158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}