{"id":813787,"date":"2024-10-03T17:56:44","date_gmt":"2024-10-03T14:56:44","guid":{"rendered":"https:\/\/www.rri.ro\/?p=813787"},"modified":"2024-10-03T18:04:44","modified_gmt":"2024-10-03T15:04:44","slug":"nachrichten-03-10-2024","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html","title":{"rendered":"Nachrichten 03.10.2024"},"content":{"rendered":"<div><span style=\"font-size: medium;\">Die Regierung in Bukarest hat den Rahmen f\u00fcr die L\u00e4nderpartnerschaft zwischen der Weltbank und Rum\u00e4nien f\u00fcr den Zeitraum 2025\u20132029 vorgestellt. Nach Angaben von Premierminister Marcel Ciolacu wird die Weltbankgruppe Rum\u00e4nien in den n\u00e4chsten drei Jahren sch\u00e4tzungsweise mehr als sechs Milliarden Dollar zu g\u00fcnstigen finanziellen Bedingungen zur Verf\u00fcgung stellen. Das Geld werde dazu beitragen, das Entwicklungsgef\u00e4lle zwischen den st\u00e4dtischen und den l\u00e4ndlichen Gebieten zu \u00fcberbr\u00fccken, so der Premierminister. Mit der Weltbank wurde au\u00dferdem ein Darlehensabkommen \u00fcber 500 Millionen Dollar f\u00fcr Ma\u00dfnahmen zum Katastrophenschutz unterzeichnet.\u00a0<\/span><\/div>\n<div><span style=\"font-size: medium;\">\u00a0<\/span><\/div>\n<div><span style=\"font-size: medium;\">Die von den Mitgliedstaaten und der Kommissionspr\u00e4sidentin Ursula von der Leyen designierten EU-Kommissare werden n\u00e4chsten Monat in den Fachaussch\u00fcssen des Europ\u00e4ischen Parlaments angeh\u00f6rt. Laut einer \u00c4u\u00dferung der EU-Parlamentspr\u00e4sidentin Roberta Metsola in den Social Media sollen die Anw\u00e4rter auf die Posten der Kommissare vom 4. bis 12. November angeh\u00f6rt werden. France Presse kommentiert, dass die Amts\u00fcbernahme der neuen Europ\u00e4ischen Kommission Anfang Dezember stattfinden k\u00f6nnte. Die Vertreterin Rum\u00e4niens, Roxana M\u00eenzatu, k\u00f6nnte den Posten der Kommissarin f\u00fcr Qualifikationen und Bildung, Besch\u00e4ftigung und soziale Rechte erhalten.<\/span><\/div>\n<div><span style=\"font-size: medium;\">\u00a0<\/span><\/div>\n<div dir=\"ltr\">\n<div>\n<div><span style=\"font-size: medium;\">Der rum\u00e4nische Minister f\u00fcr Investitionen und europ\u00e4ische Projekte, Adrian C\u00e2ciu, erkl\u00e4rte, dass Rum\u00e4nien bis zum 15. Oktober, der von der Europ\u00e4ischen Kommission gesetzten Frist, einen Siebenjahresplan zum Abbau des Haushaltsdefizits vorlegen wird. Laut C\u00e2ciu umfasst der Plan eine Reihe von Reformen, die im Nationalen Plan f\u00fcr Wiederaufbau und Widerstandsf\u00e4higkeit enthalten sind. Die Ma\u00dfnahmen bestehen vor allem in der Reduzierung nicht notwendiger Ausgaben der \u00f6ffentlichen Einrichtungen und einer besseren Einnahmeerzielung f\u00fcr den Haushalt. Details, laut Protokoll.<\/span><\/div>\n<div><\/div>\n<div><span style=\"font-size: medium;\">Junge Europ\u00e4er, die im Jahr 2006 geboren wurden, einschlie\u00dflich derer aus Rum\u00e4nien, k\u00f6nnen sich f\u00fcr das Programm DiscoverEU 2024 anmelden, bei dem sie kostenlose Reisen in die Mitgliedsstaaten der Europ\u00e4ischen Union gewinnen k\u00f6nnen. Diejenigen, die eine der 35.000 kostenlosen Reisegenehmigungen und Rabattkarten f\u00fcr Unterkunft und Verpflegung w\u00e4hrend der Reise ergattern m\u00f6chten, m\u00fcssen sich auf der Seite der Europ\u00e4ischen Kommission registrieren, die jungen Menschen gewidmet ist. Die Gewinnerp\u00e4sse bieten die M\u00f6glichkeit einer einmonatigen Reise, die die Jugendlichen zwischen M\u00e4rz 2025 und Mai 2026 antreten k\u00f6nnen. Jeder Gewinner kann sich f\u00fcr bestimmte Ziele in Europa entscheiden oder sich von der DiscoverEU-Kulturroute inspirieren lassen, die europ\u00e4ische Hauptst\u00e4dte, UNESCO-St\u00e4tten oder St\u00e4tten des europ\u00e4ischen Kulturerbes miteinander verbindet. Die Anmeldung ist bis zum 16. Oktober m\u00f6glich. Seit dem Start des Programms im Jahr 2018 haben mehr als 300.000 Menschen von diesem Programm profitiert.<\/span><\/div>\n<div><span style=\"font-size: medium;\">Die Arbeitslosenquote in Rum\u00e4nien lag im August bei 5,5 % und ist damit im Vergleich zum Juli um 0,1 Prozent gestiegen, teilte das Nationale Institut f\u00fcr Statistik mit. Die Zahl der Arbeitslosen im Alter zwischen 15 und 74 Jahren \u00fcberstieg 450.000 und stieg sowohl im Vergleich zum Vormonat als auch im Vergleich zum August 2023. Die Arbeitslosigkeit unter den Erwachsenen zwischen 25 und 74 Jahren wurde f\u00fcr den untersuchten Zeitraum auf 4,4% gesch\u00e4tzt. Die leicht steigende Tendenz dieses Indikators ist eine Warnung f\u00fcr die Regierung, denn die Entwicklung der Arbeitslosigkeit zeigt die Richtung, in die sich die Wirtschaft bewegt, und derzeit gibt es eine Verlangsamung der wirtschaftlichen Aktivit\u00e4t, sagte Wirtschaftsanalyst Aurelian Dochia. Obwohl der leichte Anstieg der Zahl der Arbeitslosen ein besorgniserregendes Signal sei, sei Rum\u00e4nien noch weit von dem kritischen Niveau entfernt, das in den vergangenen Krisenzeiten herrschte, als der Staat unter anderem mit einer wirtschaftlichen Rezession konfrontiert war, so Dochia. Wir melden uns nach den Nachrichten wieder.<\/span><\/div>\n<\/div>\n<div>\n<p>NATO-Generalsekret\u00e4r Mark Rutte hat am Donnerstag bei seinem ersten offiziellen Besuch seit \u00dcbernahme der F\u00fchrung des B\u00fcndnisses am 1. Oktober mit Pr\u00e4sident Wolodimir Zelenskyj \u00fcber den Krieg in der Ukraine und den \u201eSiegesplan\u201c Kiews gesprochen. \u201eDie Ukraine ist der Nato n\u00e4her als je zuvor und wird diesen Weg bis zur Mitgliedschaft fortsetzen\u201c, sagte Mark Rutte, der seine Unterst\u00fctzung f\u00fcr Kiew bekr\u00e4ftigte. Wolodimir Zelensk yjerkl\u00e4rte seinerseits, die Ukrainer h\u00e4tten es verdient, der NATO beizutreten, und man m\u00fcsse Moskau \u201eein klares Signal geben, dass garantierte Sicherheit f\u00fcr die Ukraine und ganz Europa unvermeidlich ist\u201c.<\/p>\n<\/div>\n<\/div>\n<div><span style=\"font-size: medium;\">Sch\u00f6nes Herbstwetter bei strahlendem Sonnenschein und es wird allm\u00e4hlich wieder w\u00e4rmer in Rum\u00e4nien. Im Westen des Landes wird allerdings gegen Abend Regen erwartet. Die H\u00f6chsttemperaturen liegen am Donnerstag zwischen 18 und 26 Grad Celsius. In Bukarest wurden gegen Mittag 21 Grad Celsius gemessen.<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Regierung in Bukarest hat den Rahmen f\u00fcr die L\u00e4nderpartnerschaft zwischen der Weltbank und Rum\u00e4nien f\u00fcr den Zeitraum 2025\u20132029 vorgestellt. Nach Angaben von Premierminister Marcel Ciolacu wird die Weltbankgruppe Rum\u00e4nien in den n\u00e4chsten drei Jahren sch\u00e4tzungsweise mehr als sechs Milliarden Dollar zu g\u00fcnstigen finanziellen Bedingungen zur Verf\u00fcgung stellen. Das Geld werde dazu beitragen, das Entwicklungsgef\u00e4lle [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":723386,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[116753],"tags":[155850,101106,128923,155849,99586,154827],"coauthors":[116091],"class_list":["post-813787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsflash-de","tag-adrian-caciu-de","tag-arbeitslosenquote","tag-premierminister-marcel-ciolacu","tag-programm-discovereu-2024","tag-regierung","tag-roxana-minzatu-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachrichten 03.10.2024 - Radio Rum\u00e4nien International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachrichten 03.10.2024 - Radio Rum\u00e4nien International\" \/>\n<meta property=\"og:description\" content=\"Die Regierung in Bukarest hat den Rahmen f\u00fcr die L\u00e4nderpartnerschaft zwischen der Weltbank und Rum\u00e4nien f\u00fcr den Zeitraum 2025\u20132029 vorgestellt. Nach Angaben von Premierminister Marcel Ciolacu wird die Weltbankgruppe Rum\u00e4nien in den n\u00e4chsten drei Jahren sch\u00e4tzungsweise mehr als sechs Milliarden Dollar zu g\u00fcnstigen finanziellen Bedingungen zur Verf\u00fcgung stellen. Das Geld werde dazu beitragen, das Entwicklungsgef\u00e4lle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Rum\u00e4nien International\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-03T14:56:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-03T15:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Nachrichten-2-NOU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Newsroom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsroom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Newsroom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-03-10-2024-id813787.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-03-10-2024-id813787.html\"},\"author\":{\"name\":\"Newsroom\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"headline\":\"Nachrichten 03.10.2024\",\"datePublished\":\"2024-10-03T14:56:44+00:00\",\"dateModified\":\"2024-10-03T15:04:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-03-10-2024-id813787.html\"},\"wordCount\":737,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-03-10-2024-id813787.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Nachrichten-2-NOU.jpg\",\"keywords\":[\"Adrian C\u00e2ciu\",\"Arbeitslosenquote\",\"Premierminister Marcel Ciolacu\",\"Programm DiscoverEU 2024\",\"Regierung\",\"Roxana Minzatu\"],\"articleSection\":[\"Newsflash\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-03-10-2024-id813787.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-03-10-2024-id813787.html\",\"name\":\"Nachrichten 03.10.2024 - Radio Rum\u00e4nien International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-03-10-2024-id813787.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-03-10-2024-id813787.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Nachrichten-2-NOU.jpg\",\"datePublished\":\"2024-10-03T14:56:44+00:00\",\"dateModified\":\"2024-10-03T15:04:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-03-10-2024-id813787.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-03-10-2024-id813787.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-03-10-2024-id813787.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Nachrichten-2-NOU.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Nachrichten-2-NOU.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\\\/nachrichten-03-10-2024-id813787.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktuell\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/aktuell\\\/newsflash-de\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Nachrichten 03.10.2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Rum\u00e4nien International\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\",\"name\":\"Newsroom\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/de\\\/author\\\/newsroom\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachrichten 03.10.2024 - Radio Rum\u00e4nien International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html","og_locale":"de_DE","og_type":"article","og_title":"Nachrichten 03.10.2024 - Radio Rum\u00e4nien International","og_description":"Die Regierung in Bukarest hat den Rahmen f\u00fcr die L\u00e4nderpartnerschaft zwischen der Weltbank und Rum\u00e4nien f\u00fcr den Zeitraum 2025\u20132029 vorgestellt. Nach Angaben von Premierminister Marcel Ciolacu wird die Weltbankgruppe Rum\u00e4nien in den n\u00e4chsten drei Jahren sch\u00e4tzungsweise mehr als sechs Milliarden Dollar zu g\u00fcnstigen finanziellen Bedingungen zur Verf\u00fcgung stellen. Das Geld werde dazu beitragen, das Entwicklungsgef\u00e4lle [&hellip;]","og_url":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html","og_site_name":"Radio Rum\u00e4nien International","article_published_time":"2024-10-03T14:56:44+00:00","article_modified_time":"2024-10-03T15:04:44+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Nachrichten-2-NOU.jpg","type":"image\/jpeg"}],"author":"Newsroom","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Newsroom","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten","Written by":"Newsroom"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html"},"author":{"name":"Newsroom","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"headline":"Nachrichten 03.10.2024","datePublished":"2024-10-03T14:56:44+00:00","dateModified":"2024-10-03T15:04:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html"},"wordCount":737,"image":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Nachrichten-2-NOU.jpg","keywords":["Adrian C\u00e2ciu","Arbeitslosenquote","Premierminister Marcel Ciolacu","Programm DiscoverEU 2024","Regierung","Roxana Minzatu"],"articleSection":["Newsflash"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html","url":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html","name":"Nachrichten 03.10.2024 - Radio Rum\u00e4nien International","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Nachrichten-2-NOU.jpg","datePublished":"2024-10-03T14:56:44+00:00","dateModified":"2024-10-03T15:04:44+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Nachrichten-2-NOU.jpg","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Nachrichten-2-NOU.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de\/nachrichten-03-10-2024-id813787.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.rri.ro\/de"},{"@type":"ListItem","position":2,"name":"Aktuell","item":"https:\/\/www.rri.ro\/de\/aktuell"},{"@type":"ListItem","position":3,"name":"Newsflash","item":"https:\/\/www.rri.ro\/de\/aktuell\/newsflash-de"},{"@type":"ListItem","position":4,"name":"Nachrichten 03.10.2024"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Rum\u00e4nien International","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88","name":"Newsroom","url":"https:\/\/www.rri.ro\/de\/author\/newsroom"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/posts\/813787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/comments?post=813787"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/posts\/813787\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/media\/723386"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/media?parent=813787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/categories?post=813787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/tags?post=813787"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/de\/wp-json\/wp\/v2\/coauthors?post=813787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}