{"id":45746,"count":6,"description":"","link":"https:\/\/www.rri.ro\/en\/tag\/alina-popescu","name":"Alina Popescu","slug":"alina-popescu","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arhive Alina Popescu - Radio Romania International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/en\/tag\/alina-popescu\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arhive Alina Popescu - Radio Romania International\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/en\/tag\/alina-popescu\" \/>\n<meta property=\"og:site_name\" content=\"Radio Romania International\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/en\\\/tag\\\/alina-popescu\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/en\\\/tag\\\/alina-popescu\",\"name\":\"Arhive Alina Popescu - Radio Romania International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/en\\\/tag\\\/alina-popescu#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/en\\\/tag\\\/alina-popescu#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alina Popescu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Romania International\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arhive Alina Popescu - Radio Romania International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/en\/tag\/alina-popescu","og_locale":"en_US","og_type":"article","og_title":"Arhive Alina Popescu - Radio Romania International","og_url":"https:\/\/www.rri.ro\/en\/tag\/alina-popescu","og_site_name":"Radio Romania International","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.rri.ro\/en\/tag\/alina-popescu","url":"https:\/\/www.rri.ro\/en\/tag\/alina-popescu","name":"Arhive Alina Popescu - Radio Romania International","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/en\/tag\/alina-popescu#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/en\/tag\/alina-popescu#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/www.rri.ro\/en"},{"@type":"ListItem","position":2,"name":"Alina Popescu"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Romania International","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/en\/wp-json\/wp\/v2\/tags\/45746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.rri.ro\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.rri.ro\/en\/wp-json\/wp\/v2\/posts?tags=45746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}