{"id":199541,"date":"2014-06-24T16:28:00","date_gmt":"2014-06-24T13:28:00","guid":{"rendered":"http:\/\/devrri.freshlemon.ro\/actualidad\/ucrania-y-europa-id199541.html"},"modified":"2024-02-21T11:05:12","modified_gmt":"2024-02-21T09:05:12","slug":"ucrania-y-europa","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html","title":{"rendered":"Ucrania y Europa"},"content":{"rendered":"<p>Rusia debe apoyar el plan propuesto por el presidente de Ucrania, Petro Poroshenko, para solucionar la crisis ucraniana y usar su influencia para contener a los separatistas del sudeste de este pa\u00eds, seg\u00fan se menciona en un comunicado  tras la reuni\u00f3n del lunes pasado del Consejo de la UE con los ministros de eExteriores. El documento tambi\u00e9n contiene un llamamiento a Mosc\u00fa para que contin\u00fae  retirando sus tropas de la frontera. A su  vez, EE UU vuelve a se\u00f1alar que est\u00e1n preparados para introducir sanciones adicionales y exigen a Rusia que use su influencia para liberar a los observadores de la OSCE retenidos por los rebeldes.&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Cabe recordar que la semana pasada, Poroshenko orden\u00f3 el cese del fuego en la regi\u00f3n de Donbass hasta el pr\u00f3ximo 27 de junio. La orden forma parte de un plan cuyo objetivo es solucionar el conflicto del sudeste de Ucrania, plan que incluye negociaciones, la creaci\u00f3n de una zona tamp\u00f3n de diez kil\u00f3metros en la frontera ruso-ucraniana y un corredor para permitir el paso  a Rusia a los mercenarios rusos presentes en Ucrania una vez depuestas las armas. Los l\u00edderes de los separatistas han declarado que respetar\u00e1n esta tregua temporal.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>El corresponsal de Radio Ruman\u00eda en Mosc\u00fa ha transmitido que ya se han celebrado negociaciones ruso-ucranianas bajo la \u00e9gida de la OSCE. Los separatistas condicionan las negociaciones a la retirada de las formaciones paramilitares ucranianas, de la Guardia Nacional y de las tropas reguladas, as\u00ed como de las compensaciones por parte de Kiev para las familias de las v\u00edctimas, heridos o muertos  durante las operaciones militares. Los rebeldes tambi\u00e9n solicitan la amnist\u00eda de todos los participantes en el movimiento de insurgencia y que el presidente ucraniano y los representantes de las dos rep\u00fablicas autoproclamadas se decidan sobre un proyecto de acta de constituci\u00f3n que establezca su estatuto.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>En visi\u00f3n de los separatistas, el documento podr\u00eda referirse a un estatuto de federaci\u00f3n, de confederaci\u00f3n o de otro estatuto especial de las dos regiones en la composici\u00f3n de Ucrania, condici\u00f3n que Kiev ha rechazado rotundamente hasta ahora. Por otra parte, el presidente de EE UU, Barack Obama, inst\u00f3 el pasado lunes, a su homol\u00f3go ruso, Vladimir Putin, a frenar el env\u00edo de armas a Ucrania y a dejar de apoyar a los separatistas en el este de ese pa\u00eds europeo. Obama le advirti\u00f3 a Putin que si Rusia no act\u00faa, le podr\u00edan imponer m\u00e1s sanciones. Anteriormente, el ministro brit\u00e1nico de Exteriores, William Hague ha declarado que, en su opini\u00f3n, el plan de paz propuesto por el presidente ucraniano, Petro Poroshenko, es \u201cun plan fuerte y muy bueno\u201d y conf\u00eda en que \u201ctodo el mundo, incluyendo Rusia, trabaje en ello\u201d. A\u00fan as\u00ed, Hague ha advertido que si el pr\u00f3ximo viernes Mosc\u00fa no ha tomado medidas reales para apoyar el plan de paz de Poroshenko, la UE le impondr\u00e1 nuevas sanciones al Kreml\u00edn.<\/p>\n<p>&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La UE ha incrementado la presi\u00f3n sobre el Kreml\u00edn, obligada ante la amenaza de sanciones econ\u00f3micas m\u00e1s duras a cooperar con la aplicaci\u00f3n del plan de paz propuesto por el presidente ucraniano, Petro Petroshenko.<\/p>\n","protected":false},"author":111,"featured_media":55299,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[],"coauthors":[],"class_list":["post-199541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-portada"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ucrania y Europa - Radio Ruman\u00eda Internacional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ucrania y Europa - Radio Ruman\u00eda Internacional\" \/>\n<meta property=\"og:description\" content=\"La UE ha incrementado la presi\u00f3n sobre el Kreml\u00edn, obligada ante la amenaza de sanciones econ\u00f3micas m\u00e1s duras a cooperar con la aplicaci\u00f3n del plan de paz propuesto por el presidente ucraniano, Petro Petroshenko.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Ruman\u00eda Internacional\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-24T13:28:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-21T09:05:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/porosenko-kerry_medium.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Valentin \u021aig\u0103u\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valentin \u021aig\u0103u\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Valentin \u021aig\u0103u\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\\\/ucrania-y-europa-id199541.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\\\/ucrania-y-europa-id199541.html\"},\"author\":{\"name\":\"Valentin \u021aig\u0103u\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/dd2e33092651deba594240e14c678732\"},\"headline\":\"Ucrania y Europa\",\"datePublished\":\"2014-06-24T13:28:00+00:00\",\"dateModified\":\"2024-02-21T09:05:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\\\/ucrania-y-europa-id199541.html\"},\"wordCount\":515,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\\\/ucrania-y-europa-id199541.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/porosenko-kerry_medium.png\",\"articleSection\":[\"En portada\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\\\/ucrania-y-europa-id199541.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\\\/ucrania-y-europa-id199541.html\",\"name\":\"Ucrania y Europa - Radio Ruman\u00eda Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\\\/ucrania-y-europa-id199541.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\\\/ucrania-y-europa-id199541.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/porosenko-kerry_medium.png\",\"datePublished\":\"2014-06-24T13:28:00+00:00\",\"dateModified\":\"2024-02-21T09:05:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/dd2e33092651deba594240e14c678732\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\\\/ucrania-y-europa-id199541.html#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\\\/ucrania-y-europa-id199541.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\\\/ucrania-y-europa-id199541.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/porosenko-kerry_medium.png\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/porosenko-kerry_medium.png\",\"width\":640,\"height\":441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\\\/ucrania-y-europa-id199541.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina de inicio\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"En portada\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/en-portada\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ucrania y Europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Ruman\u00eda Internacional\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/dd2e33092651deba594240e14c678732\",\"name\":\"Valentin \u021aig\u0103u\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/author\\\/valentin-tigau\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ucrania y Europa - Radio Ruman\u00eda Internacional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html","og_locale":"es_ES","og_type":"article","og_title":"Ucrania y Europa - Radio Ruman\u00eda Internacional","og_description":"La UE ha incrementado la presi\u00f3n sobre el Kreml\u00edn, obligada ante la amenaza de sanciones econ\u00f3micas m\u00e1s duras a cooperar con la aplicaci\u00f3n del plan de paz propuesto por el presidente ucraniano, Petro Petroshenko.","og_url":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html","og_site_name":"Radio Ruman\u00eda Internacional","article_published_time":"2014-06-24T13:28:00+00:00","article_modified_time":"2024-02-21T09:05:12+00:00","og_image":[{"width":640,"height":441,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/porosenko-kerry_medium.png","type":"image\/png"}],"author":"Valentin \u021aig\u0103u","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Valentin \u021aig\u0103u","Tiempo de lectura":"3 minutos","Written by":"Valentin \u021aig\u0103u"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html"},"author":{"name":"Valentin \u021aig\u0103u","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/dd2e33092651deba594240e14c678732"},"headline":"Ucrania y Europa","datePublished":"2014-06-24T13:28:00+00:00","dateModified":"2024-02-21T09:05:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html"},"wordCount":515,"image":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/porosenko-kerry_medium.png","articleSection":["En portada"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html","url":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html","name":"Ucrania y Europa - Radio Ruman\u00eda Internacional","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/porosenko-kerry_medium.png","datePublished":"2014-06-24T13:28:00+00:00","dateModified":"2024-02-21T09:05:12+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/dd2e33092651deba594240e14c678732"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/porosenko-kerry_medium.png","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/porosenko-kerry_medium.png","width":640,"height":441},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada\/ucrania-y-europa-id199541.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina de inicio","item":"https:\/\/www.rri.ro\/es"},{"@type":"ListItem","position":2,"name":"Actualidad","item":"https:\/\/www.rri.ro\/es\/actualidad"},{"@type":"ListItem","position":3,"name":"En portada","item":"https:\/\/www.rri.ro\/es\/actualidad\/en-portada"},{"@type":"ListItem","position":4,"name":"Ucrania y Europa"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Ruman\u00eda Internacional","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/dd2e33092651deba594240e14c678732","name":"Valentin \u021aig\u0103u","url":"https:\/\/www.rri.ro\/es\/author\/valentin-tigau"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts\/199541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/comments?post=199541"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts\/199541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/media\/55299"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/media?parent=199541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/categories?post=199541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/tags?post=199541"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/coauthors?post=199541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}