{"id":207519,"date":"2016-05-18T17:58:00","date_gmt":"2016-05-18T14:58:00","guid":{"rendered":"http:\/\/devrri.freshlemon.ro\/actualidad\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html"},"modified":"2024-02-21T14:12:53","modified_gmt":"2024-02-21T12:12:53","slug":"el-expediente-de-los-desinfectantes-en-los-hospitales","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html","title":{"rendered":"El expediente de los desinfectantes en los hospitales"},"content":{"rendered":"<p>La compa\u00f1\u00eda Hexi Pharma que ha dado lugar al  esc\u00e1ndalo de la medicina rumana relacionado con los desinfectantes diluidos, ha retirado su solicitud de entrar en insolvencia presentada  ante el Tribunal de Bucarest. Acusada de diluir las sustancias de esterilizaci\u00f3n que suministraba a varios hospitales de todo el pa\u00eds, la compa\u00f1\u00eda es objeto de un proceso penal en este caso investigado por la Fiscal\u00eda General, por participaci\u00f3n inadecuada en el delito de obstaculizar el combate de las enfermedades. <\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Los representantes de la compa\u00f1\u00eda presentaron, la semana pasada, una solicitud para entrar en insolvencia argumentando que ya no pod\u00edan hacer frente a las deudas comerciales y fiscales a ra\u00edz de la coyuntura econ\u00f3mica desfavorable.La compa\u00f1\u00eda afirmaba que ten\u00eda que pagar deudas por un valor de 23 millones de lei al presupuesto de Estado, y a varios suministradores, as\u00ed como atrasos a dos compa\u00f1\u00edas del extranjero por un  valor de m\u00e1s de 20 millones de euros. Pese a ello, los representantes de la compa\u00f1\u00eda cambiaron de opini\u00f3n y el pasado martes, los jueces tomaron nota de que la empresa hab\u00eda retirado la solicitud de entrar en insolvencia.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>La decisi\u00f3n de la compa\u00f1\u00eda llega tras la tomada por parte de los jueces, que hab\u00edan admitido una solicitud de la Fiscal\u00eda General, de llevar a cabo varias medidas de prevenci\u00f3n con respecto a  Hexi Pharma. Entre \u00e9stas figura la prohibici\u00f3n de iniciar el procedimiento de disoluci\u00f3n o liquidaci\u00f3n, de fusionar, dividir o reducir el capital social, y la prohibici\u00f3n de producir y comercializar productos biocidas. Otra medida se refiere a la prohibici\u00f3n de enajenar los activos, los pagos, las transferencias de dinero, salvo las necesarias al pago de  los servicios y los salarios. Con respecto a las investigaciones en el caso de los desinfectantes diluidos, \u00e9stas avanzan r\u00e1pidamente, ha declarado el fiscal general de Ruman\u00eda, Augustin Lazar:<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p style=margin-left: 40px;>\u201cEn un plazo razonable vamos a  efectuar una investigaci\u00f3n efectiva para poder aclarar estas cosas. Desde la fecha de notificaci\u00f3n, el fiscal implicado en la investigaci\u00f3n avanza a un ritmo muy r\u00e1pido.\u201d<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Durante las investigaciones relacionadas con Hexi Pharma, los fiscales han efectuado incluso an\u00e1lisis f\u00edsicos y qu\u00edmicos de los productos incriminados. El fiscal general Augustin Lazar mencionaba que en este caso se beneficia de todos los recursos necesarios tanto por parte del Ministerio P\u00fablico, as\u00ed como por parte de la Polic\u00eda Judicial y que el objetivo es el  de identificar a las personas responsables. Entretanto, la actividad de la compa\u00f1\u00eda Hexi Pharma es controlada tambi\u00e9n por  la Agencia Nacional de Administraci\u00f3n Fiscal que verifica incluso  sus relaciones con las empresas del extranjero.<\/p>\n<p>&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La compa\u00f1\u00eda Hexi Pharma ha retirado su solicitud de entrar en insolvencia presentada en el tribunal. Anteriormente, los jueces hab\u00edan decidido que dicha compa\u00f1\u00eda, no puede disolverse, ni enajenar  activos, ni enajenar  activos, ni producir o vender<\/p>\n","protected":false},"author":46,"featured_media":68585,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[49231],"tags":[49347,30326,49348],"coauthors":[],"class_list":["post-207519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tema-del-dia","tag-disolvente","tag-hexi-pharma","tag-infecciones-en-los-hospitales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El expediente de los desinfectantes en los hospitales - Radio Ruman\u00eda Internacional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El expediente de los desinfectantes en los hospitales - Radio Ruman\u00eda Internacional\" \/>\n<meta property=\"og:description\" content=\"La compa\u00f1\u00eda Hexi Pharma ha retirado su solicitud de entrar en insolvencia presentada en el tribunal. Anteriormente, los jueces hab\u00edan decidido que dicha compa\u00f1\u00eda, no puede disolverse, ni enajenar activos, ni enajenar activos, ni producir o vender\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Ruman\u00eda Internacional\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-18T14:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-21T12:12:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/dezinfectanti-spital-medic-640.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Leyla Cheamil\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leyla Cheamil\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Leyla Cheamil\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\\\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\\\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html\"},\"author\":{\"name\":\"Leyla Cheamil\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/e6364ed2d4b6af207a82ca66000d07e0\"},\"headline\":\"El expediente de los desinfectantes en los hospitales\",\"datePublished\":\"2016-05-18T14:58:00+00:00\",\"dateModified\":\"2024-02-21T12:12:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\\\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html\"},\"wordCount\":475,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\\\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/dezinfectanti-spital-medic-640.png\",\"keywords\":[\"disolvente\",\"Hexi Pharma\",\"infecciones en los hospitales\"],\"articleSection\":[\"Tema del d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\\\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\\\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html\",\"name\":\"El expediente de los desinfectantes en los hospitales - Radio Ruman\u00eda Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\\\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\\\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/dezinfectanti-spital-medic-640.png\",\"datePublished\":\"2016-05-18T14:58:00+00:00\",\"dateModified\":\"2024-02-21T12:12:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/e6364ed2d4b6af207a82ca66000d07e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\\\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\\\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\\\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/dezinfectanti-spital-medic-640.png\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/dezinfectanti-spital-medic-640.png\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\\\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina de inicio\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tema del d\u00eda\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/tema-del-dia\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"El expediente de los desinfectantes en los hospitales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Ruman\u00eda Internacional\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/e6364ed2d4b6af207a82ca66000d07e0\",\"name\":\"Leyla Cheamil\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/author\\\/leyla-cheamil\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El expediente de los desinfectantes en los hospitales - Radio Ruman\u00eda Internacional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html","og_locale":"es_ES","og_type":"article","og_title":"El expediente de los desinfectantes en los hospitales - Radio Ruman\u00eda Internacional","og_description":"La compa\u00f1\u00eda Hexi Pharma ha retirado su solicitud de entrar en insolvencia presentada en el tribunal. Anteriormente, los jueces hab\u00edan decidido que dicha compa\u00f1\u00eda, no puede disolverse, ni enajenar activos, ni enajenar activos, ni producir o vender","og_url":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html","og_site_name":"Radio Ruman\u00eda Internacional","article_published_time":"2016-05-18T14:58:00+00:00","article_modified_time":"2024-02-21T12:12:53+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/dezinfectanti-spital-medic-640.png","type":"image\/png"}],"author":"Leyla Cheamil","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Leyla Cheamil","Tiempo de lectura":"2 minutos","Written by":"Leyla Cheamil"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html"},"author":{"name":"Leyla Cheamil","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/e6364ed2d4b6af207a82ca66000d07e0"},"headline":"El expediente de los desinfectantes en los hospitales","datePublished":"2016-05-18T14:58:00+00:00","dateModified":"2024-02-21T12:12:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html"},"wordCount":475,"image":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/dezinfectanti-spital-medic-640.png","keywords":["disolvente","Hexi Pharma","infecciones en los hospitales"],"articleSection":["Tema del d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html","url":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html","name":"El expediente de los desinfectantes en los hospitales - Radio Ruman\u00eda Internacional","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/dezinfectanti-spital-medic-640.png","datePublished":"2016-05-18T14:58:00+00:00","dateModified":"2024-02-21T12:12:53+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/e6364ed2d4b6af207a82ca66000d07e0"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/dezinfectanti-spital-medic-640.png","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/dezinfectanti-spital-medic-640.png","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia\/el-expediente-de-los-desinfectantes-en-los-hospitales-id207519.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina de inicio","item":"https:\/\/www.rri.ro\/es"},{"@type":"ListItem","position":2,"name":"Actualidad","item":"https:\/\/www.rri.ro\/es\/actualidad"},{"@type":"ListItem","position":3,"name":"Tema del d\u00eda","item":"https:\/\/www.rri.ro\/es\/actualidad\/tema-del-dia"},{"@type":"ListItem","position":4,"name":"El expediente de los desinfectantes en los hospitales"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Ruman\u00eda Internacional","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/e6364ed2d4b6af207a82ca66000d07e0","name":"Leyla Cheamil","url":"https:\/\/www.rri.ro\/es\/author\/leyla-cheamil"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts\/207519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/comments?post=207519"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts\/207519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/media\/68585"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/media?parent=207519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/categories?post=207519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/tags?post=207519"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/coauthors?post=207519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}