{"id":553654,"date":"2014-03-28T16:47:00","date_gmt":"2014-03-28T14:47:00","guid":{"rendered":"http:\/\/devrri.freshlemon.ro\/actualidad\/terapia-con-caballos-id553654.html"},"modified":"2024-02-22T08:19:43","modified_gmt":"2024-02-22T06:19:43","slug":"terapia-con-caballos","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html","title":{"rendered":"Terapia con caballos"},"content":{"rendered":"<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>El psiquiatra estadounidense Dr. Boris Levinson fue uno de los primeros profesionales en la salud humana en escribir sobre el valor psicoterap\u00e9utico de los animales en su libro publicado en 1969. Su perro Jingles se encontr\u00f3 de forma accidental con uno de sus pacientes j\u00f3venes y este acontecimiento ayud\u00f3 en la comunicaci\u00f3n y en el proceso de curaci\u00f3n.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Las investigaciones demuestran que los perros son capaces de anticipar ataques de epilepsia en sus due\u00f1os, que los papagayos habladores alivian los dolores cardiacos, que acariciar gatos disminuye la presi\u00f3n arterial y ayuda a reducir el estr\u00e9s. Los delfines consiguen comunicarse con los ni\u00f1os autistas, la equitaci\u00f3n puede beneficiar a personas con alguna disfunci\u00f3n cognitiva, f\u00edsica o emocional y mirar un acuario puede tener un efecto relajante.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>El objetivo de la Terapia Asistida con Animales es mejorar la calidad emocional de las personas con distintas formas de discapacidady ofrecer apoyo a su inserci\u00f3n social.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>En Ruman\u00eda esta terapia alternativa esmuy reciente y se aplica para recuperar a los presos y a los ni\u00f1os con discapacidades.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Lilica Fr\u0103\u021biman, catedr\u00e1tica universitaria, pediatra en el hospital de Constanza y decana de la Facultad de Psicolog\u00eda Andrei \u0218aguna de Constanza, nos ha hablado sobre el papel de la hipoterapia, terapia con caballos:<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<blockquote><p>&#13;<\/p>\n<p><strong> <\/strong><em>\u201cLa hipoterapia sirve para varias cosas. Nosotros consideramos que es una terapia alternativa \u00fatil para las personas con problemas de adaptaci\u00f3n social ode salud. Hablamos de personas con deficiencias psicomotrices, ni\u00f1os con par\u00e1lisis cerebral, con s\u00edndromes gen\u00e9ticos, como es el s\u00edndrome Down. Hemos desarrollado la psicoterapia con caballos para ni\u00f1os con autismo o trastornos del espectro del autismo. Luego hemos aplicado esta terapia para otros tipos de enfermedades. Como bien se sabe, los ni\u00f1os autistas no viven en nuestro mundo, sino que viven en su mundo propio. No est\u00e1n enfermos, sino que no consiguen conectarse con la realidad social tal como la conocemos. El caballo, con su instinto protector y su paso sosegado, consigue acercar al ni\u00f1o a nuestro mundo. El caballo ayuda un poco al ni\u00f1o a tomar contacto con la realidad y el trote del caballo le ayuda a lograr un estado de relajaci\u00f3n quele puede ayudar a aprender nuevos movimientos, incluso palabras nuevas. Se consiguen progresos extraordinarios en la evoluci\u00f3n del ni\u00f1o autista. Lo mismo ocurre en otros tipos de enfermedades gen\u00e9ticas o enfermedades degenerativas o enfermedades secundarias como las hipoxias de nacimiento.\u201d<\/em><\/p>\n<p>&#13;\n<\/p><\/blockquote>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Los estudios cient\u00edficos efectuados a lo largo del tiempo han demostrado los efectos beneficiosos que aporta la tenencia animales de compa\u00f1\u00eda para las personas solas, enfermas,o para los ni\u00f1os con  discapacidades. Se ha comprobado que los animales pueden mejorar el estado ps\u00edquico y el nivel de comunicaci\u00f3n interpersonal, pueden aumentar la autoestima. Si la terapia con perros y gatos es m\u00e1s habitual, la terapia con caballos es menos conocida. Varios centros del pa\u00eds se han organizado para promover este tipo de terapia. Al comienzo solo se pod\u00eda practicar en verano cuando hac\u00eda buen tiempo, pero ahora hay varios centros cubiertos que se pueden utilizar todo el a\u00f1o.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>La terapia con caballos o ponis se recomienda tambi\u00e9n a los ni\u00f1os demasiado din\u00e1micos, porque el ritmo del trote del caballo se parece al ritmo cardiaco de la madre y relaja a estos ni\u00f1os. Se aplica como terapia alternativa en los casos de autismo severo. Al interaccionar con el cuerpod el caballo, el ni\u00f1o autista descubre su propio cuerpo y se crean las premisas para distinguir entre su mundo, que considera el \u00fanico universo, y el mundo exterior que es separado de \u00e9l.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Sobre la eficiencia de esta terapia nos habla de nuevo Lilica Fr\u0103\u021biman.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<blockquote><p>&#13;<\/p>\n<p><em>\u201cLos resultados dependen de la gravedad del caso y del tipo de enfermedad. He visto ni\u00f1os con autismo que han cambiado su comportamiento de una sesi\u00f3n para otra. He visto ni\u00f1os que llegaron llorando y gritando porque no quer\u00edan contactar con las personas de su alrededor y una vez a lomos del caballo, sonre\u00edan y acariciaban al caballo al cabo de solo 30 minutos. Hablar de resultados estables solo se puede hacer tras varias semanas de terapia y hay dos o tres sesiones a la semana.\u201d<\/em><\/p>\n<p>&#13;\n<\/p><\/blockquote>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Una sesi\u00f3n de hipoterapia dura entre 30 minutos y una hora en funci\u00f3n del estado del paciente y de su deseo de colaborar. Hay asociaciones que luchan por introducir la hipoterapia como una terapia complementaria para enfermedades ps\u00edquicas y pretenden introducir en el sistema nacional un curso de psicoterapia con caballos.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>(trad. Irina Calin)<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los estudios cient\u00edficos efectuados a lo largo del tiempo han demostrado los efectos beneficiosos que aporta la tenencia animales de compa\u00f1\u00eda para las personas solas, enfermas,o para los ni\u00f1os con  discapacidades.<\/p>\n","protected":false},"author":126,"featured_media":139830,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[112307],"tags":[],"coauthors":[],"class_list":["post-553654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terapia con caballos - Radio Ruman\u00eda Internacional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terapia con caballos - Radio Ruman\u00eda Internacional\" \/>\n<meta property=\"og:description\" content=\"Los estudios cient\u00edficos efectuados a lo largo del tiempo han demostrado los efectos beneficiosos que aporta la tenencia animales de compa\u00f1\u00eda para las personas solas, enfermas,o para los ni\u00f1os con discapacidades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Ruman\u00eda Internacional\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-28T14:47:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-22T06:19:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/hipoterapia-640.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ana-Maria Cononovici\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana-Maria Cononovici\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Ana-Maria Cononovici\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/terapia-con-caballos-id553654.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/terapia-con-caballos-id553654.html\"},\"author\":{\"name\":\"Ana-Maria Cononovici\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/70ee98042ca8b95ae29876ed4848670e\"},\"headline\":\"Terapia con caballos\",\"datePublished\":\"2014-03-28T14:47:00+00:00\",\"dateModified\":\"2024-02-22T06:19:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/terapia-con-caballos-id553654.html\"},\"wordCount\":791,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/terapia-con-caballos-id553654.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/hipoterapia-640.png\",\"articleSection\":[\"Sociedad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/terapia-con-caballos-id553654.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/terapia-con-caballos-id553654.html\",\"name\":\"Terapia con caballos - Radio Ruman\u00eda Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/terapia-con-caballos-id553654.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/terapia-con-caballos-id553654.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/hipoterapia-640.png\",\"datePublished\":\"2014-03-28T14:47:00+00:00\",\"dateModified\":\"2024-02-22T06:19:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/70ee98042ca8b95ae29876ed4848670e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/terapia-con-caballos-id553654.html#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/terapia-con-caballos-id553654.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/terapia-con-caballos-id553654.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/hipoterapia-640.png\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/hipoterapia-640.png\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/terapia-con-caballos-id553654.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina de inicio\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cr\u00f3nica semanal\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sociedad\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Terapia con caballos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Ruman\u00eda Internacional\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/70ee98042ca8b95ae29876ed4848670e\",\"name\":\"Ana-Maria Cononovici\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/author\\\/ana-maria-cononovici\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terapia con caballos - Radio Ruman\u00eda Internacional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html","og_locale":"es_ES","og_type":"article","og_title":"Terapia con caballos - Radio Ruman\u00eda Internacional","og_description":"Los estudios cient\u00edficos efectuados a lo largo del tiempo han demostrado los efectos beneficiosos que aporta la tenencia animales de compa\u00f1\u00eda para las personas solas, enfermas,o para los ni\u00f1os con discapacidades.","og_url":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html","og_site_name":"Radio Ruman\u00eda Internacional","article_published_time":"2014-03-28T14:47:00+00:00","article_modified_time":"2024-02-22T06:19:43+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/hipoterapia-640.png","type":"image\/png"}],"author":"Ana-Maria Cononovici","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ana-Maria Cononovici","Tiempo de lectura":"4 minutos","Written by":"Ana-Maria Cononovici"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html"},"author":{"name":"Ana-Maria Cononovici","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/70ee98042ca8b95ae29876ed4848670e"},"headline":"Terapia con caballos","datePublished":"2014-03-28T14:47:00+00:00","dateModified":"2024-02-22T06:19:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html"},"wordCount":791,"image":{"@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/hipoterapia-640.png","articleSection":["Sociedad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html","url":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html","name":"Terapia con caballos - Radio Ruman\u00eda Internacional","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/hipoterapia-640.png","datePublished":"2014-03-28T14:47:00+00:00","dateModified":"2024-02-22T06:19:43+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/70ee98042ca8b95ae29876ed4848670e"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/hipoterapia-640.png","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/hipoterapia-640.png","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/terapia-con-caballos-id553654.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina de inicio","item":"https:\/\/www.rri.ro\/es"},{"@type":"ListItem","position":2,"name":"Cr\u00f3nica semanal","item":"https:\/\/www.rri.ro\/es\/cronica-semanal"},{"@type":"ListItem","position":3,"name":"Sociedad","item":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad"},{"@type":"ListItem","position":4,"name":"Terapia con caballos"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Ruman\u00eda Internacional","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/70ee98042ca8b95ae29876ed4848670e","name":"Ana-Maria Cononovici","url":"https:\/\/www.rri.ro\/es\/author\/ana-maria-cononovici"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts\/553654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/comments?post=553654"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts\/553654\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/media\/139830"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/media?parent=553654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/categories?post=553654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/tags?post=553654"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/coauthors?post=553654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}