{"id":553905,"date":"2017-05-10T19:45:00","date_gmt":"2017-05-10T16:45:00","guid":{"rendered":"http:\/\/devrri.freshlemon.ro\/actualidad\/evaluacion-de-la-educacion-id553905.html"},"modified":"2024-02-22T08:22:18","modified_gmt":"2024-02-22T06:22:18","slug":"evaluacion-de-la-educacion","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html","title":{"rendered":"Evaluaci\u00f3n de la educaci\u00f3n"},"content":{"rendered":"<p>El sistema educativo rumano procura hacer frente a los desaf\u00edos del siglo XXI a pesar de verse atrapado en una vor\u00e1gine de cambios que se suceden sin cesar desde hace unos veinte a\u00f1os. Uno de los desaf\u00edos m\u00e1s importantes es la autoevaluaci\u00f3n del sistema que consiste en evaluar a los docentes y los resultados de los alumnos y los estudiantes. Recientemente, un estudio realizado por las autoridades rumanas junto con UNICEF y la Organizaci\u00f3n de Cooperaci\u00f3n y Desarrollo en Europa (OCDE) pone bajo la lupa la evaluaci\u00f3n y los ex\u00e1menes en el \u00e1mbito educativo. Actualmente hay pruebas de diagn\u00f3stico para el alumnado de segundo, cuarto y sexto curso. Luego, en el octavo curso, los alumnos realizan la prueba de selectividad llamada Evaluaci\u00f3n Nacional para acceso al liceo. Esta prueba despierta muchas controversias. Ioana B\u0103lt\u0103re\u0163u, miembra del Consejo Nacional de Alumnos :<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p style=margin-left: 40px;><strong><em>En lo que se refiere a nuestra evaluaci\u00f3n el Consejo Nacional de Alumnos ha destacado que muchas veces se enfatiza demasiado el estudio de las asignaturas que son objeto de las pruebas y de los ex\u00e1menes nacionales. Estos ex\u00e1menes eval\u00faan en primer lugar la memorizaci\u00f3n de contenidos en detrimento de las capacidades de razonamiento. Casi un 40% de los alumnos rumanos de 15 a\u00f1os de edad son analfabetos funcionales tal como lo demuestran los resultados recientes de los ex\u00e1menes PISA. Aunque saben leer, no entienden los textos respectivos a causa de t\u00e9cnicas de ense\u00f1anza y aprendizaje centrandas en la memorizaci\u00f3n.  <\/em><\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Los alumnos hacen muchos ex\u00e1menes a lo largo de su vida escolar y ahora les gustar\u00eda tambi\u00e9n implicarse en la evaluaci\u00f3n de la forma en que se les educa y se les trata en las escuelas. Ioana B\u0103lt\u0103re\u0163u:<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><em><strong>Consideramos que la implicaci\u00f3n de los alumnos en la evaluaci\u00f3n interna sigue siendo deficitaria. En un 97,5% de los casos los alumnos no pueden expresar su opini\u00f3n y ni siquiera est\u00e1n convocados a las reuniones en que deber\u00edan participar como el Consejo Escolar,  la comisi\u00f3n de evaluaci\u00f3n y aseguramiento de la calidad cuando se debaten temas relacionados con la lucha contra la violencia. Hace falta respetar la ley en vigor y respetar los derechos de los alumnos que son representantes del alumnado de una escuela.  Creemos que es absolutamente necesario que las evaluaciones dejen de ser una simple formalidad y se apliquen como un mecanismo que puede consolidar un sistema educativo de calidad.<\/strong><\/em><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>El estudio \u201dLas evaluaciones en el sistema educativo rumano\u201d realizado por UNICEF en colaboraci\u00f3n con la OCDE se refiere precisamente a este tema de las modalidades en que estas pruebas pueden ser m\u00e1s eficientes. De dicho estudio resulta que la situaci\u00f3n actual no es muy alentadora. En 2015 los alumnos rumanos registraron progresos en las pruebas PISA frente al 2012. Pero en el cap\u00edtulo \u201dCiencias\u201d, por ejemplo, casi un 39% de los alumnos de 15 a\u00f1os de edad se situaron por debajo del nivel 2, o sea por debajo del nivel b\u00e1sico necesario al finalizar el sistema educativo obligario para que sean eficientes en una sociedad del conocimiento. Partiendo de esta situaci\u00f3n ser\u00eda interesante preguntarnos \u00bfc\u00f3mo hacer que las  pruebas y los ex\u00e1menes sirvan no solo para medir sus conocimientos sino tambi\u00e9n para mejorar sus resultados?  Seg\u00fan los autores del informe, la respuesta consiste en flexibilizar el sistema educativo. La escuela debe convertirse no solo en un espacio de grandes logros, sino tambi\u00e9n de la inclusi\u00f3n, donde los alumnos consigan las habilidades y los conocimientos que se solicitan actualmente en el mercado laboral. A\u00fan quedan muchas cosas por mejorar en este aspecto, considera Andreas Schleicher, director de la OCDE.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p style=margin-left: 40px;><em><strong>Al principio de los a\u00f1os 2000, en Ruman\u00eda no hab\u00eda ninguna autoridad independiente encargada de evaluar las escuelas. Hoy en d\u00eda hay un centro de evaluaci\u00f3n y examen muy fuerte. Pero lo m\u00e1s importante es que Ruman\u00eda ofrece ahora uno de los pocos ejemplos de progreso real en Europa. Los nuevos curr\u00edculos est\u00e1n sincronizados con las aspiraciones del siglo XXI. Ofrecen a todos los j\u00f3venes la posibilidad de profundizar sus conocimientos, de adquirir las habilidades y el pensamiento cr\u00edtico necesarios para participar en la sociedad del ma\u00f1ana. Pero muchas veces en la educaci\u00f3n es f\u00e1cil teorizar y muy dif\u00edcil llevar a la pr\u00e1ctica las teor\u00edas. Parte de la infraestrucutura y de los docentes no est\u00e1n sincronizados con las necesidades del siglo XXI. Los ex\u00e1menes nacionales todav\u00eda determinan el futuro de los ni\u00f1os en base a un sistema muy r\u00edgido de conocimientos acad\u00e9micos desde una edad muy joven de  tan solo 14 a\u00f1os. Para nosotros esto es muy anticuado e incorrecto.<\/strong><\/em><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Para las autoridades rumanas, el aspecto m\u00e1s importante del informe  UNICEF-OCDE es la recomendaci\u00f3n de que estas pruebas del sistema primario y secundario tengan un car\u00e1cter formativo y no establezcan clasificaciones, ha declarado, Pavel N\u0103stase,  ministro de Educaci\u00f3n.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p style=margin-left: 40px;><strong><em>Tenemos que cambiar el enfoque y tratar la evaluaci\u00f3n de los alumnos, de los docentes, del sistema en general, como una oportunidad para recibir \u201dfeedback\u201d y de intervenir para hacer que el proceso educativo sea de mejor calidad y realmente centrado en los alumnos. Nosotros deseamos que los docentes reciban formaci\u00f3n para poder evaluar constantemente a los alumnos durante los cursos, d\u00eda a d\u00eda y no s\u00f3lo a trav\u00e9s de pruebas o ex\u00e1menes. De esta forma los alumnos sentir\u00e1n menos presi\u00f3n y les ser\u00e1 m\u00e1s f\u00e1cil mostrar lo que realmente saben. Por consiguiente un elemento muy importante de este informe es su componente de evaluaci\u00f3n formativa. Este tipo de evaluaci\u00f3n tiene como objetivo crear una ficha personalizada con recomendaciones de formaci\u00f3n para cada alumno. De momento realizamos la evaluaci\u00f3n, pero no en todas las escuelas se pasa a la segunda parte que es sacar las conclusiones necesarias de las evaluaciones y preparar un plan personalizado de formaci\u00f3n para cada alumno. <\/em><\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>El Ministerio de Educaci\u00f3n est\u00e1 preparando varios programas financiados de fondos europeos para el sistema educativo universitario y preuniversitario, centrados en la evaluaci\u00f3n del alumnado y de los docentes.  <\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sistema educativo rumano procura hacer frente a los desaf\u00edos del siglo XXI a pesar de verse atrapado en una vor\u00e1gine de cambios que se suceden sin cesar desde hace unos veinte a\u00f1os.<\/p>\n","protected":false},"author":2,"featured_media":71072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[112307],"tags":[],"coauthors":[],"class_list":["post-553905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evaluaci\u00f3n de la educaci\u00f3n - Radio Ruman\u00eda Internacional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evaluaci\u00f3n de la educaci\u00f3n - Radio Ruman\u00eda Internacional\" \/>\n<meta property=\"og:description\" content=\"El sistema educativo rumano procura hacer frente a los desaf\u00edos del siglo XXI a pesar de verse atrapado en una vor\u00e1gine de cambios que se suceden sin cesar desde hace unos veinte a\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Ruman\u00eda Internacional\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-10T16:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-22T06:22:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/scoala-si-elevii.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Rom\u00e2nia Interna\u021bional\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rom\u00e2nia Interna\u021bional\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Rom\u00e2nia Interna\u021bional\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/evaluacion-de-la-educacion-id553905.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/evaluacion-de-la-educacion-id553905.html\"},\"author\":{\"name\":\"Rom\u00e2nia Interna\u021bional\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/18fac491bccbfe149b92aea77ad60abd\"},\"headline\":\"Evaluaci\u00f3n de la educaci\u00f3n\",\"datePublished\":\"2017-05-10T16:45:00+00:00\",\"dateModified\":\"2024-02-22T06:22:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/evaluacion-de-la-educacion-id553905.html\"},\"wordCount\":1074,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/evaluacion-de-la-educacion-id553905.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/scoala-si-elevii.png\",\"articleSection\":[\"Sociedad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/evaluacion-de-la-educacion-id553905.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/evaluacion-de-la-educacion-id553905.html\",\"name\":\"Evaluaci\u00f3n de la educaci\u00f3n - Radio Ruman\u00eda Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/evaluacion-de-la-educacion-id553905.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/evaluacion-de-la-educacion-id553905.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/scoala-si-elevii.png\",\"datePublished\":\"2017-05-10T16:45:00+00:00\",\"dateModified\":\"2024-02-22T06:22:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/18fac491bccbfe149b92aea77ad60abd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/evaluacion-de-la-educacion-id553905.html#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/evaluacion-de-la-educacion-id553905.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/evaluacion-de-la-educacion-id553905.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/scoala-si-elevii.png\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/scoala-si-elevii.png\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\\\/evaluacion-de-la-educacion-id553905.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina de inicio\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cr\u00f3nica semanal\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sociedad\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/cronica-semanal\\\/sociedad\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Evaluaci\u00f3n de la educaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Ruman\u00eda Internacional\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/18fac491bccbfe149b92aea77ad60abd\",\"name\":\"Rom\u00e2nia Interna\u021bional\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/author\\\/redactia\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evaluaci\u00f3n de la educaci\u00f3n - Radio Ruman\u00eda Internacional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html","og_locale":"es_ES","og_type":"article","og_title":"Evaluaci\u00f3n de la educaci\u00f3n - Radio Ruman\u00eda Internacional","og_description":"El sistema educativo rumano procura hacer frente a los desaf\u00edos del siglo XXI a pesar de verse atrapado en una vor\u00e1gine de cambios que se suceden sin cesar desde hace unos veinte a\u00f1os.","og_url":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html","og_site_name":"Radio Ruman\u00eda Internacional","article_published_time":"2017-05-10T16:45:00+00:00","article_modified_time":"2024-02-22T06:22:18+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/scoala-si-elevii.png","type":"image\/png"}],"author":"Rom\u00e2nia Interna\u021bional","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rom\u00e2nia Interna\u021bional","Tiempo de lectura":"5 minutos","Written by":"Rom\u00e2nia Interna\u021bional"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html"},"author":{"name":"Rom\u00e2nia Interna\u021bional","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/18fac491bccbfe149b92aea77ad60abd"},"headline":"Evaluaci\u00f3n de la educaci\u00f3n","datePublished":"2017-05-10T16:45:00+00:00","dateModified":"2024-02-22T06:22:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html"},"wordCount":1074,"image":{"@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/scoala-si-elevii.png","articleSection":["Sociedad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html","url":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html","name":"Evaluaci\u00f3n de la educaci\u00f3n - Radio Ruman\u00eda Internacional","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/scoala-si-elevii.png","datePublished":"2017-05-10T16:45:00+00:00","dateModified":"2024-02-22T06:22:18+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/18fac491bccbfe149b92aea77ad60abd"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/scoala-si-elevii.png","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/scoala-si-elevii.png","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad\/evaluacion-de-la-educacion-id553905.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina de inicio","item":"https:\/\/www.rri.ro\/es"},{"@type":"ListItem","position":2,"name":"Cr\u00f3nica semanal","item":"https:\/\/www.rri.ro\/es\/cronica-semanal"},{"@type":"ListItem","position":3,"name":"Sociedad","item":"https:\/\/www.rri.ro\/es\/cronica-semanal\/sociedad"},{"@type":"ListItem","position":4,"name":"Evaluaci\u00f3n de la educaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Ruman\u00eda Internacional","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/18fac491bccbfe149b92aea77ad60abd","name":"Rom\u00e2nia Interna\u021bional","url":"https:\/\/www.rri.ro\/es\/author\/redactia"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts\/553905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/comments?post=553905"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts\/553905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/media\/71072"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/media?parent=553905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/categories?post=553905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/tags?post=553905"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/coauthors?post=553905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}