{"id":837289,"date":"2024-11-30T10:26:49","date_gmt":"2024-11-30T08:26:49","guid":{"rendered":"https:\/\/www.rri.ro\/?p=837289"},"modified":"2024-11-30T10:26:49","modified_gmt":"2024-11-30T08:26:49","slug":"retrospectiva-semanal-274","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html","title":{"rendered":"Retrospectiva semanal"},"content":{"rendered":"<p><strong>Elecciones con sorpresas y esc\u00e1ndalos<\/strong><\/p>\n<p>La organizaci\u00f3n en Ruman\u00eda, en un solo a\u00f1o, de todo tipo de elecciones &#8211; presidenciales, parlamentarias, europarlamentarias y locales &#8211; y de tres domingos consecutivos &#8211; 24 de noviembre, 1 y 8 de diciembre &#8211; reservados a la elecci\u00f3n del presidente y del Parlamento, represent\u00f3, aunque s\u00f3lo fuera en teor\u00eda, una verdadera prueba para las autoridades y la sociedad en su conjunto. Sin embargo, tras la primera vuelta de las elecciones presidenciales, el 24 de noviembre, a los retos log\u00edsticos se sumaron una gran sorpresa y un enorme esc\u00e1ndalo pol\u00edtico y social. En contra de todas las previsiones, el independiente soberanista C\u0103lin Georgescu, percibido como un extremista prorruso, se situ\u00f3 en primer lugar de las opciones de voto de los rumanos, seguido de la candidata de la USR (oposici\u00f3n), Elena Lasconi. Se impuso al primer ministro socialdem\u00f3crata Marcel Ciolacu por menos de 3.000 votos, tras una noche llena de giros y sorpresas. \u00bfQu\u00e9 ocurri\u00f3 despu\u00e9s? El primer ministro Ciolacu dimiti\u00f3 como l\u00edder del PSD, al igual que Nicolae Ciuc\u0103 como jefe del PNL (en cogobierno), tras quedar s\u00f3lo quinto en las opciones de voto de los rumanos. El Tribunal Constitucional, que el jueves deb\u00eda validar los resultados de la primera vuelta, orden\u00f3 una nueva comprobaci\u00f3n y recuento de todas las papeletas tras recibir una denuncia de que los votos obtenidos por un candidato que se retir\u00f3 de la carrera en el \u00faltimo momento hab\u00edan pasado a Elena Lasconi. La decisi\u00f3n de la Tribunal Constitucional de Ruman\u00eda fue criticada por la mayor\u00eda de los candidatos participantes en la contienda electoral, que advirtieron de que una posible anulaci\u00f3n de la votaci\u00f3n del 24 de noviembre generar\u00eda tensi\u00f3n e inestabilidad. Mientras tanto, tambi\u00e9n el jueves, el Consejo Supremo de Defensa del Pa\u00eds (CSAT, por sus siglas en rumano) se reuni\u00f3 y constat\u00f3 ciberataques destinados a influir en la imparcialidad del proceso electoral. Al mismo tiempo, uno de los candidatos -a\u00f1adi\u00f3 un comunicado de prensa del CSAT- recibi\u00f3 un trato preferente y una exposici\u00f3n masiva en TikTok. La plataforma, de propiedad china, neg\u00f3 las acusaciones dirigidas indirectamente contra C\u0103lin Georgescu, al afirmar que la mayor\u00eda de los candidatos hicieron campa\u00f1a en su plataforma, mientras que los que ganaron tambi\u00e9n lo hicieron en otras plataformas digitales, as\u00ed como en medios de comunicaci\u00f3n tradicionales. Por su parte, el Servicio de Telecomunicaciones Especiales inform\u00f3 de que se hab\u00edan aplicado medidas proactivas para prevenir y contrarrestar los riesgos de ciberseguridad para la organizaci\u00f3n de las elecciones del 24 de noviembre, y que los sistemas inform\u00e1ticos funcionaban con par\u00e1metros \u00f3ptimos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Elecciones parlamentarias, como en sordina<\/strong><\/p>\n<p>El \u00abruido\u00bb infernal tras la primera vuelta de las elecciones presidenciales ha hecho palidecer las elecciones parlamentarias previstas para el 1 de diciembre, Fiesta Nacional. No obstante, el voto de los rumanos es crucial en la medida en que la futura configuraci\u00f3n de la legislatura y la composici\u00f3n del Gobierno dependen de su resultado. Al t\u00e9rmino de una campa\u00f1a electoral que se prolongar\u00e1 hasta la ma\u00f1ana del 30 de noviembre, m\u00e1s de 8.000 candidatos de 31 partidos y alianzas y 19 organizaciones de minor\u00edas nacionales aspiran a ganar el voto de los rumanos para entrar en el Parlamento. Mientras que en Ruman\u00eda se vota en casi 19.000 colegios electorales el domingo, se espera que los rumanos en el extranjero acudan a las urnas en 950 colegios electorales durante dos d\u00edas: el s\u00e1bado 30 de noviembre y el domingo 1 de diciembre.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Refer\u00e9ndum para Bucarest<\/strong><\/p>\n<p>Paralelamente a la primera vuelta de las elecciones presidenciales, el 24 de noviembre, se organiz\u00f3 en Bucarest un refer\u00e9ndum deseado por el alcalde general Nicu\u0219or Dan. M\u00e1s del 64% de los ciudadanos de Bucarest respondieron \u00abS\u00ed\u00bb a la pregunta de si estaban de acuerdo con que el Consejo General del Ayuntamiento asumiera la distribuci\u00f3n por sectores de los impuestos sobre la renta y las tasas y los impuestos locales. Actualmente, este reparto lo hacen el Gobierno y el Parlamento. Asimismo, m\u00e1s del 66% de los habitantes de la capital est\u00e1n de acuerdo con que el alcalde general expida todas las licencias de obras. Por \u00faltimo, en la tercera pregunta del refer\u00e9ndum, propuesta por el PSD, m\u00e1s del 84% de los ciudadanos de Bucarest estuvieron de acuerdo en que el Ayuntamiento General financie un programa de lucha contra el consumo de drogas en las escuelas. La participaci\u00f3n fue de casi el 41%. Para ser aplicada, la votaci\u00f3n debe ser confirmada por el Legislativo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Rumanos y libre circulaci\u00f3n<\/strong><\/p>\n<p>Bucarest ha acogido con satisfacci\u00f3n la decisi\u00f3n del Comit\u00e9 de Representantes Permanentes de los Gobiernos de los Estados miembros de la Uni\u00f3n Europea (COREPER), que ha emitido un dictamen favorable a la entrada de Ruman\u00eda y Bulgaria en el espacio Schengen tambi\u00e9n con sus fronteras terrestres a partir del 1 de enero de 2025. La decisi\u00f3n se tom\u00f3 por unanimidad en Bruselas. El acuerdo pasar\u00e1 al Consejo de Justicia y Asuntos de Interior para su aprobaci\u00f3n a mediados de diciembre. Por otro lado, Ruman\u00eda ha cumplido los criterios de la tasa de denegaci\u00f3n de visados esenciales para clasificarse al Programa de Exenci\u00f3n de Visados, que permite viajar sin visado a Estados Unidos. El Departamento de Estado estadounidense ha publicado un informe que muestra que Ruman\u00eda ha quedado por debajo del umbral del 3% impuesto por la ley estadounidense. En concreto, los rumanos han presentado este a\u00f1o unas 80.000 solicitudes de visado, de las cuales 78.000, una cifra r\u00e9cord, han sido aceptadas por las oficinas diplom\u00e1ticas estadounidenses.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La nueva Comisi\u00f3n Europea, lista para empezar a trabajar<\/strong><\/p>\n<p>El Parlamento Europeo vot\u00f3 el mi\u00e9rcoles a favor de la nueva Comisi\u00f3n Europea. La rumana Roxana M\u00eenzatu ser\u00e1 una de las vicepresidentas del Ejecutivo, tambi\u00e9n dirigido por Ursula von der Leyen. Su primera iniciativa ser\u00e1 la adopci\u00f3n de un plan estrat\u00e9gico para impulsar la econom\u00eda y la competitividad europeas. Roxana M\u00eenzatu tambi\u00e9n coordinar\u00e1 indirectamente esta \u00e1rea, ya que se encargar\u00e1 de las pol\u00edticas sociales y la formaci\u00f3n profesional de los trabajadores europeos. Tambi\u00e9n se encargar\u00e1 del amplio espectro de la preparaci\u00f3n de la sociedad para tiempos de crisis, que abarca no s\u00f3lo las guerras y las cat\u00e1strofes clim\u00e1ticas, sino tambi\u00e9n la transici\u00f3n ecol\u00f3gica, la digitalizaci\u00f3n y las cuestiones sociales. La nueva Comisi\u00f3n entrar\u00e1 en funciones el 1 de diciembre.<\/p>\n<p>Versi\u00f3n en espa\u00f1ol: Monica Tar\u0103u<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elecciones con sorpresas y esc\u00e1ndalos La organizaci\u00f3n en Ruman\u00eda, en un solo a\u00f1o, de todo tipo de elecciones &#8211; presidenciales, parlamentarias, europarlamentarias y locales &#8211; y de tres domingos consecutivos &#8211; 24 de noviembre, 1 y 8 de diciembre &#8211; reservados a la elecci\u00f3n del presidente y del Parlamento, represent\u00f3, aunque s\u00f3lo fuera en teor\u00eda, [&hellip;]<\/p>\n","protected":false},"author":109,"featured_media":811729,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"footnotes":""},"categories":[49372],"tags":[159183,48978,149957,49255,150152,150821,149336,146555,159184,153816,154107,48949,143248],"coauthors":[115219],"class_list":["post-837289","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-retrospectiva-semanal","tag-1-de-diciembre-fiesta-nacional","tag-bucarest","tag-ciberataques","tag-comision-europea","tag-consejo-supremo-de-defensa","tag-elecciones-parlamentarias","tag-elecciones-presidenciales","tag-nicusor-dan-es","tag-programa-de-exencion-de-visados","tag-referendum-es","tag-roxana-minzatu-es","tag-rumania","tag-schengen-es","post_format-post-format-gallery"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retrospectiva semanal - Radio Ruman\u00eda Internacional<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retrospectiva semanal - Radio Ruman\u00eda Internacional\" \/>\n<meta property=\"og:description\" content=\"Elecciones con sorpresas y esc\u00e1ndalos La organizaci\u00f3n en Ruman\u00eda, en un solo a\u00f1o, de todo tipo de elecciones &#8211; presidenciales, parlamentarias, europarlamentarias y locales &#8211; y de tres domingos consecutivos &#8211; 24 de noviembre, 1 y 8 de diciembre &#8211; reservados a la elecci\u00f3n del presidente y del Parlamento, represent\u00f3, aunque s\u00f3lo fuera en teor\u00eda, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Ruman\u00eda Internacional\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-30T08:26:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/09\/Eveniment-Top-colaj-nou.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roxana Vasile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roxana Vasile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Roxana Vasile\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\\\/retrospectiva-semanal-274-id837289.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\\\/retrospectiva-semanal-274-id837289.html\"},\"author\":{\"name\":\"Roxana Vasile\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/0745b519f2d1287783422f162c4112af\"},\"headline\":\"Retrospectiva semanal\",\"datePublished\":\"2024-11-30T08:26:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\\\/retrospectiva-semanal-274-id837289.html\"},\"wordCount\":1118,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\\\/retrospectiva-semanal-274-id837289.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Eveniment-Top-colaj-nou.jpg\",\"keywords\":[\"1 de diciembre Fiesta Nacional\",\"Bucarest\",\"ciberataques\",\"Comisi\u00f3n Europea\",\"Consejo Supremo de Defensa\",\"elecciones parlamentarias\",\"elecciones presidenciales\",\"Nicusor Dan\",\"Programa de Exenci\u00f3n de Visados\",\"referendum\",\"Roxana Minzatu\",\"Rumania\",\"Schengen\"],\"articleSection\":[\"Retrospectiva semanal\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\\\/retrospectiva-semanal-274-id837289.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\\\/retrospectiva-semanal-274-id837289.html\",\"name\":\"Retrospectiva semanal - Radio Ruman\u00eda Internacional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\\\/retrospectiva-semanal-274-id837289.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\\\/retrospectiva-semanal-274-id837289.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Eveniment-Top-colaj-nou.jpg\",\"datePublished\":\"2024-11-30T08:26:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/0745b519f2d1287783422f162c4112af\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\\\/retrospectiva-semanal-274-id837289.html#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\\\/retrospectiva-semanal-274-id837289.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\\\/retrospectiva-semanal-274-id837289.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Eveniment-Top-colaj-nou.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Eveniment-Top-colaj-nou.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\\\/retrospectiva-semanal-274-id837289.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina de inicio\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Retrospectiva semanal\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/actualidad\\\/retrospectiva-semanal\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Retrospectiva semanal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Ruman\u00eda Internacional\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/0745b519f2d1287783422f162c4112af\",\"name\":\"Roxana Vasile\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/es\\\/author\\\/roxana-vasile\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retrospectiva semanal - Radio Ruman\u00eda Internacional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html","og_locale":"es_ES","og_type":"article","og_title":"Retrospectiva semanal - Radio Ruman\u00eda Internacional","og_description":"Elecciones con sorpresas y esc\u00e1ndalos La organizaci\u00f3n en Ruman\u00eda, en un solo a\u00f1o, de todo tipo de elecciones &#8211; presidenciales, parlamentarias, europarlamentarias y locales &#8211; y de tres domingos consecutivos &#8211; 24 de noviembre, 1 y 8 de diciembre &#8211; reservados a la elecci\u00f3n del presidente y del Parlamento, represent\u00f3, aunque s\u00f3lo fuera en teor\u00eda, [&hellip;]","og_url":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html","og_site_name":"Radio Ruman\u00eda Internacional","article_published_time":"2024-11-30T08:26:49+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/09\/Eveniment-Top-colaj-nou.jpg","type":"image\/jpeg"}],"author":"Roxana Vasile","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Roxana Vasile","Tiempo de lectura":"6 minutos","Written by":"Roxana Vasile"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html"},"author":{"name":"Roxana Vasile","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/0745b519f2d1287783422f162c4112af"},"headline":"Retrospectiva semanal","datePublished":"2024-11-30T08:26:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html"},"wordCount":1118,"image":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/09\/Eveniment-Top-colaj-nou.jpg","keywords":["1 de diciembre Fiesta Nacional","Bucarest","ciberataques","Comisi\u00f3n Europea","Consejo Supremo de Defensa","elecciones parlamentarias","elecciones presidenciales","Nicusor Dan","Programa de Exenci\u00f3n de Visados","referendum","Roxana Minzatu","Rumania","Schengen"],"articleSection":["Retrospectiva semanal"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html","url":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html","name":"Retrospectiva semanal - Radio Ruman\u00eda Internacional","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/09\/Eveniment-Top-colaj-nou.jpg","datePublished":"2024-11-30T08:26:49+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/0745b519f2d1287783422f162c4112af"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/09\/Eveniment-Top-colaj-nou.jpg","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/09\/Eveniment-Top-colaj-nou.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal\/retrospectiva-semanal-274-id837289.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina de inicio","item":"https:\/\/www.rri.ro\/es"},{"@type":"ListItem","position":2,"name":"Actualidad","item":"https:\/\/www.rri.ro\/es\/actualidad"},{"@type":"ListItem","position":3,"name":"Retrospectiva semanal","item":"https:\/\/www.rri.ro\/es\/actualidad\/retrospectiva-semanal"},{"@type":"ListItem","position":4,"name":"Retrospectiva semanal"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Ruman\u00eda Internacional","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/0745b519f2d1287783422f162c4112af","name":"Roxana Vasile","url":"https:\/\/www.rri.ro\/es\/author\/roxana-vasile"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts\/837289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/users\/109"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/comments?post=837289"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/posts\/837289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/media\/811729"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/media?parent=837289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/categories?post=837289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/tags?post=837289"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/es\/wp-json\/wp\/v2\/coauthors?post=837289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}