{"id":394053,"date":"2019-12-31T17:50:00","date_gmt":"2019-12-31T15:50:00","guid":{"rendered":"http:\/\/devrri.freshlemon.ro\/le-roumain-mot-a-mot\/consulter-les-lecons\/31-12-2019-mise-a-jour-id394053.html"},"modified":"2019-12-31T17:50:00","modified_gmt":"2019-12-31T15:50:00","slug":"31-12-2019-mise-a-jour","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html","title":{"rendered":"31.12.2019 (mise \u00e0 jour)"},"content":{"rendered":"<p><strong>V\u0153ux \u2013<\/strong> \u00ab 2019 a \u00e9t\u00e9 lann\u00e9e de la victoire de la d\u00e9mocratie et de limplication civique, lorsque nous avons montr\u00e9 \u00e0 tous que nous sommes une nation unie autour de valeurs et did\u00e9aux communs \u00bb, affirmait le pr\u00e9sident de la Roumanie, Klaus Iohannis, dans son message pour le Nouvel an. Le chef de lEtat a exprim\u00e9 sa confiance quen cette nouvelle ann\u00e9e, les Roumains continueront d\u00eatre anim\u00e9s par le r\u00eave dune Roumanie meilleure. Il a exhort\u00e9 \u00e0 construire, avec solidarit\u00e9 et espoir, une Roumanie normale, le pays qui devient vraiment le chez soi pour tous les Roumains, o\u00f9 quils se trouvent. \u00ab Nous entrons dans une nouvelle ann\u00e9e et une nouvelle d\u00e9cennie, et je souhaite que cela soit le d\u00e9but dune p\u00e9riode de normalit\u00e9 et de d\u00e9mocratie r\u00e9elle pour la Roumanie \u00bb, affirmait, dans son message pour le Nouvel an, le premier ministre Ludovic Orban. Il a exhort\u00e9 les Roumains \u00e0 regarder ce quils laissent derri\u00e8re eux comme un mod\u00e8le de ce quils doivent faire pour vraiment accomplir le r\u00eave de libert\u00e9, d\u00e9mocratie et prosp\u00e9rit\u00e9 qui les a mobilis\u00e9s voici 30 ans contre le totalitarisme. \u00ab Nous accueillons le Nouvel an avec espoir et confiance en la voie que nous avons choisie, \u00e9tant de nouveau dans la grande famille europ\u00e9enne et des partenaires appr\u00e9ci\u00e9s par lAlliance de lAtlantique Nord \u00bb, ajoutait le chef du cabinet de Bucarest dans ses v\u0153ux pour la Nouvelle ann\u00e9e. A son tour, Marcel Ciolacu, pr\u00e9sident de la Chambre des d\u00e9put\u00e9s et chef par int\u00e9rim du PSD, affirme dans son message que \u00ab 2020 sera lann\u00e9e de la bataille pour les droits de chaque Roumain \u00bb et que pas un effort ne sera de trop pour bloquer ce quil appelle \u00ab les abus, les ill\u00e9galit\u00e9s, lincomp\u00e9tence et lamateurisme de lactuelle gouvernance \u00bb. <\/p>\n<p><\/p>\n<p><p><strong class=cms-bold>H\u00f4pital<\/strong> &#8211; Les&#13;<br \/>\nautorit\u00e9s roumaines continuent leur enqu\u00eate et les v\u00e9rifications dans le cas de&#13;<br \/>\nl&rsquo;incident \u00e0 l&rsquo;H\u00f4pital Floreasca de Bucarest &#8211; le plus grand h\u00f4pital des&#13;<br \/>\nurgences de Roumanie. L&rsquo;Autorit\u00e9 roumaine de gestion de la qualit\u00e9 dans la&#13;<br \/>\nSant\u00e9 a suspendu lundi l&rsquo;accr\u00e9ditation de fonctionnement de l&rsquo;H\u00f4pital&#13;<br \/>\nFloreasca. Cette d\u00e9cision a \u00e9t\u00e9 prise vu que l&rsquo;h\u00f4pital n&rsquo;a pas rapport\u00e9 dans un&#13;<br \/>\nd\u00e9lai de 24 heures un incident lors duquel une patiente de 66 ans a br\u00fbl\u00e9&#13;<br \/>\npendant une intervention chirurgicale. La femme est d\u00e9c\u00e9d\u00e9e, alors que le&#13;<br \/>\nService Homicides de la Police de la Capitale fait des investigations pour&#13;<br \/>\nhomicide involontaire. Il existe aussi une enqu\u00eate du Coll\u00e8ge des m\u00e9decins, et&#13;<br \/>\nle Corps de contr\u00f4le du minist\u00e8re de la Sant\u00e9 proc\u00e8de \u00e0 des v\u00e9rifications dont&#13;<br \/>\nles conclusions seront pr\u00e9sent\u00e9es la semaine prochaine. En parall\u00e8le, l&rsquo;h\u00f4pital&#13;<br \/>\ndoit rem\u00e9dier aux carences qui ont favoris\u00e9 cet \u00e9tat de choses. L&rsquo;accr\u00e9ditation&#13;<br \/>\nde fonctionnement de l&rsquo;H\u00f4pital Floreasca a \u00e9t\u00e9 suspendue, toutefois&#13;<br \/>\nl&rsquo;\u00e9tablissement fonctionne normalement. <\/p>\n<p><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p> <strong style=font-size: 1em;>Emplois \u2013<\/strong><span style=font-size: 1em;> LInspection g\u00e9n\u00e9rale de limmigration peut d\u00e9livrer en 2020 des permis de travail sur le territoire de la Roumanie pour 30.000 ressortissants \u00e9trangers nouvellement admis. Le nombre de ces permis est similaire \u00e0 celui de 2019. Cette ann\u00e9e, les employeurs ont sollicit\u00e9 des avis pour plus de 750 fonctions occupationnelles, allant des op\u00e9rateurs de machines et installations jusquaux fonctionnaires sup\u00e9rieurs. La plupart des citoyens \u00e9trangers pr\u00e9sents sur le march\u00e9 roumain de lemploi proviennent de pays tels que Vietnam, N\u00e9pal, Inde, R\u00e9publique de Moldova et Sri Lanka. <\/span><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>T\u00e9l\u00e9vision <\/strong>\u2013 Le minist\u00e8re roumain des Affaires \u00e9trang\u00e8res a pris acte du fait quaux termes dune d\u00e9cision du Conseil de lAudiovisuel de R\u00e9publique de Moldova, la cha\u00eene de t\u00e9l\u00e9vision TVR Moldova se verra accorder une fr\u00e9quence \u00e0 couverture nationale, ce qui permettra la diffusion num\u00e9rique de ses programmes sur lensemble du territoire.  La diplomatie roumaine rappelle quelle a d\u00e9ploy\u00e9 des efforts importants et continus pour que la TVR Moldova, qui est une cha\u00eene de la t\u00e9l\u00e9vision publique roumaine, regagne la fr\u00e9quence d\u00e9mission nationale qui lui avait \u00e9t\u00e9 retir\u00e9e abusivement en 2017 par le gouvernement communiste philo russe au pouvoir \u00e0 Chisinau \u00e0 cette \u00e9poque-l\u00e0. Le minist\u00e8re des Affaires \u00e9trang\u00e8res de Bucarest estime donc que la d\u00e9cision de lAutorit\u00e9 de r\u00e9gulation dans le domaine de laudiovisuel peut \u00eatre consid\u00e9r\u00e9e comme \u00e9tant une mesure de r\u00e9paration. La diplomatie roumaine exprime sa conviction que ladite d\u00e9cision contribuera \u00e0 renforcer les liens de la R\u00e9publique de Moldova avec lUE et \u00e0 am\u00e9liorer lacc\u00e8s des citoyens moldaves \u00e0 une information correcte et impartiale dans lespace europ\u00e9en.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>M\u00e9t\u00e9o <\/strong>\u2013 Le premier jour de 2020 apportera des temp\u00e9ratures autour des normales de saison. Le ciel sera variable, et des pr\u00e9cipitations faibles seront signal\u00e9es sous forme de chutes de neige en montagne et de giboul\u00e9es dans lest du pays. Les maximales iront de -1 \u00e0 8\u00b0.<\/p>\n<p>&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u0153ux \u2013 \u00ab 2019 a \u00e9t\u00e9 lann\u00e9e de la victoire de la d\u00e9mocratie et de limplication civique, lorsque nous avons montr\u00e9 \u00e0 tous que nous sommes une nation unie autour de valeurs et did\u00e9aux communs \u00bb, affirmait le pr\u00e9sident de la Roumanie, Klaus Iohannis, dans son message pour le Nouvel an. Le chef de lEtat [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":391122,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[89002],"tags":[86988,85854,143871,177577,146159,55315,85082],"coauthors":[],"class_list":["post-394053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-flash","tag-emplois","tag-hopital","tag-klaus-iohannis-fr","tag-ludovic-orban-fr","tag-marcel-ciolacu-fr","tag-tvr-moldova","tag-voeux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>31.12.2019 (mise \u00e0 jour) - Radio Roumanie Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"31.12.2019 (mise \u00e0 jour) - Radio Roumanie Internationale\" \/>\n<meta property=\"og:description\" content=\"V\u0153ux \u2013 \u00ab 2019 a \u00e9t\u00e9 lann\u00e9e de la victoire de la d\u00e9mocratie et de limplication civique, lorsque nous avons montr\u00e9 \u00e0 tous que nous sommes une nation unie autour de valeurs et did\u00e9aux communs \u00bb, affirmait le pr\u00e9sident de la Roumanie, Klaus Iohannis, dans son message pour le Nouvel an. Le chef de lEtat [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Roumanie Internationale\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-31T15:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-franceza-ok2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Newsroom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsroom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Newsroom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/31-12-2019-mise-a-jour-id394053.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/31-12-2019-mise-a-jour-id394053.html\"},\"author\":{\"name\":\"Newsroom\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"headline\":\"31.12.2019 (mise \u00e0 jour)\",\"datePublished\":\"2019-12-31T15:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/31-12-2019-mise-a-jour-id394053.html\"},\"wordCount\":844,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/31-12-2019-mise-a-jour-id394053.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/stiri-franceza-ok2.png\",\"keywords\":[\"emplois\",\"h\u00f4pital\",\"Klaus Iohannis\",\"Ludovic Orban\",\"Marcel Ciolacu\",\"TVR Moldova\",\"voeux\"],\"articleSection\":[\"Le flash\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/31-12-2019-mise-a-jour-id394053.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/31-12-2019-mise-a-jour-id394053.html\",\"name\":\"31.12.2019 (mise \u00e0 jour) - Radio Roumanie Internationale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/31-12-2019-mise-a-jour-id394053.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/31-12-2019-mise-a-jour-id394053.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/stiri-franceza-ok2.png\",\"datePublished\":\"2019-12-31T15:50:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/31-12-2019-mise-a-jour-id394053.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/31-12-2019-mise-a-jour-id394053.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/31-12-2019-mise-a-jour-id394053.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/stiri-franceza-ok2.png\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/stiri-franceza-ok2.png\",\"width\":420,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/31-12-2019-mise-a-jour-id394053.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Page d'accueil\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le flash\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"31.12.2019 (mise \u00e0 jour)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Roumanie Internationale\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\",\"name\":\"Newsroom\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/author\\\/newsroom\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"31.12.2019 (mise \u00e0 jour) - Radio Roumanie Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html","og_locale":"fr_FR","og_type":"article","og_title":"31.12.2019 (mise \u00e0 jour) - Radio Roumanie Internationale","og_description":"V\u0153ux \u2013 \u00ab 2019 a \u00e9t\u00e9 lann\u00e9e de la victoire de la d\u00e9mocratie et de limplication civique, lorsque nous avons montr\u00e9 \u00e0 tous que nous sommes une nation unie autour de valeurs et did\u00e9aux communs \u00bb, affirmait le pr\u00e9sident de la Roumanie, Klaus Iohannis, dans son message pour le Nouvel an. Le chef de lEtat [&hellip;]","og_url":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html","og_site_name":"Radio Roumanie Internationale","article_published_time":"2019-12-31T15:50:00+00:00","og_image":[{"width":420,"height":280,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-franceza-ok2.png","type":"image\/png"}],"author":"Newsroom","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Newsroom","Dur\u00e9e de lecture estim\u00e9e":"4 minutes","Written by":"Newsroom"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html"},"author":{"name":"Newsroom","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"headline":"31.12.2019 (mise \u00e0 jour)","datePublished":"2019-12-31T15:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html"},"wordCount":844,"image":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-franceza-ok2.png","keywords":["emplois","h\u00f4pital","Klaus Iohannis","Ludovic Orban","Marcel Ciolacu","TVR Moldova","voeux"],"articleSection":["Le flash"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html","url":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html","name":"31.12.2019 (mise \u00e0 jour) - Radio Roumanie Internationale","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-franceza-ok2.png","datePublished":"2019-12-31T15:50:00+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-franceza-ok2.png","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-franceza-ok2.png","width":420,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/31-12-2019-mise-a-jour-id394053.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Page d'accueil","item":"https:\/\/www.rri.ro\/fr"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s","item":"https:\/\/www.rri.ro\/fr\/actualites"},{"@type":"ListItem","position":3,"name":"Le flash","item":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash"},{"@type":"ListItem","position":4,"name":"31.12.2019 (mise \u00e0 jour)"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Roumanie Internationale","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88","name":"Newsroom","url":"https:\/\/www.rri.ro\/fr\/author\/newsroom"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/posts\/394053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/comments?post=394053"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/posts\/394053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/media\/391122"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/media?parent=394053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/categories?post=394053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/tags?post=394053"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/coauthors?post=394053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}