{"id":394202,"date":"2020-03-15T19:24:00","date_gmt":"2020-03-15T17:24:00","guid":{"rendered":"http:\/\/devrri.freshlemon.ro\/le-roumain-mot-a-mot\/consulter-les-lecons\/15-03-2020-mise-a-jour-id394202.html"},"modified":"2020-03-15T19:24:00","modified_gmt":"2020-03-15T17:24:00","slug":"15-03-2020-mise-a-jour","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html","title":{"rendered":"15.03.2020 (mise \u00e0 jour)"},"content":{"rendered":"<\/p>\n<p><strong class=cms-bold>Coronavirus<\/strong>&#13;<br \/>\n&#8211; L&rsquo;\u00e9tat d&rsquo;urgence entrera en vigueur en Roumanie la semaine prochaine, a&#13;<br \/>\nannonc\u00e9 le pr\u00e9sident Klaus Iohannis, qui a expliqu\u00e9 avoir pris cette d\u00e9cision&#13;<br \/>\npour que les autorit\u00e9s puissent mieux g\u00e9rer la situation cr\u00e9\u00e9e par la&#13;<br \/>\ndiss\u00e9mination du nouveau coronavirus. Ainsi, l&rsquo;Ex\u00e9cutif pourra-t-il allouer des&#13;<br \/>\nfonds suppl\u00e9mentaires au secteur de la sant\u00e9, pour acheter des m\u00e9dicaments et&#13;<br \/>\nde l&rsquo;\u00e9quipement m\u00e9dical en utilisant des proc\u00e9dures simplifi\u00e9es et rapides. Il&#13;<br \/>\npourra \u00e9galement imposer des restrictions ou  interdictions n\u00e9cessaires pour combattre l&rsquo;\u00e9pid\u00e9mie.&#13;<br \/>\nLa diss\u00e9mination  du COVID-19 moins&#13;<br \/>\nrapide en Roumanie est la meilleure preuve de l&rsquo;efficacit\u00e9 des mesures prises,&#13;<br \/>\na d\u00e9clar\u00e9 le premier ministre Ludovic Orban, lors d&rsquo;une visioconf\u00e9rence tenue&#13;<br \/>\ndimanche. Et lui d&rsquo;ajouter que, dans sa premi\u00e8re r\u00e9union post-investiture, le&#13;<br \/>\ngouvernement  adoptera des actes&#13;<br \/>\nnormatifs pour endiguer la diss\u00e9mination de l&rsquo;infection au coronavirus ainsi&#13;<br \/>\nque des mesures de soutien r\u00e9el aux secteurs \u00e9conomiques impact\u00e9s. A partir de&#13;<br \/>\nce dimanche soir, toutes les personnes qui ne pr\u00e9sentent aucun sympt\u00f4me&#13;<br \/>\nclinique et qui arrivent en Roumanie depuis des pays enregistrant au moins 500&#13;<br \/>\ncas confirm\u00e9s de contamination au COVID-19 seront plac\u00e9es en isolement \u00e0&#13;<br \/>\ndomicile pour 14 jours.La Roumanie enregistre en ce moment 139cas&#13;<br \/>\nde contamination confirm\u00e9s au COVID-19, dont 34 dans la capitale, Bucarest&#13;<br \/>\nselon un dernier bilan officiel. 9 personnes ont gu\u00e9ri du nouveau coronavirus&#13;<br \/>\net ont pu quitter l&rsquo;h\u00f4pital. Plus de 2.900personnes sont plac\u00e9es en quarantaine,&#13;<br \/>\n\u00e0 l&rsquo;attente du r\u00e9sultat des analyses m\u00e9dicales, et plus de 14.600 autres sont&#13;<br \/>\nconfin\u00e9es \u00e0 domicile, sous surveillance m\u00e9dicale. Samedi, la Roumanie est&#13;<br \/>\nofficiellement entr\u00e9e dans le stade 3 de l&rsquo;\u00e9pid\u00e9mie et le Comit\u00e9 national pour&#13;<br \/>\nles situations d&rsquo;urgence a annonc\u00e9 de nouvelles mesures pour contenir la&#13;<br \/>\ndiss\u00e9mination du coronavirus. Il s&rsquo;agit, entre autres, de restrictions&#13;<br \/>\nconcernant les activit\u00e9s culturelles, scientifiques, artistiques, religieuses,&#13;<br \/>\nsportives et de divertissement rassemblant plus de 50 personnes. Le personnel&#13;<br \/>\nessentiel pour assurer le fonctionnement de la centrale nucl\u00e9aire de Cernavod\u0103&#13;<br \/>\n(sud-est) est plac\u00e9 en isolement pr\u00e9ventif. Les facteurs de la Poste et les&#13;<br \/>\ntechniciens d&rsquo;intervention pour les services communaux (eau, \u00e9gouts,&#13;<br \/>\n\u00e9lectricit\u00e9, internet, t\u00e9l\u00e9phonie), qui entrent en contact avec des personnes&#13;<br \/>\nplac\u00e9es en confinement, doivent utiliser de l&rsquo;\u00e9quipement de protection, et des produits&#13;<br \/>\nd\u00e9sinfectants pour les mains. Par ailleurs, le minist\u00e8re des affaires&#13;<br \/>\n\u00e9trang\u00e8res de Bucarest informe que les autorit\u00e9s roumaines donneront une r\u00e9ponse&#13;<br \/>\npositive \u00e0 la demande de la R\u00e9publique de Moldova, formul\u00e9e par voie&#13;<br \/>\ndiplomatique, d&rsquo;autoriser la livraison de certains m\u00e9dicaments. Cette d\u00e9cision&#13;<br \/>\nest prise dans le contexte de l&rsquo;arr\u00eat, par la Roumanie, des exportations de&#13;<br \/>\nm\u00e9dicaments, suite \u00e0 la mise en place du code rouge d&rsquo;infection au nouveau coronavirus.<\/p>\n<p><\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p><strong class=cms-bold>COVID-19<\/strong>&#13;<br \/>\n&#8211; L&rsquo;Europe est actuellement le foyer mondial de la pand\u00e9mie de COVID-19,&#13;<br \/>\nconsid\u00e8re l&rsquo;Organisation mondiale de la sant\u00e9, et un nombre croissant de pays&#13;<br \/>\neurop\u00e9ens ferment leurs fronti\u00e8res ou appliquent des restrictions \u00e0 l&rsquo;acc\u00e8s des&#13;<br \/>\n\u00e9trangers sur leurs territoires, notamment dans les r\u00e9gions les plus touch\u00e9es.&#13;<br \/>\nLes gouvernements prennent des mesures urgentes pour arr\u00eater la pand\u00e9mie de&#13;<br \/>\ncoronavirus, qui a d\u00e9j\u00e0 infect\u00e9  quelque 169.000&#13;<br \/>\npersonnes et tu\u00e9 6.500 autres dans le monde entier. L&rsquo;Italie enregistre plus de&#13;<br \/>\n21.000 cas de contamination et pr\u00e8s de 1.900 morts. L&rsquo;Espagne, deuxi\u00e8me pays&#13;<br \/>\neurop\u00e9en le plus touch\u00e9 apr\u00e8s l&rsquo;Italie, a pris des mesures draconiennes,&#13;<br \/>\ninstituant une quarantaine presque totale et l&rsquo;\u00e9tat d&rsquo;urgence pour une p\u00e9riode&#13;<br \/>\nde 15 jours. Les Espagnols ne sortent plus de leur domicile que pour aller s&rsquo;acheter&#13;<br \/>\ndes produits de premi\u00e8re n\u00e9cessit\u00e9 et des m\u00e9dicaments ou pour se rendre au&#13;<br \/>\ntravail. La France, qui enregistre plus de 100 d\u00e9c\u00e8s, a d\u00e9cid\u00e9 de fermer tous&#13;<br \/>\nles caf\u00e9s, restaurants et salles de cin\u00e9ma, ainsi que la majorit\u00e9 des magasins.&#13;<br \/>\nPourtant, les Fran\u00e7ais votent aujourd&rsquo;hui, au premier tour de scrutin des \u00e9lections&#13;<br \/>\nmunicipales. Berlin a interdit, entre autres, tout \u00e9v\u00e9nement public ou priv\u00e9&#13;<br \/>\navec plus de 50 participants. La Hongrie a annonc\u00e9 le premier d\u00e9c\u00e8s provoqu\u00e9&#13;<br \/>\npar le COVID-19. Les \u00e9tablissements scolaires seront ferm\u00e9s \u00e0 partir de lundi&#13;<br \/>\nen Bulgarie et aux Pays-Bas. Isra\u00ebl a d\u00e9cid\u00e9 de fermer les galeries&#13;<br \/>\ncommerciales, les h\u00f4tels et les restaurants, et a annonc\u00e9 l&rsquo;utilisation de la technologie&#13;<br \/>\nanti-terroriste pour r\u00e9duire le risque de diss\u00e9mination du nouveau coronavirus.&#13;<br \/>\nLa Russie vient de cr\u00e9er un Conseil de coordination pour combattre le COVID-19,&#13;<br \/>\ntandis que le pr\u00e9sident am\u00e9ricain Donald Trump a d\u00e9cid\u00e9 d&rsquo;inclure le Royaume&#13;<br \/>\nUni et l&rsquo;Irlande sur la liste de pays europ\u00e9ens frapp\u00e9s par l&rsquo;interdiction de&#13;<br \/>\nvoyager aux Etats-Unis. La Chine a annonc\u00e9 ce dimanche 20 nouveaux cas de&#13;<br \/>\ncontamination au COVID-19, dont 16 sont des personnes rentr\u00e9es de l&rsquo;\u00e9tranger.<\/p>\n<p><\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p><strong class=cms-bold>Diplomatie<\/strong> &#8211; L&rsquo;ambassadeur&#13;<br \/>\nam\u00e9ricain \u00e0 Bucarest, Adrian Zuckerman, salue l&rsquo;investiture du nouveau gouvernement&#13;<br \/>\nde Bucarest, appr\u00e9ciant le fait que les Roumains se soient unis pour r\u00e9pondre \u00e0&#13;<br \/>\nun probl\u00e8me d&rsquo;une magnitude globale. Dans un message affich\u00e9 dimanche sur le&#13;<br \/>\nsite de l&rsquo;ambassade des Etats-Unis \u00e0 Bucarest, Adrian Zuckerman a f\u00e9licit\u00e9 les membres&#13;<br \/>\ndes diff\u00e9rents partis politiques, notamment le pr\u00e9sident de la Chambre des&#13;<br \/>\nd\u00e9put\u00e9s, qui ont fait en sorte que la confirmation et la prestation de serment&#13;<br \/>\ndu gouvernement aient eu lieu rapidement, d&rsquo;avoir plac\u00e9 la s\u00e9curit\u00e9 de la&#13;<br \/>\nRoumanie et de son peuple au-dessus de l&rsquo;int\u00e9r\u00eat politique. Dans l&rsquo;opinion du&#13;<br \/>\ndiplomate am\u00e9ricain, cela t\u00e9moigne de l&rsquo;int\u00e9grit\u00e9 et de la d\u00e9termination qui&#13;<br \/>\nont transform\u00e9 la Roumanie en une partie cruciale de la communaut\u00e9 \u00e9conomique,&#13;<br \/>\nsociale et politique de l&rsquo;Europe. Les Roumains n&rsquo;ont pas de meilleur ami que&#13;<br \/>\nles Etats-Unis, qui l&rsquo;\u00e9pauleront \u00e0 chaque pas, a ajout\u00e9 Adrian Zuckerman. Le&#13;<br \/>\nnouveau gouvernement de Bucarest, du lib\u00e9ral Ludovic Orban a pr\u00eat\u00e9 serment&#13;<br \/>\ndevant le pr\u00e9sident Klaus Iohannis, ce samedi.<\/p>\n<p><\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p><strong class=cms-bold>M\u00e9t\u00e9o<\/strong> &#8211; Le&#13;<br \/>\ntemps reste gris et froid en Roumanie dans les prochaines 24 heures. Lundi, les&#13;<br \/>\ntemp\u00e9ratures maximales ne d\u00e9passeront pas les 10\u00b0.<\/p>\n<p>&#13;<br \/>\n&#13;<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coronavirus&#13; &#8211; L&rsquo;\u00e9tat d&rsquo;urgence entrera en vigueur en Roumanie la semaine prochaine, a&#13; annonc\u00e9 le pr\u00e9sident Klaus Iohannis, qui a expliqu\u00e9 avoir pris cette d\u00e9cision&#13; pour que les autorit\u00e9s puissent mieux g\u00e9rer la situation cr\u00e9\u00e9e par la&#13; diss\u00e9mination du nouveau coronavirus. Ainsi, l&rsquo;Ex\u00e9cutif pourra-t-il allouer des&#13; fonds suppl\u00e9mentaires au secteur de la sant\u00e9, pour acheter [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":391122,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[89002],"tags":[89504,35339,92568,85718,153317,147064,148548,47026,85412],"coauthors":[],"class_list":["post-394202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-flash","tag-ambassadeur","tag-coronavirus","tag-etat-durgence","tag-etats-unis","tag-message-fr","tag-meteo-fr","tag-oms-fr","tag-pandemie","tag-roumanie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>15.03.2020 (mise \u00e0 jour) - Radio Roumanie Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"15.03.2020 (mise \u00e0 jour) - Radio Roumanie Internationale\" \/>\n<meta property=\"og:description\" content=\"Coronavirus&#013; &#8211; L&rsquo;\u00e9tat d&rsquo;urgence entrera en vigueur en Roumanie la semaine prochaine, a&#013; annonc\u00e9 le pr\u00e9sident Klaus Iohannis, qui a expliqu\u00e9 avoir pris cette d\u00e9cision&#013; pour que les autorit\u00e9s puissent mieux g\u00e9rer la situation cr\u00e9\u00e9e par la&#013; diss\u00e9mination du nouveau coronavirus. Ainsi, l&rsquo;Ex\u00e9cutif pourra-t-il allouer des&#013; fonds suppl\u00e9mentaires au secteur de la sant\u00e9, pour acheter [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Roumanie Internationale\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-15T17:24:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-franceza-ok2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Newsroom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsroom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Newsroom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/15-03-2020-mise-a-jour-id394202.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/15-03-2020-mise-a-jour-id394202.html\"},\"author\":{\"name\":\"Newsroom\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"headline\":\"15.03.2020 (mise \u00e0 jour)\",\"datePublished\":\"2020-03-15T17:24:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/15-03-2020-mise-a-jour-id394202.html\"},\"wordCount\":1062,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/15-03-2020-mise-a-jour-id394202.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/stiri-franceza-ok2.png\",\"keywords\":[\"ambassadeur\",\"coronavirus\",\"\u00e9tat d'urgence\",\"Etats-Unis\",\"message\",\"meteo\",\"OMS\",\"pandemie\",\"Roumanie\"],\"articleSection\":[\"Le flash\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/15-03-2020-mise-a-jour-id394202.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/15-03-2020-mise-a-jour-id394202.html\",\"name\":\"15.03.2020 (mise \u00e0 jour) - Radio Roumanie Internationale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/15-03-2020-mise-a-jour-id394202.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/15-03-2020-mise-a-jour-id394202.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/stiri-franceza-ok2.png\",\"datePublished\":\"2020-03-15T17:24:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/15-03-2020-mise-a-jour-id394202.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/15-03-2020-mise-a-jour-id394202.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/15-03-2020-mise-a-jour-id394202.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/stiri-franceza-ok2.png\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/stiri-franceza-ok2.png\",\"width\":420,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\\\/15-03-2020-mise-a-jour-id394202.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Page d'accueil\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le flash\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/le-flash\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"15.03.2020 (mise \u00e0 jour)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Roumanie Internationale\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\",\"name\":\"Newsroom\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/author\\\/newsroom\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15.03.2020 (mise \u00e0 jour) - Radio Roumanie Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html","og_locale":"fr_FR","og_type":"article","og_title":"15.03.2020 (mise \u00e0 jour) - Radio Roumanie Internationale","og_description":"Coronavirus&#13; &#8211; L&rsquo;\u00e9tat d&rsquo;urgence entrera en vigueur en Roumanie la semaine prochaine, a&#13; annonc\u00e9 le pr\u00e9sident Klaus Iohannis, qui a expliqu\u00e9 avoir pris cette d\u00e9cision&#13; pour que les autorit\u00e9s puissent mieux g\u00e9rer la situation cr\u00e9\u00e9e par la&#13; diss\u00e9mination du nouveau coronavirus. Ainsi, l&rsquo;Ex\u00e9cutif pourra-t-il allouer des&#13; fonds suppl\u00e9mentaires au secteur de la sant\u00e9, pour acheter [&hellip;]","og_url":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html","og_site_name":"Radio Roumanie Internationale","article_published_time":"2020-03-15T17:24:00+00:00","og_image":[{"width":420,"height":280,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-franceza-ok2.png","type":"image\/png"}],"author":"Newsroom","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Newsroom","Dur\u00e9e de lecture estim\u00e9e":"5 minutes","Written by":"Newsroom"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html"},"author":{"name":"Newsroom","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"headline":"15.03.2020 (mise \u00e0 jour)","datePublished":"2020-03-15T17:24:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html"},"wordCount":1062,"image":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-franceza-ok2.png","keywords":["ambassadeur","coronavirus","\u00e9tat d'urgence","Etats-Unis","message","meteo","OMS","pandemie","Roumanie"],"articleSection":["Le flash"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html","url":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html","name":"15.03.2020 (mise \u00e0 jour) - Radio Roumanie Internationale","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-franceza-ok2.png","datePublished":"2020-03-15T17:24:00+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-franceza-ok2.png","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/stiri-franceza-ok2.png","width":420,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash\/15-03-2020-mise-a-jour-id394202.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Page d'accueil","item":"https:\/\/www.rri.ro\/fr"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s","item":"https:\/\/www.rri.ro\/fr\/actualites"},{"@type":"ListItem","position":3,"name":"Le flash","item":"https:\/\/www.rri.ro\/fr\/actualites\/le-flash"},{"@type":"ListItem","position":4,"name":"15.03.2020 (mise \u00e0 jour)"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Roumanie Internationale","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88","name":"Newsroom","url":"https:\/\/www.rri.ro\/fr\/author\/newsroom"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/posts\/394202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/comments?post=394202"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/posts\/394202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/media\/391122"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/media?parent=394202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/categories?post=394202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/tags?post=394202"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/coauthors?post=394202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}