{"id":400275,"date":"2020-03-17T12:40:00","date_gmt":"2020-03-17T10:40:00","guid":{"rendered":"http:\/\/devrri.freshlemon.ro\/le-roumain-mot-a-mot\/consulter-les-lecons\/etat-durgence-en-roumanie-id400275.html"},"modified":"2020-03-17T12:40:00","modified_gmt":"2020-03-17T10:40:00","slug":"etat-durgence-en-roumanie","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html","title":{"rendered":"Etat d\u2019urgence en Roumanie"},"content":{"rendered":"<p>Pour la premi\u00e8re fois ces 20 derni\u00e8res ann\u00e9es, l\u2019\u00e9tat d\u2019urgence a \u00e9t\u00e9 d\u00e9cr\u00e9t\u00e9 lundi, en raison de la pand\u00e9mie de coronavirus. Selon le pr\u00e9sident Klaus Iohannis, qui a fait cette annonce, la propagation de l\u2019infection au COVID-19 ne peut \u00eatre stopp\u00e9e que par des mesures exceptionnelles qui ont prouv\u00e9 leurs effets positifs dans des pays gravement affect\u00e9s jusqu\u2019ici. C\u2019est pourquoi, pendant 30 jours, de telles mesures seront prises en Roumanie aussi. Elles sont aff\u00e9rentes \u00e0 la priorit\u00e9 z\u00e9ro &#8212; la sant\u00e9 des gens. Les \u00e9coles et universit\u00e9s resteront ferm\u00e9es, les fronti\u00e8res pourraient \u00eatre ferm\u00e9es aussi, et en cas de besoin, les transports routiers, ferroviaires ou a\u00e9riens pourraient \u00eatre interdits. Si cela s\u2019impose, les restaurants, les h\u00f4tels ou d\u2019autres lieux publics pourraient \u00eatre temporairement ferm\u00e9s. Des stocks d\u2019\u00e9quipements de protection, des d\u00e9sinfectants et des m\u00e9dicaments utilis\u00e9s pour soigner les personnes infect\u00e9es au nouveau coronavirus pourraient \u00eatre r\u00e9quisitionn\u00e9s. Le pr\u00e9sident Klaus Iohannis : <em>\u00ab Si le besoin s\u2019en fait sentir, les prix des m\u00e9dicaments et des appareils m\u00e9dicaux peuvent \u00eatre plafonn\u00e9s, ainsi que ceux des aliments strictement n\u00e9cessaires et des services communaux, tels que l\u2019\u00e9lectricit\u00e9, le gaz, l\u2019alimentation en eau, les services de salubrit\u00e9, les carburants, dans les limites de leur prix moyen des trois derniers mois avant l\u2019\u00e9tat d\u2019urgence. Les services m\u00e9dicaux pour traiter les cas d\u2019infection li\u00e9s au nouveau coronavirus et \u00e0 ses complications sont accord\u00e9s \u00e0 toutes les personnes qui se trouvent sur le territoire de la Roumanie et les frais sont support\u00e9s par le budget du Fonds national unique d\u2019assurance maladie. Pour les personnes en confinement \u00e0 domicilepour limiter la propagation du COVID-19, des mesures sp\u00e9ciales de soutien seront d\u00e9finies, qui seront mises en \u0153uvre par les pouvoirs publics. Les employeurs et employ\u00e9s affect\u00e9s par les effets de la crise COVID-19 seront soutenus par des d\u00e9rogations aux dispositions l\u00e9gales en vigueur. Les travailleurs et leurs familles des secteurs \u00e9conomiques dont l\u2019activit\u00e9 est affect\u00e9e ou m\u00eame arr\u00eat\u00e9e en tout ou en partie pendant l\u2019\u00e9tat d\u2019urgence b\u00e9n\u00e9ficieront de protection sociale, par des d\u00e9cisions des autorit\u00e9s publiques. \u00bb<\/em><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>La mise en place de l\u2019\u00e9tat d\u2019urgence produit \u00e9galement des effets en justice &#8212; a ajout\u00e9 le pr\u00e9sident de la Roumanie &#8212; qui a mentionn\u00e9 que le traitement des affaires se poursuivra uniquement en cas d\u2019urgence sp\u00e9ciale. Klaus Iohannis a r\u00e9it\u00e9r\u00e9 son appel aux citoyens de respecter les r\u00e8gles impos\u00e9es par les autorit\u00e9s : <em>\u00ab Chers Roumains, \u00e9coutez les messages officiels, respectez strictement les r\u00e8gles, maintenez l\u2019hygi\u00e8ne des mains, \u00e9vitez les lieux bond\u00e9s, limitez autant que possible tout d\u00e9placement. Maintenant plus que jamais, prenez soin de vos proches, notamment des personnes \u00e2g\u00e9es et des plus vuln\u00e9rables. M\u00eame si cela peut s\u2019av\u00e9rer tr\u00e8s difficile, gardez la distance sociale. \u00bb<\/em><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Le d\u00e9cret sur la mise en place de l\u2019\u00e9tat d\u2019urgence, sign\u00e9 par le chef de l\u2019Etat, a \u00e9t\u00e9 publi\u00e9 au Journal officiel. Jeudi \u00e0 midi, le parlement se r\u00e9unira en s\u00e9ance pl\u00e9ni\u00e8re pour le voter. Nouveau signe de l\u2019urgence sanitaire que nous traversons, les d\u00e9bats auront lieu par t\u00e9l\u00e9conf\u00e9rence ; seuls les pr\u00e9sidents des deux Chambres du parlement seront pr\u00e9sents dans la salle. Les parlementaires voteront par l\u2019interm\u00e9diaire d\u2019une application informatique s\u00e9curis\u00e9e. La r\u00e9union sera diffus\u00e9e sur le site Internet de la Chambre des d\u00e9put\u00e9s. (Trad. Ligia Mihaiescu)<\/p>\n<p>&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour la premi\u00e8re fois ces 20 derni\u00e8res ann\u00e9es, l\u2019\u00e9tat d\u2019urgence a \u00e9t\u00e9 d\u00e9cr\u00e9t\u00e9 lundi, en raison de la pand\u00e9mie de coronavirus. Selon le pr\u00e9sident Klaus Iohannis, qui a fait cette annonce, la propagation de l\u2019infection au COVID-19 ne peut \u00eatre stopp\u00e9e que par des mesures exceptionnelles qui ont prouv\u00e9 leurs effets positifs dans des pays [&hellip;]<\/p>\n","protected":false},"author":109,"featured_media":80800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[93377],"tags":[35374,160880,92568,143871],"coauthors":[],"class_list":["post-400275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-dossiers-de-lactualite","tag-covid-19","tag-decret-fr","tag-etat-durgence","tag-klaus-iohannis-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Etat d\u2019urgence en Roumanie - Radio Roumanie Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Etat d\u2019urgence en Roumanie - Radio Roumanie Internationale\" \/>\n<meta property=\"og:description\" content=\"Pour la premi\u00e8re fois ces 20 derni\u00e8res ann\u00e9es, l\u2019\u00e9tat d\u2019urgence a \u00e9t\u00e9 d\u00e9cr\u00e9t\u00e9 lundi, en raison de la pand\u00e9mie de coronavirus. Selon le pr\u00e9sident Klaus Iohannis, qui a fait cette annonce, la propagation de l\u2019infection au COVID-19 ne peut \u00eatre stopp\u00e9e que par des mesures exceptionnelles qui ont prouv\u00e9 leurs effets positifs dans des pays [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Roumanie Internationale\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-17T10:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/klaus-iohannis-ok.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Roxana Vasile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roxana Vasile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Roxana Vasile\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\\\/etat-durgence-en-roumanie-id400275.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\\\/etat-durgence-en-roumanie-id400275.html\"},\"author\":{\"name\":\"Roxana Vasile\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/0745b519f2d1287783422f162c4112af\"},\"headline\":\"Etat d\u2019urgence en Roumanie\",\"datePublished\":\"2020-03-17T10:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\\\/etat-durgence-en-roumanie-id400275.html\"},\"wordCount\":634,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\\\/etat-durgence-en-roumanie-id400275.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/klaus-iohannis-ok.png\",\"keywords\":[\"Covid-19\",\"decret\",\"\u00e9tat d'urgence\",\"Klaus Iohannis\"],\"articleSection\":[\"Les dossiers de l'actualit\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\\\/etat-durgence-en-roumanie-id400275.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\\\/etat-durgence-en-roumanie-id400275.html\",\"name\":\"Etat d\u2019urgence en Roumanie - Radio Roumanie Internationale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\\\/etat-durgence-en-roumanie-id400275.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\\\/etat-durgence-en-roumanie-id400275.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/klaus-iohannis-ok.png\",\"datePublished\":\"2020-03-17T10:40:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/0745b519f2d1287783422f162c4112af\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\\\/etat-durgence-en-roumanie-id400275.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\\\/etat-durgence-en-roumanie-id400275.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\\\/etat-durgence-en-roumanie-id400275.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/klaus-iohannis-ok.png\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/klaus-iohannis-ok.png\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\\\/etat-durgence-en-roumanie-id400275.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Page d'accueil\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les dossiers de l'actualit\u00e9\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/actualites\\\/les-dossiers-de-lactualite\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Etat d\u2019urgence en Roumanie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Roumanie Internationale\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/0745b519f2d1287783422f162c4112af\",\"name\":\"Roxana Vasile\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/fr\\\/author\\\/roxana-vasile\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Etat d\u2019urgence en Roumanie - Radio Roumanie Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html","og_locale":"fr_FR","og_type":"article","og_title":"Etat d\u2019urgence en Roumanie - Radio Roumanie Internationale","og_description":"Pour la premi\u00e8re fois ces 20 derni\u00e8res ann\u00e9es, l\u2019\u00e9tat d\u2019urgence a \u00e9t\u00e9 d\u00e9cr\u00e9t\u00e9 lundi, en raison de la pand\u00e9mie de coronavirus. Selon le pr\u00e9sident Klaus Iohannis, qui a fait cette annonce, la propagation de l\u2019infection au COVID-19 ne peut \u00eatre stopp\u00e9e que par des mesures exceptionnelles qui ont prouv\u00e9 leurs effets positifs dans des pays [&hellip;]","og_url":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html","og_site_name":"Radio Roumanie Internationale","article_published_time":"2020-03-17T10:40:00+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/klaus-iohannis-ok.png","type":"image\/png"}],"author":"Roxana Vasile","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Roxana Vasile","Dur\u00e9e de lecture estim\u00e9e":"3 minutes","Written by":"Roxana Vasile"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html"},"author":{"name":"Roxana Vasile","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/0745b519f2d1287783422f162c4112af"},"headline":"Etat d\u2019urgence en Roumanie","datePublished":"2020-03-17T10:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html"},"wordCount":634,"image":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/klaus-iohannis-ok.png","keywords":["Covid-19","decret","\u00e9tat d'urgence","Klaus Iohannis"],"articleSection":["Les dossiers de l'actualit\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html","url":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html","name":"Etat d\u2019urgence en Roumanie - Radio Roumanie Internationale","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/klaus-iohannis-ok.png","datePublished":"2020-03-17T10:40:00+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/0745b519f2d1287783422f162c4112af"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/klaus-iohannis-ok.png","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2023\/10\/klaus-iohannis-ok.png","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite\/etat-durgence-en-roumanie-id400275.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Page d'accueil","item":"https:\/\/www.rri.ro\/fr"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s","item":"https:\/\/www.rri.ro\/fr\/actualites"},{"@type":"ListItem","position":3,"name":"Les dossiers de l'actualit\u00e9","item":"https:\/\/www.rri.ro\/fr\/actualites\/les-dossiers-de-lactualite"},{"@type":"ListItem","position":4,"name":"Etat d\u2019urgence en Roumanie"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Roumanie Internationale","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/0745b519f2d1287783422f162c4112af","name":"Roxana Vasile","url":"https:\/\/www.rri.ro\/fr\/author\/roxana-vasile"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/posts\/400275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/users\/109"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/comments?post=400275"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/posts\/400275\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/media\/80800"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/media?parent=400275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/categories?post=400275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/tags?post=400275"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/fr\/wp-json\/wp\/v2\/coauthors?post=400275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}