{"id":447456,"date":"2013-01-29T14:31:00","date_gmt":"2013-01-29T12:31:00","guid":{"rendered":"http:\/\/devrri.freshlemon.ro\/news\/crisi-fine-della-missione-fmi-in-romania-id447456.html"},"modified":"2013-01-29T14:31:00","modified_gmt":"2013-01-29T12:31:00","slug":"crisi-fine-della-missione-fmi-in-romania","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html","title":{"rendered":"Crisi: fine della missione FMI in Romania"},"content":{"rendered":"<p>&#13;<br \/>\n\tDopo due settimane di colloqui con le autorit\u00e0 di Bucarest, gli esperti del Fondo monetario internazionale, della Commissione europea e della Banca mondiale hanno gradito, di principio, la sollecitazione delle autorit\u00e0 romene sulla proroga di tre mesi dell\u2019accordo di tipo preventivo, dopo aver constatato dei ritardi in materia di riforme e impegni assunti.<\/p>\n<p>&#13;<\/p>\n<p>&#13;<br \/>\n\t<br \/>&#13;<br \/>\n\tI creditori internazionali ritengono l\u2019energia e i trasporti i principali settori che la Romania deve sviluppare, e valutano che le compagnie energetiche ricavano profitto, ma non sufficiente per giustificare investimenti. Inoltre, Bucarest deve attirare un livello quanto pi\u00f9 alto di fondi europei. Gli esperti ritengono che la crescita quasi nulla nel 2012 \u00e8 da attribuire all\u2019agricoltura e ai ritardi nelle riforme.<\/p>\n<p>&#13;<\/p>\n<p>&#13;<br \/>\n\t<br \/>&#13;<br \/>\n\tPer il 2013, il Fondo prevede una crescita dell\u20191,5%, e valuta che serve una cifra superiore. Inoltre, gli esperti ritengono che le autorit\u00e0 romene non hanno raggiunto i target sul deficit di bilancio in cash, sulla riduzione degli arretrati e sugli attivi esteri netti della Banca Centrale.<\/p>\n<p>&#13;<\/p>\n<p>&#13;<br \/>\n\t<br \/>&#13;<br \/>\n\tIl FMI sottolonea, per\u00f2, che la Romania ha raggiunto la pi\u00f9 importante meta, precisamente quella sul deficit di bilancio calcolato secondo la metodologia europea, che, secondo le stime, \u00e8 stata inferiore al 3% del Pil nel 2012.<\/p>\n<p>&#13;<\/p>\n<p>&#13;<br \/>\n\t<br \/>&#13;<br \/>\n\tDa parte sua, il premier Victor Ponta ha spiegato che tra i risultati concreti della visita della delegazione congiunta del FMI, della CE e della BM si annovera l\u2019accordo sulla forma finale della Finanziaria per il 2013 e sulla privatizzazione della Divisione Merci delle Ferrovie dello Stato.<\/p>\n<p>&#13;<\/p>\n<p>&#13;<br \/>\n\t<br \/>&#13;<br \/>\n\tIl FMI ha definito il bilancio per il 2013 come abbastanza equilibrato, in quanto stanzia i fondi necessari a salari e pensioni, ma anche al cofinanziamento dei progetti europei. D\u2019altra parte, il premier Ponta ha promesso che il Governo continuer\u00e0 le misure volte a migliorare le attivit\u00e0 delle compagnie statali.<\/p>\n<p>&#13;<\/p>\n<p>&#13;<br \/>\n\t<br \/>&#13;<br \/>\n\tLe autorit\u00e0 di Bucarest hanno discusso con i creditori internazionali anche l\u2019introduzione della partecipazione finanziaria dei romeni nel sistema sanitario a partire dal 1 marzo. Si tratta di una tassa di 10 lei (2,2 euro), che sar\u00e0 incassata quando i pazienti vengono dimessi dall\u2019ospedale. In questo modo, le autorit\u00e0 tentano di limitare le degenze ingiustificate o persino fittizie in ospedali.<\/p>\n<p>&#13;<\/p>\n<p>&#13;<br \/>\n\t<br \/>&#13;<br \/>\n\tInvece, le associazioni dei pazienti criticano la misura, ritenendo che limiter\u00e0 l\u2019accesso della popolazione povera ai servizi sanitari. A fine anno sar\u00e0 valutata l\u2019efficacia del sistema e si decider\u00e0 se la partecipazione finanziaria sar\u00e0 mantenuta o meno.<\/p>\n<p>&#13;<\/p>\n<p>&#13;<br \/>\n\t<br \/>&#13;<br \/>\n\tIntanto, il governo romeno ha espresso l\u2019interesse di firmare un nuovo accordo di tipo preventivo col FMI, in quanto, come ha spiegato il premier, consentirebbe il consolidamento dei risultati economici raggiunti lo scorso anno, e le prospettive per il 2013, che riguardano la stabilit\u00e0, il tasso di cambio, la fiducia degli imprenditori, ma anche dei creditori dello stato romeno. (trad. Iuliana Anghel)<\/p>\n<p>&#13;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#13; Dopo due settimane di colloqui con le autorit\u00e0 di Bucarest, gli esperti del Fondo monetario internazionale, della Commissione europea e della Banca mondiale hanno gradito, di principio, la sollecitazione delle autorit\u00e0 romene sulla proroga di tre mesi dell\u2019accordo di tipo preventivo, dopo aver constatato dei ritardi in materia di riforme e impegni assunti. &#13; [&hellip;]<\/p>\n","protected":false},"author":107,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[99264],"tags":[],"coauthors":[],"class_list":["post-447456","post","type-post","status-publish","format-standard","hentry","category-in-primo-piano"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crisi: fine della missione FMI in Romania - Radio Romania Internazionale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crisi: fine della missione FMI in Romania - Radio Romania Internazionale\" \/>\n<meta property=\"og:description\" content=\"&#013; Dopo due settimane di colloqui con le autorit\u00e0 di Bucarest, gli esperti del Fondo monetario internazionale, della Commissione europea e della Banca mondiale hanno gradito, di principio, la sollecitazione delle autorit\u00e0 romene sulla proroga di tre mesi dell\u2019accordo di tipo preventivo, dopo aver constatato dei ritardi in materia di riforme e impegni assunti. &#013; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Romania Internazionale\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-29T12:31:00+00:00\" \/>\n<meta name=\"author\" content=\"Daniela Budu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela Budu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/in-primo-piano\\\/crisi-fine-della-missione-fmi-in-romania-id447456.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/in-primo-piano\\\/crisi-fine-della-missione-fmi-in-romania-id447456.html\"},\"author\":{\"name\":\"Daniela Budu\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/b46b8f80d7d6e4b5ac9f14f0acbad0c4\"},\"headline\":\"Crisi: fine della missione FMI in Romania\",\"datePublished\":\"2013-01-29T12:31:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/in-primo-piano\\\/crisi-fine-della-missione-fmi-in-romania-id447456.html\"},\"wordCount\":459,\"articleSection\":[\"In primo piano\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/in-primo-piano\\\/crisi-fine-della-missione-fmi-in-romania-id447456.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/in-primo-piano\\\/crisi-fine-della-missione-fmi-in-romania-id447456.html\",\"name\":\"Crisi: fine della missione FMI in Romania - Radio Romania Internazionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"datePublished\":\"2013-01-29T12:31:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/b46b8f80d7d6e4b5ac9f14f0acbad0c4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/in-primo-piano\\\/crisi-fine-della-missione-fmi-in-romania-id447456.html#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/in-primo-piano\\\/crisi-fine-della-missione-fmi-in-romania-id447456.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/in-primo-piano\\\/crisi-fine-della-missione-fmi-in-romania-id447456.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"In primo piano\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/in-primo-piano\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Crisi: fine della missione FMI in Romania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Romania Internazionale\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/b46b8f80d7d6e4b5ac9f14f0acbad0c4\",\"name\":\"Daniela Budu\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/author\\\/daniela-budu\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crisi: fine della missione FMI in Romania - Radio Romania Internazionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html","og_locale":"it_IT","og_type":"article","og_title":"Crisi: fine della missione FMI in Romania - Radio Romania Internazionale","og_description":"&#13; Dopo due settimane di colloqui con le autorit\u00e0 di Bucarest, gli esperti del Fondo monetario internazionale, della Commissione europea e della Banca mondiale hanno gradito, di principio, la sollecitazione delle autorit\u00e0 romene sulla proroga di tre mesi dell\u2019accordo di tipo preventivo, dopo aver constatato dei ritardi in materia di riforme e impegni assunti. &#13; [&hellip;]","og_url":"https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html","og_site_name":"Radio Romania Internazionale","article_published_time":"2013-01-29T12:31:00+00:00","author":"Daniela Budu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Daniela Budu","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html"},"author":{"name":"Daniela Budu","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/b46b8f80d7d6e4b5ac9f14f0acbad0c4"},"headline":"Crisi: fine della missione FMI in Romania","datePublished":"2013-01-29T12:31:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html"},"wordCount":459,"articleSection":["In primo piano"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html","url":"https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html","name":"Crisi: fine della missione FMI in Romania - Radio Romania Internazionale","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"datePublished":"2013-01-29T12:31:00+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/b46b8f80d7d6e4b5ac9f14f0acbad0c4"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/it\/news\/in-primo-piano\/crisi-fine-della-missione-fmi-in-romania-id447456.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/www.rri.ro\/it"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.rri.ro\/it\/news"},{"@type":"ListItem","position":3,"name":"In primo piano","item":"https:\/\/www.rri.ro\/it\/news\/in-primo-piano"},{"@type":"ListItem","position":4,"name":"Crisi: fine della missione FMI in Romania"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Romania Internazionale","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/b46b8f80d7d6e4b5ac9f14f0acbad0c4","name":"Daniela Budu","url":"https:\/\/www.rri.ro\/it\/author\/daniela-budu"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/447456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/users\/107"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/comments?post=447456"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/447456\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media?parent=447456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/categories?post=447456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/tags?post=447456"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/coauthors?post=447456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}