{"id":929810,"date":"2025-09-20T16:44:44","date_gmt":"2025-09-20T13:44:44","guid":{"rendered":"https:\/\/www.rri.ro\/?p=929810"},"modified":"2025-09-20T19:22:25","modified_gmt":"2025-09-20T16:22:25","slug":"20-09-2025","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html","title":{"rendered":"20.09.2025"},"content":{"rendered":"<p>Esercitazione \u2013 A partire da oggi, stanno iniziando ad entrare in Romania, via Curtici (ovest) le prime colonne di equipaggiamento militare delle truppe dei paesi membri NATO, che prenderanno parte all&#8217;esercitazione &#8220;Dacian Fall&#8221;, DAFA 2025, in programma in Romania e Bulgaria dal 20 ottobre al 13 novembre. Il principale obiettivo dell&#8217;esercitazione \u00e8 l&#8217;integrazione operativa delle strutture subordinate e affiliate al Comando Multinazionale della Divisione Sud-Est e segna la fase finale dell&#8217;elevazione al livello di brigata dei battle groups NATO dei due paesi, ha affermato il Generale Dorin Toma, a capo della suddetta struttura alleata con sede a Bucarest. Oltre 5.000 soldati alleati con 1.200 mezzi tecnici provenienti da 10 stati alleati prenderanno parte all&#8217;esercitazione, che si svolger\u00e0 contemporaneamente nei poligoni di addestramento. Gli stati partecipanti sono Belgio, Bulgaria, Francia, Italia, Lussemburgo, Macedonia del Nord, Polonia, Portogallo, Romania e Spagna. Le esercitazioni NATO, compresa DAFA 25, sono di natura difensiva e vengono svolte nel pieno rispetto degli obblighi internazionali assunti dalla Romania, precisa il Ministero della Difesa Nazionale.<\/p>\n<p>Aerei russi &#8211; La NATO e l&#8217;Unione Europea hanno condannato la violazione dello spazio aereo estone da parte di tre caccia russi venerd\u00ec. Il Ministero della Difesa russo ha negato che i suoi aerei avessero sorvolato l&#8217;Estonia. Tallinn ha invocato l&#8217;articolo 4 del Trattato NATO, chiedendo consultazioni urgenti con gli alleati sulla risposta. Le reazioni finora sono state di sostegno totale. Anche la Romania ha condannato la violazione dello spazio aereo estone da parte di tre caccia russi, ha scritto sui social media la ministra degli Esteri romena, Oana \u0162oiu. Questo mese, droni russi hanno violato anche lo spazio aereo di Romania e Polonia. Il 13 settembre, un drone appartenente alla Federazione Russa ha sorvolato per 50 minuti lo spazio aereo romeno ed ha lasciato il Paese sotto il monitoraggio degli aerei militari della NATO. In Polonia, le autorit\u00e0 hanno affermato che lo spazio aereo nazionale \u00e8 stato violato da almeno 19 droni russi nella notte tra il 9 e il 10 settembre, alcuni dei quali sono stati abbattuti dalle forze aeree del Paese e della NATO.<\/p>\n<p>AIEA &#8211; La Romania \u00e8 diventata membro nel Consiglio dei Governatori dell&#8217;Agenzia Internazionale per l&#8217;Energia Atomica, con un mandato biennale, dopo le elezioni tenutesi venerd\u00ec, nell\u2019ultimo giorno della conferenza generale dell&#8217;agenzia, ha annunciato il Ministero degli Affari Esteri di Bucarest. In passato, la Romania ha guidato l&#8217;agenzia tra il 2008 e il 2010. Il MAE ha affermato che il nuovo mandato \u00e8 un riconoscimento dell&#8217;esperienza romena maturata in oltre 60 anni di attivit\u00e0 nel settore nucleare civile. La Romania era molto vicina a ottenere la carica di direttore dell&#8217;Agenzia Internazionale per l&#8217;Energia Atomica tramite il diplomatico Cornel Feru\u0163\u0103, che ha ricoperto tale incarico ad interim per sei mesi nel 2019.<\/p>\n<p>Giornate di Bucarest \u2013 Le Giornate di Bucarest si celebrano questo fine settimana con concerti all&#8217;aperto, spettacoli teatrali, proiezioni cinematografiche, mostre e visite guidate. La serie di eventi celebra i 566 anni dalla prima menzione della citt\u00e0 in un documento. L&#8217;evento &#8220;Strade Aperte&#8221; anima Calea Victoriei con decine di eventi artistici e comunitari. Una sfilata spettacolare su questo viale ricrea l&#8217;atmosfera di un tempo: cavalli, costumi d&#8217;epoca, artisti e personaggi storici. Una mostra fotografica che coglie l&#8217;atmosfera della Capitale durante il periodo tra le due guerre pu\u00f2 essere visitata presso l&#8217;Arco di Trionfo, mentre i Palazzi Brancovene\u0219ti alle Porte di Bucarest organizzano ricostituzioni storico-militari e cerimonie in onore degli eroi. La sede del comune sar\u00e0 aperta ai visitatori per visite guidate, proiezioni di film, mostre e attivit\u00e0 creative.<\/p>\n<p>Festival video mapping &#8211; Il pi\u00f9 grande festival di video mapping del mondo torna oggi, per due giorni, a Bucarest, nella Piazza della Costituzione. iMapp celebra un doppio anniversario: 566 anni dalla prima menzione di Bucarest nei documenti e dieci anni di esistenza del festival. Sette squadre, vincitrici dei pi\u00f9 grandi festival di fama mondiale, presentano le loro opere sulla facciata pi\u00f9 grande del mondo: la facciata di 23.000 metri quadrati del Palazzo del Parlamento. Le squadre in gara provengono da paesi di tre continenti: Cina, Giappone, Indonesia, Ungheria, Germania, Francia e Stati Uniti d&#8217;America. Quest&#8217;anno, sono organizzati anche due momenti speciali in onore di due artisti romeni del patrimonio culturale mondiale: una proiezione dedicata a George Enescu e un&#8217;opera di video mapping ispirata all&#8217;opera dello scultore Constantin Br\u00e2ncu\u0219i.<\/p>\n<p>Festival Enescu &#8211;\u00a0 La 27\/a edizione del Festival Internazionale George Enescu chiude i battenti in Romania domenica. Quasi 100 concerti e spettacoli sono stati programmati durante il festival. Il pubblico ha potuto ascoltare interpretazioni delle opere di George Enescu, dalle celebri Rapsodie romene alle Sinfonie, Suite orchestrali, opere da camera rare e la monumentale opera &#8220;Oedipe&#8221;, presentata in una produzione firmata dal lungimirante regista Stefano Poda, oltre a opere firmate da importanti compositori come Dmitri Shostakovich, Pierre Boulez e Maurice Ravel. Quest&#8217;anno, il festival celebra anche il 70\u00b0 anniversario della scomparsa del grande compositore, rendendo omaggio alla sua eredit\u00e0 artistica e al profondo impatto sulla musica classica universale. Fin dalla prima edizione, Radio Romania \u00e8 stata al fianco del Festival Enescu in qualit\u00e0 di co-produttore.<\/p>\n<p>Risarcimenti &#8211; La Romania ha ricevuto 5,7 milioni di euro di risarcimento per quattro oggetti del patrimonio culturale rubati da un museo nei Paesi Bassi a gennaio di quest&#8217;anno: tre braccialetti dacici e un elmo d&#8217;oro, esposti in una mostra con oltre 500 pezzi prestati dalla Romania. Il Ministero della Cultura ha dichiarato in un comunicato che il Museo Nazionale di Storia ha confermato che l&#8217;assicuratore ha trasferito l&#8217;intero importo previsto dalla polizza assicurativa. L&#8217;ultima tranche \u00e8 stata versata il 12 settembre e, secondo la legge, il museo verser\u00e0 l&#8217;importo al bilancio statale. Se gli oggetti verranno restituiti, il denaro dovr\u00e0 essere versato all&#8217;assicuratore. Nel frattempo, l&#8217;indagine penale sul furto continua. Il ministro della Cultura, Andras Demeter, ha chiesto proposte per modificare le procedure di esposizione temporanea di oggetti del patrimonio culturale romeno, al fine di ridurre il rischio di avvenimenti del genere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esercitazione \u2013 A partire da oggi, stanno iniziando ad entrare in Romania, via Curtici (ovest) le prime colonne di equipaggiamento militare delle truppe dei paesi membri NATO, che prenderanno parte all&#8217;esercitazione &#8220;Dacian Fall&#8221;, DAFA 2025, in programma in Romania e Bulgaria dal 20 ottobre al 13 novembre. Il principale obiettivo dell&#8217;esercitazione \u00e8 l&#8217;integrazione operativa delle [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":745145,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[98934],"tags":[],"coauthors":[116091],"class_list":["post-929810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-topnews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>20.09.2025 - Radio Romania Internazionale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20.09.2025 - Radio Romania Internazionale\" \/>\n<meta property=\"og:description\" content=\"Esercitazione \u2013 A partire da oggi, stanno iniziando ad entrare in Romania, via Curtici (ovest) le prime colonne di equipaggiamento militare delle truppe dei paesi membri NATO, che prenderanno parte all&#8217;esercitazione &#8220;Dacian Fall&#8221;, DAFA 2025, in programma in Romania e Bulgaria dal 20 ottobre al 13 novembre. Il principale obiettivo dell&#8217;esercitazione \u00e8 l&#8217;integrazione operativa delle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Romania Internazionale\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-20T13:44:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-20T16:22:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1269\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Newsroom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsroom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/20-09-2025-id929810.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/20-09-2025-id929810.html\"},\"author\":{\"name\":\"Newsroom\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"headline\":\"20.09.2025\",\"datePublished\":\"2025-09-20T13:44:44+00:00\",\"dateModified\":\"2025-09-20T16:22:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/20-09-2025-id929810.html\"},\"wordCount\":984,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/20-09-2025-id929810.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stiri-italiana-bleu-site-1269.jpg\",\"articleSection\":[\"Topnews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/20-09-2025-id929810.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/20-09-2025-id929810.html\",\"name\":\"20.09.2025 - Radio Romania Internazionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/20-09-2025-id929810.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/20-09-2025-id929810.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stiri-italiana-bleu-site-1269.jpg\",\"datePublished\":\"2025-09-20T13:44:44+00:00\",\"dateModified\":\"2025-09-20T16:22:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/20-09-2025-id929810.html#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/20-09-2025-id929810.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/20-09-2025-id929810.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stiri-italiana-bleu-site-1269.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stiri-italiana-bleu-site-1269.jpg\",\"width\":1269,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/20-09-2025-id929810.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Topnews\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"20.09.2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Romania Internazionale\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\",\"name\":\"Newsroom\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/author\\\/newsroom\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20.09.2025 - Radio Romania Internazionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html","og_locale":"it_IT","og_type":"article","og_title":"20.09.2025 - Radio Romania Internazionale","og_description":"Esercitazione \u2013 A partire da oggi, stanno iniziando ad entrare in Romania, via Curtici (ovest) le prime colonne di equipaggiamento militare delle truppe dei paesi membri NATO, che prenderanno parte all&#8217;esercitazione &#8220;Dacian Fall&#8221;, DAFA 2025, in programma in Romania e Bulgaria dal 20 ottobre al 13 novembre. Il principale obiettivo dell&#8217;esercitazione \u00e8 l&#8217;integrazione operativa delle [&hellip;]","og_url":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html","og_site_name":"Radio Romania Internazionale","article_published_time":"2025-09-20T13:44:44+00:00","article_modified_time":"2025-09-20T16:22:25+00:00","og_image":[{"width":1269,"height":720,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","type":"image\/jpeg"}],"author":"Newsroom","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Newsroom","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html"},"author":{"name":"Newsroom","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"headline":"20.09.2025","datePublished":"2025-09-20T13:44:44+00:00","dateModified":"2025-09-20T16:22:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html"},"wordCount":984,"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","articleSection":["Topnews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html","url":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html","name":"20.09.2025 - Radio Romania Internazionale","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","datePublished":"2025-09-20T13:44:44+00:00","dateModified":"2025-09-20T16:22:25+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","width":1269,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/20-09-2025-id929810.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/www.rri.ro\/it"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.rri.ro\/it\/news"},{"@type":"ListItem","position":3,"name":"Topnews","item":"https:\/\/www.rri.ro\/it\/news\/topnews"},{"@type":"ListItem","position":4,"name":"20.09.2025"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Romania Internazionale","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88","name":"Newsroom","url":"https:\/\/www.rri.ro\/it\/author\/newsroom"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/929810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/comments?post=929810"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/929810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media\/745145"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media?parent=929810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/categories?post=929810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/tags?post=929810"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/coauthors?post=929810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}