{"id":943829,"date":"2025-10-25T17:00:41","date_gmt":"2025-10-25T14:00:41","guid":{"rendered":"https:\/\/www.rri.ro\/?p=943829"},"modified":"2025-10-25T18:19:49","modified_gmt":"2025-10-25T15:19:49","slug":"25-10-2025","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html","title":{"rendered":"25.10.2025"},"content":{"rendered":"<p>Festa dell\u2019Esercito Romeno &#8211; Il presidente romeno Nicu\u015for Dan ha dichiarato oggi a Ia\u015fi (nord-est) che la modernizzazione dell&#8217;esercito romeno \u00e8 una priorit\u00e0. Egli ha sottolineato che non basta dire di volere la pace, ma bisogna essere responsabili e prepararsi a scoraggiare la guerra. Il presidente ha partecipato alla cerimonia militare e religiosa organizzata a Ia\u015fi, in occasione della Festa dell&#8217;Esercito Romeno. A sua volta, il presidente del Senato, Mircea Abrudean, ha affermato che la Romania \u00e8 oggi un Paese sicuro e un pilastro di stabilit\u00e0 nell&#8217;Europa orientale, e che i cittadini romeni beneficiano delle pi\u00f9 solide garanzie di sicurezza della nostra storia. Anche il primo ministro Ilie Bolojan ha affermato che un obiettivo importante in questo periodo \u00e8 rafforzare l&#8217;esercito, l&#8217;industria della difesa e le infrastrutture critiche e investire maggiormente nella formazione del personale e nella tecnologia. Sabato si \u00e8 celebrata la Giornata dell&#8217;Esercito attraverso eventi organizzati nelle principali guarnigioni del Paese, nelle basi militari in cui sono schierati i militari romeni e nei teatri operativi, nonch\u00e9 negli stati in cui la Romania ha addetti alla difesa accreditati e nelle capitali degli stati in cui il Paese ha rappresentanze permanenti. A Bucarest, presso la Tomba del Milite Ignoto nel Parco Carlo I, si \u00e8 svolta una cerimonia militare e religiosa con deposizione di corone di fiori, seguita dal cambio della guardia. Aerei militari dell&#8217;Aeronautica Militare Romena hanno sorvolato il monumento. Cerimonie militari e religiose si sono svolte anche nelle principali guarnigioni del Paese, presso i Monumenti degli Eroi, nonch\u00e9 presso i cimiteri e i monumenti dei militari romeni in Austria, Bosnia ed Erzegovina, Bulgaria, Repubblica Ceca, Repubblica di Moldavia e Ungheria.<\/p>\n<p>Nato &#8211; Un nuovo squadrone di aerei F-16 Fighting Falcon inizia una missione sotto il comando NATO. Lo ha annunciato il ministro della Difesa romeno, Ionu\u0163 Mo\u015fteanu. Secondo lui, si tratta del secondo squadrone di F-16 certificato per missioni NATO, una chiara dimostrazione della professionalit\u00e0 dell&#8217;Aeronautica Militare romena e della nostra capacit\u00e0 di operare al fianco degli alleati. Attualmente, la Romania dispone di tre squadroni che garantiscono la protezione dello spazio aereo: due romeni, a Fete\u015fti (sud-est) e C\u00e2mpia Turzii (centro), e uno alleato, composto da aerei Typhoon dell&#8217;Aeronautica Militare tedesca, a Mihail Kog\u0103lniceanu (sud-est). &#8220;Insieme, formano un vero e proprio ombrello di sicurezza sul fianco orientale della NATO. Ogni missione di polizia aerea, ogni ora di volo, ogni squadra dietro questi velivoli fa parte di uno sforzo collettivo: quello di preservare la pace e la sicurezza nella regione&#8221;, ha affermato il ministro Mo\u015fteanu.<\/p>\n<p>La Cattedrale Nazionale &#8211; Gli affreschi della Cattedrale Nazionale saranno consacrati domenica dal Patriarca Ecumenico Bartolomeo I di Costantinopoli e dal Patriarca Daniele della Chiesa Ortodossa Romena (maggioritaria), accompagnati da decine di gerarchi e sacerdoti. L&#8217;evento, a cui sono attese oltre centomila persone, segna il Centenario del Patriarcato Romeno. Nel 2025, ricorrono 140 anni dal riconoscimento della Chiesa Ortodossa Romena come Chiesa Autocefala e 100 anni dalla sua elevazione al rango di Patriarcato. La consacrazione dell&#8217;altare della Cattedrale Nazionale ha avuto luogo il 25 novembre 2018, anno del Centenario della Grande Unit\u00e0. La Cattedrale Nazionale \u00e8 alta 120 metri, con le campane che pesano complessivamente 33 tonnellate. L&#8217;architettura della Cattedrale rappresenta una sintesi tra tradizione e contemporaneit\u00e0, armonizzando elementi architettonici provenienti da diverse aree della Romania, nonch\u00e9 elementi monumentali di alcune cattedrali occidentali, tenendo conto che, oggi, gran parte della diaspora romena si trova in Occidente. I mosaici della Cattedrale Nazionale coprono una superficie di circa 25.000 metri quadrati. Attraverso la loro concezione iconografica, lo stile e il repertorio ornamentale, i mosaici traggono ispirazione sia dall&#8217;arte bizantina che da quella medievale romena.<\/p>\n<p>Salario minimo &#8211; In Romania, il Consiglio Nazionale Tripartito per il Dialogo Sociale si riunir\u00e0 alla met\u00e0 della prossima settimana per discutere l&#8217;opportunit\u00e0 di aumentare il salario minimo garantito, ha annunciato il Segretario Generale del Governo, Radu Oprea. Egl ha aggiunto che esistono solide argomentazioni a favore di un aumento, sia dal punto di vista giuridico, economico e sociale. Radu Oprea ha sottolineato che, nel contesto in cui quasi 850.000 romeni percepiscono il salario minimo, la diminuzione del reddito influisce sui consumi e sulla produttivit\u00e0 del lavoro. Il leader ad interim del PSD, Sorin Grindeanu, ha affermato che la Romania rischia una procedura di infrazione se non aumenta il salario minimo. Il premier liberale Ilie Bolojan, tuttavia, ha recentemente dichiarato che la coalizione di governo ha concordato di cercare di mantenere il salario minimo al livello attuale nel 2026. Il PSD e il PNL fanno parte della coalizione di governo, insieme all&#8217;USR e all&#8217;UDMR.<\/p>\n<p>Ora solare &#8211; La Romania, come la maggior parte dei paesi europei, passer\u00e0 all&#8217;ora solare nella notte tra sabato e domenica. Le lancette dell\u2019orologio saranno spostate indietro di un&#8217;ora, dalle 04:00 alle 03:00, e domenica sar\u00e0 il giorno pi\u00f9 lungo dell&#8217;anno. L&#8217;ora solare fa parte di un sistema di regolazione stagionale dell&#8217;ora introdotto per la prima volta in Europa nel XX secolo, con l&#8217;obiettivo di ottimizzare l&#8217;uso della luce naturale e ridurre il consumo energetico. Il cambio stagionale dell&#8217;ora continua a essere oggetto di dibattito a livello europeo. Sebbene la Commissione europea abbia proposto di eliminare questa pratica, gli Stati membri non hanno ancora raggiunto un consenso e la decisione finale sull&#8217;adozione permanente dell&#8217;ora legale o solare rimane a livello nazionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Festa dell\u2019Esercito Romeno &#8211; Il presidente romeno Nicu\u015for Dan ha dichiarato oggi a Ia\u015fi (nord-est) che la modernizzazione dell&#8217;esercito romeno \u00e8 una priorit\u00e0. Egli ha sottolineato che non basta dire di volere la pace, ma bisogna essere responsabili e prepararsi a scoraggiare la guerra. Il presidente ha partecipato alla cerimonia militare e religiosa organizzata a [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":745145,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[98934],"tags":[],"coauthors":[116091],"class_list":["post-943829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-topnews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>25.10.2025 - Radio Romania Internazionale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"25.10.2025 - Radio Romania Internazionale\" \/>\n<meta property=\"og:description\" content=\"Festa dell\u2019Esercito Romeno &#8211; Il presidente romeno Nicu\u015for Dan ha dichiarato oggi a Ia\u015fi (nord-est) che la modernizzazione dell&#8217;esercito romeno \u00e8 una priorit\u00e0. Egli ha sottolineato che non basta dire di volere la pace, ma bisogna essere responsabili e prepararsi a scoraggiare la guerra. Il presidente ha partecipato alla cerimonia militare e religiosa organizzata a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Romania Internazionale\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-25T14:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-25T15:19:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1269\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Newsroom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsroom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-10-2025-id943829.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-10-2025-id943829.html\"},\"author\":{\"name\":\"Newsroom\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"headline\":\"25.10.2025\",\"datePublished\":\"2025-10-25T14:00:41+00:00\",\"dateModified\":\"2025-10-25T15:19:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-10-2025-id943829.html\"},\"wordCount\":891,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-10-2025-id943829.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stiri-italiana-bleu-site-1269.jpg\",\"articleSection\":[\"Topnews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-10-2025-id943829.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-10-2025-id943829.html\",\"name\":\"25.10.2025 - Radio Romania Internazionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-10-2025-id943829.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-10-2025-id943829.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stiri-italiana-bleu-site-1269.jpg\",\"datePublished\":\"2025-10-25T14:00:41+00:00\",\"dateModified\":\"2025-10-25T15:19:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-10-2025-id943829.html#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-10-2025-id943829.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-10-2025-id943829.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stiri-italiana-bleu-site-1269.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stiri-italiana-bleu-site-1269.jpg\",\"width\":1269,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-10-2025-id943829.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Topnews\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"25.10.2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Romania Internazionale\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\",\"name\":\"Newsroom\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/author\\\/newsroom\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"25.10.2025 - Radio Romania Internazionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html","og_locale":"it_IT","og_type":"article","og_title":"25.10.2025 - Radio Romania Internazionale","og_description":"Festa dell\u2019Esercito Romeno &#8211; Il presidente romeno Nicu\u015for Dan ha dichiarato oggi a Ia\u015fi (nord-est) che la modernizzazione dell&#8217;esercito romeno \u00e8 una priorit\u00e0. Egli ha sottolineato che non basta dire di volere la pace, ma bisogna essere responsabili e prepararsi a scoraggiare la guerra. Il presidente ha partecipato alla cerimonia militare e religiosa organizzata a [&hellip;]","og_url":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html","og_site_name":"Radio Romania Internazionale","article_published_time":"2025-10-25T14:00:41+00:00","article_modified_time":"2025-10-25T15:19:49+00:00","og_image":[{"width":1269,"height":720,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","type":"image\/jpeg"}],"author":"Newsroom","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Newsroom","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html"},"author":{"name":"Newsroom","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"headline":"25.10.2025","datePublished":"2025-10-25T14:00:41+00:00","dateModified":"2025-10-25T15:19:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html"},"wordCount":891,"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","articleSection":["Topnews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html","url":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html","name":"25.10.2025 - Radio Romania Internazionale","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","datePublished":"2025-10-25T14:00:41+00:00","dateModified":"2025-10-25T15:19:49+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","width":1269,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-10-2025-id943829.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/www.rri.ro\/it"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.rri.ro\/it\/news"},{"@type":"ListItem","position":3,"name":"Topnews","item":"https:\/\/www.rri.ro\/it\/news\/topnews"},{"@type":"ListItem","position":4,"name":"25.10.2025"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Romania Internazionale","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88","name":"Newsroom","url":"https:\/\/www.rri.ro\/it\/author\/newsroom"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/943829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/comments?post=943829"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/943829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media\/745145"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media?parent=943829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/categories?post=943829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/tags?post=943829"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/coauthors?post=943829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}