{"id":944406,"date":"2025-10-27T18:48:11","date_gmt":"2025-10-27T16:48:11","guid":{"rendered":"https:\/\/www.rri.ro\/?p=944406"},"modified":"2025-10-27T20:15:58","modified_gmt":"2025-10-27T18:15:58","slug":"27-10-2025-aggiornamento","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html","title":{"rendered":"27.10.2025 (aggiornamento)"},"content":{"rendered":"<p>UE &#8211; Il commissario Europeo per l&#8217;Economia, Valdis Dombrovskis, effettua una visita di due giorni a\u00a0 Bucarest per discutere gli ultimi sviluppi economici e di bilancio della Romania. Sul tavolo anche l&#8217;attuazione del Piano Nazionale di Ripresa e Resilienza, nonch\u00e8 le priorit\u00e0 politiche dell&#8217;Unione. Il commissario visiter\u00e0 alcuni progetti finanziati attraverso il Piano Nazionale di Ripresa e Resilienza, insieme al ministro degli Investimenti e dei Progetti Europei, Drago\u015f P\u00eeslaru, e incontrer\u00e0 il governatore della Banca Centrale, Mugur Is\u0103rescu. Inoltre, Dombrovskis ha previsti colloqui il presidente Nicu\u015for Dan, con il premier Ilie Bolojan, con il ministro delle Finanze, Alexandru Nazare, nonch\u00e8 con rappresentanti del Parlamento.<\/p>\n<p>&nbsp;<\/p>\n<p>Energia \u2013 L\u2019Unione Europea intende offrire linee di finanziamento di fino a 30 miliardi di euro agli stati membri per l\u2019attuazione di progetti di interconnessione energetica. Lo ha annunciato il ministro dell\u2019Energia romeno, Bogdan Ivan, precisando che, in questo senso, la Romania si propone di assumere il ruolo di coordinatore di una strategia comune con i paesi vicini, da presentare alla Commissione Europea in vista del futuro bilancio comunitario pluriennale. Il ministro ha affermato che, in termini di reddito, i romeni pagano l\u2019elettricit\u00e0 pi\u00f9 cara dell\u2019Unione Europea. Ivan ha spiegato che la Commissione Europea \u00e8 aperta all\u2019individuazione di \u00a0soluzioni volte a risolvere questo problema sia attraverso normative e investimenti nelle infrastrutture per realizzare un\u2019interconnessione con l\u2019energia a basso costo fornita dall\u2019Europa occidentale, sia attraverso l\u2019apertura di nuove capacit\u00e0 produttive a livello nazionale. Per due giorni, la Romania ha ospitato un incontro dei ministri dell\u2019energia di 17 stati europei con il commissario europeo per l\u2019Energia, Dan Jorgensen. I partecipanti hanno esaminato progetti comuni per ridurre la dipendenza degli stati della regione dalle importazioni di energia dalla Russia.<\/p>\n<p>&nbsp;<\/p>\n<p>Difesa \u2013 A Bucarest, i senatori esaminano questa settimana il disegno di legge sulla preparazione della popolazione alla difesa, secondo il quale i giovani tra i 18 e i 35 anni possono arruolarsi volontariamente in un programma di addestramento militare di base della durata di quattro mesi. Il documento ha gi\u00e0 superato il voto della Camera dei Deputati e si trova con la procedura \u00a0procedura d\u2019urgenza all\u2019esame del Senato. Stando al ddl, al termine del periodo di addestramento, i volontari riceveranno tre stipendi lordi medi e rimarranno nella riserva operativa dell\u2019esercito romeno. Queste misure hanno lo scopo di ringiovanire la riserva operativa dell\u2019esercito, ha spiegato il ministro della Difesa, Ionu\u0163 Mo\u015fteanu. D\u2019altra parte, alla Camera dei Deputati, \u00e8 atteso anche il disegno di legge sulla difesa nazionale che sar\u00e0 sottoposto al dibattito delle commissioni specializzate. La normativa stabilisce il modo in cui viene organizzata e funziona la difesa della Romania, nonch\u00e8 le \u00a0istituzioni e i meccanismi responsabili per la protezione del territorio.<\/p>\n<p>&nbsp;<\/p>\n<p>Retribuzione \u2013 Il Consiglio Nazionale Tripartito, che riunisce sindacati, associazioni dei datori di lavoro e rappresentanti del governo, esaminano dopodomani l\u2019opportunit\u00e0 dell\u2019aumento dello stipendio minimo in Romania. Il primo ministro liberale Ilie Bolojan ha affermato che la coalizione di governo aveva concordato di mantenere la retribuzione al livello attuale anche nel 2026, mentre il leader ad interim del PSD, Sorin Grindeanu, ha richiamato l\u2019attenzione sul fatto che \u00e8 in gioco una direttiva europea, che la Romania dovrebbe rispettare. Dal canto suo, il presidente Nicu\u015for Dan ha dichiarato che la direttiva in causa \u00e8 stata contestata presso la Corte di Giustizia dell\u2019UE e ha specificato che, anche nel caso in cui venisse mantenuta, \u00e8 comunque necessaria una discussione sul possibile aumento del salario minimo, che attualmente ammonta a 4.050 lei lordi (800 euro). Sempre mercoled\u00ec, quattro importanti confederazioni sindacali annunciano manifestazioni di protesta davanti alla sede del governo contro \u00a0l\u2019austerit\u00e0, nonch\u00e8 contro il \u201cdisprezzo per il lavoro e di coloro che lavorano\u201d, hanno dichiarato i leader sindacali. I sindacati sollecitano l\u2019aumento del salario minimo e delle pensioni, il rispetto dei diritti legali e contrattuali dei dipendenti, una tassazione equa, la fine delle misure di austerit\u00e0 applicabili solo alla popolazione, nonch\u00e9 la tutela dei posti di lavoro e degli investimenti, escludendo i licenziamenti.<\/p>\n<p>&nbsp;<\/p>\n<p>Governo &#8211; Il governo romeno ha approvato la modifica dell&#8217;ordinanza che limita le spese dei comuni fino alla fine dell&#8217;anno, eliminando anche una serie di provvedimenti che impedivano il normale funzionamento delle istituzioni. Uno dei settori pi\u00f9 colpiti \u00e8 stato quello della cultura, la decisione odierna consentendo la continuazione del finanziamento per diverse attivit\u00e0. Inoltre, le spese potranno essere sostenute tramite donazioni e sponsorizzazioni, in conformit\u00e0 con la missione pubblica dell&#8217;istituzione. Saranno permesse inoltre spese per la partecipazione a vari festival artistici, fiere o altri eventi culturali. Per evitare simili blocchi nel futuro, il Ministero della Cultura ha annunciato che inizier\u00e0 la modifica del quadro legislativo, con l\u2019obiettivo di separare i finanziamenti destinati alle attivit\u00e0 culturali da altri tipi di spese.<\/p>\n<p>&nbsp;<\/p>\n<p>Amministrative Bucarest \u2013 Il socialdemocratico Daniel B\u0103lu\u0163\u0103, sindaco del Rione 4 di Bucarest, \u00e8 stato designato dal partito come candidato per il Comune della Capitale, mentre il liberale Ciprian Ciucu, sindaco del Rione 6, ha annunciato la sua candidatura per la carica. Secondo un sondaggio condotto da Avangarde su un campione di 1.000 persone, i due sono in testa negli intenti di voto dei bucarestini: Daniel B\u0103lu\u0163\u0103, con il 25%, e Ciprian Ciucu, con il 23%. Seguono il deputato dell\u2019USR, C\u0103t\u0103lin Drul\u0103, con il 18%, e la giornalista indipendente Anca Alexandrescu \u2013 16%. Le elezioni amministrative per la carica di sindaco generale di Bucarest si terranno il 7 dicembre. La carica \u00e8 rimasta vacante dopo l\u2019elezione di Nicu\u0219or Dan a presidente della Romania. Il sondaggio \u00e8 stato condotto tra il 19 e il 25 ottobre 2025 su un campione di 1.000 intervistati di Bucarest, e presenta un margine di errore di +\/- 3,2%.<\/p>\n<p>&nbsp;<\/p>\n<p>Festa \u2013 I cristiani ortodossi hanno celebrato oggi San Demetrio il Nuovo, patrono di Bucarest e della Valacchia, le cui reliquie si trovano nella Cattedrale del Patriarcato di Bucarest. La Divina Liturgia \u00e8 stata celebrata dal Patriarca della Chiesa Ortodossa Romena, Daniel, insieme al Patriarca Ecumenico Bartolomeo I di Costantinopoli. Sempre oggi, il presidente Nicu\u0219or Dan ha conferito onorificenze al Patriarca Ecumenico e al Patriarcato di Bucarest. Ieri, Bartolomeo I e il Patriarca Daniel hanno celebrato la messa di consacrazione e degli affreschi della Cattedrale Nazionale.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UE &#8211; Il commissario Europeo per l&#8217;Economia, Valdis Dombrovskis, effettua una visita di due giorni a\u00a0 Bucarest per discutere gli ultimi sviluppi economici e di bilancio della Romania. Sul tavolo anche l&#8217;attuazione del Piano Nazionale di Ripresa e Resilienza, nonch\u00e8 le priorit\u00e0 politiche dell&#8217;Unione. Il commissario visiter\u00e0 alcuni progetti finanziati attraverso il Piano Nazionale di [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":723460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[98934],"tags":[],"coauthors":[116091],"class_list":["post-944406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-topnews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>27.10.2025 (aggiornamento) - Radio Romania Internazionale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"27.10.2025 (aggiornamento) - Radio Romania Internazionale\" \/>\n<meta property=\"og:description\" content=\"UE &#8211; Il commissario Europeo per l&#8217;Economia, Valdis Dombrovskis, effettua una visita di due giorni a\u00a0 Bucarest per discutere gli ultimi sviluppi economici e di bilancio della Romania. Sul tavolo anche l&#8217;attuazione del Piano Nazionale di Ripresa e Resilienza, nonch\u00e8 le priorit\u00e0 politiche dell&#8217;Unione. Il commissario visiter\u00e0 alcuni progetti finanziati attraverso il Piano Nazionale di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Romania Internazionale\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T16:48:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T18:15:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Newsroom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsroom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/27-10-2025-aggiornamento-id944406.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/27-10-2025-aggiornamento-id944406.html\"},\"author\":{\"name\":\"Newsroom\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"headline\":\"27.10.2025 (aggiornamento)\",\"datePublished\":\"2025-10-27T16:48:11+00:00\",\"dateModified\":\"2025-10-27T18:15:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/27-10-2025-aggiornamento-id944406.html\"},\"wordCount\":1028,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/27-10-2025-aggiornamento-id944406.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"articleSection\":[\"Topnews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/27-10-2025-aggiornamento-id944406.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/27-10-2025-aggiornamento-id944406.html\",\"name\":\"27.10.2025 (aggiornamento) - Radio Romania Internazionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/27-10-2025-aggiornamento-id944406.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/27-10-2025-aggiornamento-id944406.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"datePublished\":\"2025-10-27T16:48:11+00:00\",\"dateModified\":\"2025-10-27T18:15:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/27-10-2025-aggiornamento-id944406.html#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/27-10-2025-aggiornamento-id944406.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/27-10-2025-aggiornamento-id944406.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/27-10-2025-aggiornamento-id944406.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Topnews\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"27.10.2025 (aggiornamento)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Romania Internazionale\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\",\"name\":\"Newsroom\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/author\\\/newsroom\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"27.10.2025 (aggiornamento) - Radio Romania Internazionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html","og_locale":"it_IT","og_type":"article","og_title":"27.10.2025 (aggiornamento) - Radio Romania Internazionale","og_description":"UE &#8211; Il commissario Europeo per l&#8217;Economia, Valdis Dombrovskis, effettua una visita di due giorni a\u00a0 Bucarest per discutere gli ultimi sviluppi economici e di bilancio della Romania. Sul tavolo anche l&#8217;attuazione del Piano Nazionale di Ripresa e Resilienza, nonch\u00e8 le priorit\u00e0 politiche dell&#8217;Unione. Il commissario visiter\u00e0 alcuni progetti finanziati attraverso il Piano Nazionale di [&hellip;]","og_url":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html","og_site_name":"Radio Romania Internazionale","article_published_time":"2025-10-27T16:48:11+00:00","article_modified_time":"2025-10-27T18:15:58+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","type":"image\/jpeg"}],"author":"Newsroom","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Newsroom","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html"},"author":{"name":"Newsroom","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"headline":"27.10.2025 (aggiornamento)","datePublished":"2025-10-27T16:48:11+00:00","dateModified":"2025-10-27T18:15:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html"},"wordCount":1028,"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","articleSection":["Topnews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html","url":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html","name":"27.10.2025 (aggiornamento) - Radio Romania Internazionale","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","datePublished":"2025-10-27T16:48:11+00:00","dateModified":"2025-10-27T18:15:58+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/27-10-2025-aggiornamento-id944406.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/www.rri.ro\/it"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.rri.ro\/it\/news"},{"@type":"ListItem","position":3,"name":"Topnews","item":"https:\/\/www.rri.ro\/it\/news\/topnews"},{"@type":"ListItem","position":4,"name":"27.10.2025 (aggiornamento)"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Romania Internazionale","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88","name":"Newsroom","url":"https:\/\/www.rri.ro\/it\/author\/newsroom"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/944406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/comments?post=944406"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/944406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media\/723460"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media?parent=944406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/categories?post=944406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/tags?post=944406"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/coauthors?post=944406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}