{"id":959019,"date":"2025-12-04T16:51:56","date_gmt":"2025-12-04T14:51:56","guid":{"rendered":"https:\/\/www.rri.ro\/?p=959019"},"modified":"2025-12-04T18:47:29","modified_gmt":"2025-12-04T16:47:29","slug":"04-12-2025","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html","title":{"rendered":"04.12.2025"},"content":{"rendered":"<p>Romania-Austria \u2013 L&#8217;Austria sostiene l&#8217;adesione della Romania all&#8217;Organizzazione per la Cooperazione e lo Sviluppo Economico. Lo ha dichiarato il cancelliere Christian Stocker in una conferenza stampa congiunta a Vienna assieme al premier romeno, Ilie Bolojan. &#8220;La Romania \u00e8 un partner sul quale possiamo contare, date le nostre relazioni storiche, politiche ed economiche di lunga data. Siamo inoltre uniti da una comunit\u00e0 molto numerosa di romeni residenti in Austria, che fornisce un contributo importante all&#8217;economia e alla vita sociale del Paese&#8221;, ha affermato Christian Stocker. Il cancelliere ha sottolineato che l&#8217;Austria \u00e8 il secondo maggiore investitore in Romania, ma anche il fatto che numerose aziende romene investono in Austria. Riguardo alla guerra in Ucraina, il cncelliere austriaco ha detto che la Romania e l&#8217;Austria desiderano una pace basata sui diritti dei popoli e che l&#8217;Unione Europea e l&#8217;Ucraina dovrebbero trovarsi al tavolo dei negoziati. Non si pu\u00f2 pensare a una pace duratura senza che l&#8217;Ucraina e i paesi dell&#8217;UE concordino sulle soluzioni proposte, ha affermato dal canto suo, Ilie Bolojan. Per quanto riguarda l&#8217;immigrazione, il cancelliere austriaco ha ringraziato per il contributo della Romania alla protezione delle frontiere e alla lotta alla migrazione clandestina. La Romania, paese di confine dell&#8217;UE, ha la responsabilit\u00e0 di non consentire il transito illegale delle frontiere, cosa che ha fatto in tutti questi anni, ha affermato Ilie Bolojan. Ha aggiunto che, in questi anni, il numero di immigrati clandestini che hanno attraversato i confini dell&#8217;Unione, attraverso l&#8217;area sud-orientale, \u00e8 diminuito notevolmente. Sul tavolo delle discussioni anche temi legati all\u2019energia, cooperazione economica, investimenti, sicurezza sul Mar Nero e allargamento dell&#8217;UE.<\/p>\n<p>&nbsp;<\/p>\n<p>Ucraina \u2013 La Russia otterr\u00e0 il controllo del Donbass e della Novorossiya con la forza o attraverso il ritiro dell&#8217;esercito ucraino. Lo ha affermato il presidente russo, Vladimir Putin, subito dopo le discussioni avute a Mosca con l&#8217;inviato speciale della Casa Bianca, Steve Witkoff, sul piano di pace proposto dagli americani. Putin ha definito l&#8217;incontro come \u201cutile\u201d, ma le sue richieste lasciano intendere che non sia disposto a fare concessioni. La cosiddetta Novorossiya include tutta l&#8217;Ucraina meridionale, fino al confine con la Romania e la Repubblica di Moldova, territorio rivendicato per la prima volta da Putin nel 2014, poco dopo l&#8217;invasione della Penisola di Crimea. Putin ha parlato della Novorossiya anche in un saggio del 2022 in cui negava l&#8217;esistenza di una nazione ucraina, nonch\u00e8 tre giorni prima dell&#8217;invasione dell&#8217;Ucraina.<\/p>\n<p>&nbsp;<\/p>\n<p>Mar Nero &#8211; Il Servizio di Sicurezza Ucraino (SBU) afferma che tutti i suoi droni marittimi impiegati in missioni operative nella regione del Mar Nero sono stati identificati, che nessuno \u00e8 stato perso oppure entrato nelle acque territoriali della Romania. Secondo la fonte, citata dalle agenzie di stampa internazionali, l&#8217;Ucraina rispetta rigorosamente il diritto internazionale, non viola i confini internazionali e tratta i suoi \u00a0partner con rispetto. La reazione arriva dopo che il Ministero della Difesa romeno ha annunciato che un drone marittimo rilevato nel Mar Nero, a 36 miglia a est di Costanza (la pi\u00f9 grande citt\u00e0 portuale romena), in grado di mettere in pericolo la navigazione, \u00e8 stato neutralizzato dai sommozzatori militari delle Forze Navali Romene. Nei quasi quattro anni trascorsi dall&#8217;invasione russa dell&#8217;Ucraina, circa 150 mine navali sono state neutralizzate nel Mar Nero, sette delle quali distrutte dalla Marina romena. Le preoccupazioni sulla sicurezza della navigazione sul Mar Nero dopo gli attacchi alle petroliere russe, alcuni rivendicati dall&#8217;Ucraina, hanno portato a un aumento dei premi assicurativi in \u200b\u200bun tratto di mare cruciale per il trasporto di grano, petrolio o greggio. Tre paesi rivieraschi, Romania, Bulgaria e Turchia, tutti alleati NATO, hanno creato una task force congiunta per disinnescare le mine vaganti.<\/p>\n<p>&nbsp;<\/p>\n<p>Insolvenze \u2013 Il numero di aziende romene che hanno dichiarato la loro insolvenza a novembre \u00e8 aumentato di quasi il 50% rispetto allo stesso periodo dell&#8217;anno scorso. Secondo una piattaforma di analisi finanziaria, la maggior parte delle insolvenze \u00e8 stata registrata nei settori ristorazione, edilizia e trasporto merci su strada. Secondo gli esperti, questa situazione dimostra che le aziende hanno difficolt\u00e0 a coprire le spese totali, causa l&#8217;aumento dei costi, delle imposte e degli obblighi fiscali, nonch\u00e8 in seguito all&#8217;aumento dei prezzi per l&#8217;energia.<\/p>\n<p>&nbsp;<\/p>\n<p>Difesa \u2013 Il Ministero della Difesa romeno ha annunciato la firma del contratto per l&#8217;acquisizione di una corvetta leggera classe HISAR dal governo turco. Il prezzo di acquisto \u00e8 di 223 milioni di euro e include, oltre al costo della nave, l&#8217;addestramento del personale, nonch\u00e8 un pacchetto di supporto logistico. La nave fa parte del programma di equipaggiamento delle Forze Navali Romene, volto ad aumentare l&#8217;efficienza delle missioni di protezione delle infrastrutture marittime critiche, pattugliamento e missioni di combattimento. L&#8217;acquisizione \u00e8 stata approvata dal Consiglio Supremo dei Difesa a marzo.<\/p>\n<p>&nbsp;<\/p>\n<p>Premio \u2013 L&#8217;attore Victor Rebengiuc ha ricevuto il premio &#8220;Romania Europea 2025&#8221; , conferito dall&#8217;Associazione Iniziativa Culturale Democratica Europea. Alla cerimonia di premiazione ha partecipato anche il presidente Nicus\u0219or Dan, il quale ha elogiato la dedizione dell&#8217;attore, sottolineando anche il suo impegno sociale. A settembre, Victor Rebengiuc, una delle figure pi\u00f9 apprezzate dell&#8217;arte e dell&#8217;azione civica romena, ha annunciato il suo ritiro dall&#8217;attivit\u00e0, all&#8217;et\u00e0 di 92 anni, dopo una straordinaria carriera di oltre sette decenni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Romania-Austria \u2013 L&#8217;Austria sostiene l&#8217;adesione della Romania all&#8217;Organizzazione per la Cooperazione e lo Sviluppo Economico. Lo ha dichiarato il cancelliere Christian Stocker in una conferenza stampa congiunta a Vienna assieme al premier romeno, Ilie Bolojan. &#8220;La Romania \u00e8 un partner sul quale possiamo contare, date le nostre relazioni storiche, politiche ed economiche di lunga data. [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":723460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[98934],"tags":[],"coauthors":[116091],"class_list":["post-959019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-topnews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>04.12.2025 - Radio Romania Internazionale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"04.12.2025 - Radio Romania Internazionale\" \/>\n<meta property=\"og:description\" content=\"Romania-Austria \u2013 L&#8217;Austria sostiene l&#8217;adesione della Romania all&#8217;Organizzazione per la Cooperazione e lo Sviluppo Economico. Lo ha dichiarato il cancelliere Christian Stocker in una conferenza stampa congiunta a Vienna assieme al premier romeno, Ilie Bolojan. &#8220;La Romania \u00e8 un partner sul quale possiamo contare, date le nostre relazioni storiche, politiche ed economiche di lunga data. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Romania Internazionale\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-04T14:51:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-04T16:47:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Newsroom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsroom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/04-12-2025-id959019.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/04-12-2025-id959019.html\"},\"author\":{\"name\":\"Newsroom\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"headline\":\"04.12.2025\",\"datePublished\":\"2025-12-04T14:51:56+00:00\",\"dateModified\":\"2025-12-04T16:47:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/04-12-2025-id959019.html\"},\"wordCount\":872,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/04-12-2025-id959019.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"articleSection\":[\"Topnews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/04-12-2025-id959019.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/04-12-2025-id959019.html\",\"name\":\"04.12.2025 - Radio Romania Internazionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/04-12-2025-id959019.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/04-12-2025-id959019.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"datePublished\":\"2025-12-04T14:51:56+00:00\",\"dateModified\":\"2025-12-04T16:47:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/04-12-2025-id959019.html#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/04-12-2025-id959019.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/04-12-2025-id959019.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/04-12-2025-id959019.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Topnews\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"04.12.2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Romania Internazionale\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\",\"name\":\"Newsroom\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/author\\\/newsroom\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"04.12.2025 - Radio Romania Internazionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html","og_locale":"it_IT","og_type":"article","og_title":"04.12.2025 - Radio Romania Internazionale","og_description":"Romania-Austria \u2013 L&#8217;Austria sostiene l&#8217;adesione della Romania all&#8217;Organizzazione per la Cooperazione e lo Sviluppo Economico. Lo ha dichiarato il cancelliere Christian Stocker in una conferenza stampa congiunta a Vienna assieme al premier romeno, Ilie Bolojan. &#8220;La Romania \u00e8 un partner sul quale possiamo contare, date le nostre relazioni storiche, politiche ed economiche di lunga data. [&hellip;]","og_url":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html","og_site_name":"Radio Romania Internazionale","article_published_time":"2025-12-04T14:51:56+00:00","article_modified_time":"2025-12-04T16:47:29+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","type":"image\/jpeg"}],"author":"Newsroom","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Newsroom","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html"},"author":{"name":"Newsroom","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"headline":"04.12.2025","datePublished":"2025-12-04T14:51:56+00:00","dateModified":"2025-12-04T16:47:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html"},"wordCount":872,"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","articleSection":["Topnews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html","url":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html","name":"04.12.2025 - Radio Romania Internazionale","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","datePublished":"2025-12-04T14:51:56+00:00","dateModified":"2025-12-04T16:47:29+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/04-12-2025-id959019.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/www.rri.ro\/it"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.rri.ro\/it\/news"},{"@type":"ListItem","position":3,"name":"Topnews","item":"https:\/\/www.rri.ro\/it\/news\/topnews"},{"@type":"ListItem","position":4,"name":"04.12.2025"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Romania Internazionale","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88","name":"Newsroom","url":"https:\/\/www.rri.ro\/it\/author\/newsroom"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/959019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/comments?post=959019"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/959019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media\/723460"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media?parent=959019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/categories?post=959019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/tags?post=959019"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/coauthors?post=959019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}