{"id":961981,"date":"2025-12-13T16:56:29","date_gmt":"2025-12-13T14:56:29","guid":{"rendered":"https:\/\/www.rri.ro\/?p=961981"},"modified":"2025-12-13T17:46:16","modified_gmt":"2025-12-13T15:46:16","slug":"13-12-2025","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html","title":{"rendered":"13.12.2025"},"content":{"rendered":"<p>Proteste &#8211; Le proteste iniziate a met\u00e0 settimana per la riforma delle leggi sulla Giustizia e per le dimissioni dei responsabili di abusi nel sistema giudiziario sono continuate anche nel fine settimana a Bucarest e in altre citt\u00e0 della Romania, ma anche all&#8217;estero. D\u2019altra parte, la petizione lanciata dalle organizzazioni non governative Declic e Funky Citizens per la modifica delle leggi sulla Giustizia sta raggiungendo 150.000 firme. I firmatari chiedono al primo ministro e al presidente della Romania di avviare una vera riforma del sistema giudiziario, attraverso una procedura trasparente e onesta, che vada oltre le semplici dichiarazioni pubbliche. Le principali richieste dei manifestanti sono il ripristino dell&#8217;indipendenza dei giudici, l&#8217;abolizione dell&#8217;immunit\u00e0 de facto dei magistrati, la riduzione del controllo esercitato dal Consiglio Superiore della Magistratura sul sistema giudiziario o la revoca urgente dei capi delle procure. Le proteste sono iniziate dopo le rivelazioni di un documentario realizzato da Recorder sui problemi del sistema giudiziario romeno. Nel reportage sono presentati diversi procuratori e giudici, alcuni con identit\u00e0 protette, che rivelano il modo in cui la dirigenza della Corte d&#8217;Appello di Bucarest sostituiva sistematicamente i giudici per ottenere sentenze favorevoli a persone accusate di corruzione. Centinaia di magistrati hanno denunciato pubblicamente gli abusi nel sistema giudiziario. La Sezione Giudici del Consiglio Superiore della Magistratura ha deciso di segnalare l\u2019Ispezione Giudiziaria per effettuare verifiche in relazione alle questioni segnalate nel documentario presentato da Recorder.<\/p>\n<p>&nbsp;<\/p>\n<p>BEI &#8211; La Banca Europea per gli Investimenti aumenter\u00e0 nel 2026 il valore dei prestiti destinati ai progetti per la difesa fino a 4,5 miliardi di euro e potrebbe rivedere al rialzo le cifre in caso di maggiore domanda. Lo ha dichiarato alla Reuters la presidente dell&#8217;istituzione, Nadia Calvino, precisando che &#8220;ci stiamo concentrando in particolare sulla mobilit\u00e0 militare, sulle infrastrutture critiche, sul confine orientale e sui sistemi anti-drone&#8221;. I fondi saranno stanziati dalla somma disponibile per i prestiti nel 2026, stimata a 100 miliardi di euro, lo stesso livello del 2025. D\u2019altra parte, oltre la met\u00e0 dei prestiti previsti nel 2026 sar\u00e0 destinata a progetti che contribuiranno a combattere i mutamenti climatici. La BEI erogher\u00e0 fondi anche attraverso TechEU, \u00a0programma che mira a investire 70 miliardi di euro nello sviluppo delle aziende tecnologiche europee.<\/p>\n<p>&nbsp;<\/p>\n<p>Energia &#8211; E&#8217; entrata in funzione la pi\u00f9 importante capacit\u00e0 di accumulo di energia a batteria operativa in Romania. Secondo il ministro dell&#8217;Energia, Bogdan Ivan, al momento, si tratta di una delle soluzioni pi\u00f9 efficienti per ridurre gli squilibri del sistema, integrare meglio l&#8217;energia prodotta dai prosumer e, soprattutto, mantenere i costi sotto controllo per i cittadini. Sempre ieri, a C\u00e2mpia Turzii (centro), sono iniziati i lavori per una centrale elettrica a gas a ciclo combinato, un investimento che garantir\u00e0 energia sicura e costante, essenziale per l&#8217;equilibrio del sistema.<\/p>\n<p>&nbsp;<\/p>\n<p>Influenza- L&#8217;Istituto Nazionale Cantacuzino ha confermato che in Romania \u00e8 stato rilevato il ceppo del virus influenzale circolante a livello internazionale, che secondo il Centro Europeo per la Prevenzione e il Controllo delle Malattie presenta un rischio moderato per la popolazione. Tuttavia, l&#8217;Istituto Nazionale di Sanit\u00e0 Pubblica richiama l&#8217;attenzione sul fatto che la situazione pu\u00f2 diventare pericolosa per le persone incluse in determinate categorie. In questo senso, il rischio di sviluppare una malattia grave risulta elevato per le persone di et\u00e0 superiore ai 65 anni, per coloro che soffrono di malattie metaboliche, polmonari, cardiovascolari, neuromuscolari o altre malattie croniche preesistenti, per le donne in gravidanza, le persone con difese immunitarie basse o per le persone che vivono in strutture di assistenza a lungo termine. Gli specialisti raccomandano alla popolazione di vaccinarsi, di mantenere l&#8217;igiene, nonch\u00e8 di evitare gli spazi affollati.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proteste &#8211; Le proteste iniziate a met\u00e0 settimana per la riforma delle leggi sulla Giustizia e per le dimissioni dei responsabili di abusi nel sistema giudiziario sono continuate anche nel fine settimana a Bucarest e in altre citt\u00e0 della Romania, ma anche all&#8217;estero. D\u2019altra parte, la petizione lanciata dalle organizzazioni non governative Declic e Funky [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":723460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[98934],"tags":[],"coauthors":[116091],"class_list":["post-961981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-topnews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>13.12.2025 - Radio Romania Internazionale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"13.12.2025 - Radio Romania Internazionale\" \/>\n<meta property=\"og:description\" content=\"Proteste &#8211; Le proteste iniziate a met\u00e0 settimana per la riforma delle leggi sulla Giustizia e per le dimissioni dei responsabili di abusi nel sistema giudiziario sono continuate anche nel fine settimana a Bucarest e in altre citt\u00e0 della Romania, ma anche all&#8217;estero. D\u2019altra parte, la petizione lanciata dalle organizzazioni non governative Declic e Funky [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Romania Internazionale\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-13T14:56:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-13T15:46:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Newsroom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsroom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/13-12-2025-id961981.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/13-12-2025-id961981.html\"},\"author\":{\"name\":\"Newsroom\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"headline\":\"13.12.2025\",\"datePublished\":\"2025-12-13T14:56:29+00:00\",\"dateModified\":\"2025-12-13T15:46:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/13-12-2025-id961981.html\"},\"wordCount\":608,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/13-12-2025-id961981.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"articleSection\":[\"Topnews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/13-12-2025-id961981.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/13-12-2025-id961981.html\",\"name\":\"13.12.2025 - Radio Romania Internazionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/13-12-2025-id961981.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/13-12-2025-id961981.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"datePublished\":\"2025-12-13T14:56:29+00:00\",\"dateModified\":\"2025-12-13T15:46:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/13-12-2025-id961981.html#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/13-12-2025-id961981.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/13-12-2025-id961981.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/13-12-2025-id961981.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Topnews\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"13.12.2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Romania Internazionale\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\",\"name\":\"Newsroom\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/author\\\/newsroom\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"13.12.2025 - Radio Romania Internazionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html","og_locale":"it_IT","og_type":"article","og_title":"13.12.2025 - Radio Romania Internazionale","og_description":"Proteste &#8211; Le proteste iniziate a met\u00e0 settimana per la riforma delle leggi sulla Giustizia e per le dimissioni dei responsabili di abusi nel sistema giudiziario sono continuate anche nel fine settimana a Bucarest e in altre citt\u00e0 della Romania, ma anche all&#8217;estero. D\u2019altra parte, la petizione lanciata dalle organizzazioni non governative Declic e Funky [&hellip;]","og_url":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html","og_site_name":"Radio Romania Internazionale","article_published_time":"2025-12-13T14:56:29+00:00","article_modified_time":"2025-12-13T15:46:16+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","type":"image\/jpeg"}],"author":"Newsroom","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Newsroom","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html"},"author":{"name":"Newsroom","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"headline":"13.12.2025","datePublished":"2025-12-13T14:56:29+00:00","dateModified":"2025-12-13T15:46:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html"},"wordCount":608,"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","articleSection":["Topnews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html","url":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html","name":"13.12.2025 - Radio Romania Internazionale","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","datePublished":"2025-12-13T14:56:29+00:00","dateModified":"2025-12-13T15:46:16+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/13-12-2025-id961981.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/www.rri.ro\/it"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.rri.ro\/it\/news"},{"@type":"ListItem","position":3,"name":"Topnews","item":"https:\/\/www.rri.ro\/it\/news\/topnews"},{"@type":"ListItem","position":4,"name":"13.12.2025"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Romania Internazionale","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88","name":"Newsroom","url":"https:\/\/www.rri.ro\/it\/author\/newsroom"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/961981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/comments?post=961981"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/961981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media\/723460"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media?parent=961981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/categories?post=961981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/tags?post=961981"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/coauthors?post=961981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}