{"id":963980,"date":"2025-12-18T19:21:49","date_gmt":"2025-12-18T17:21:49","guid":{"rendered":"https:\/\/www.rri.ro\/?p=963980"},"modified":"2025-12-18T21:39:12","modified_gmt":"2025-12-18T19:39:12","slug":"18-12-2025-aggiornamento","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html","title":{"rendered":"18.12.2025 (aggiornamento)"},"content":{"rendered":"<p>Consiglio Europeo \u2013 Il presidente romeno, Nicu\u0219or Dan, partecipa al Consiglio Europeo di Bruxelles. I capi di stato e di governo dei Paesi membri esaminano la situazione in Ucraina, con particolare attenzione alle garanzie di sicurezza per Kiev e alle azioni diplomatiche destinate al raggiungimento di una pace giusta e duratura. Viene inoltre discusso il tema dell&#8217;utilizzo degli asset russi per finanziare gli aiuti all&#8217;Ucraina, una questione che non \u00e8 sostenuta da tutti i leader europei. A Bruxelles, il presidente ucraino Volodymyr Zelensky ha affermato che il suo Paese ha bisogno di una rapida decisione da parte dell&#8217;UE sull&#8217;utilizzo di questi beni per finanziare lo sforzo bellico e per coprire i bisogni della popolazione. Nel frattempo, i leader europei stanno discutendo di un prestito di 90 miliardi di euro per l&#8217;Ucraina. I negoziati sugli asset russi si annunciano di durata, dato che gran parte si trovano in Belgio, uno stato che finora non \u00e8 stato convinto e teme un contenzioso con la Russia. Zelensky ha tuttavia avvertito che, in assenza di una decisione, l&#8217;Ucraina rischia di rimanere senza soldi nei primi tre mesi del prossimo anno.<\/p>\n<p>&nbsp;<\/p>\n<p>Politica \u2013 Il presidente dell\u2019USR, Dominic Fritz, ha convocato domani il Comitato Politico del partito per votare le proposte di nomina alla guida dei Ministeri della Difesa e dell\u2019Economia. Il ministro dell\u2019Economia, Radu Miru\u0163\u0103, \u00e8 proposto per la carica di ministro della Difesa, ricoprendo anche quella di vicepremier. Secondo un comunicato dell\u2019USR, il senatore Irineu Dar\u0103u \u00e8 proposto per la guida del Ministero dell\u2019Economia.<\/p>\n<p>&nbsp;<\/p>\n<p>Proteste \u2013 La decisione di aumentare il salario minimo in Romania a partire dalla met\u00e0 del prossimo anno, presa ieri dalla coalizione di governo, provoca insoddisfazione sia per i sindacati che per i datori di lavoro. Mentre i rappresentanti dei lavoratori chiedono che l&#8217;aumento fino a 4.325 lei (circa 865 euro) venga applicato dal 1\u00b0 gennaio, voci dal mondo imprenditoriale sostengono che la misura non sia affatto appropriata nel 2026, a causa della situazione economica. Alcune migliaia di membri delle quattro principali confederazioni sindacali nazionali hanno protestato oggi a Bucarest chiedendo al capo dello stato, Nicu\u015for Dan, di mediare il conflitto con il governo. L&#8217;insoddisfazione non riguarda solo il livello del salario minimo, ma anche altre decisioni prese di recente o annunciate per l\u2019anno prossimo. Il segretario generale della Confederazione Sindacale Cartel Alfa, Mihai B\u0103rbulescu, ha affermato che le misure adottate dal premier Ilie Bolojan non sono riuscite a &#8220;far uscire il Paese dalla crisi n\u00e9 a migliorare la situazione finanziaria&#8221;. Ieri, la coalizione di governo ha inoltre stabilito una riduzione del 10% delle spese a livello dell\u2019amministrazione centrale, senza incidere sul livello degli stipendi base, la riduzione del 10% dell\u2019importo forfettario percepito da senatori e deputati, nonch\u00e9 il livello dei sussidi ricevuti dai partiti politici.<\/p>\n<p>&nbsp;<\/p>\n<p>Rivoluzione 1989 \u2013 A Timi\u015foara, la citt\u00e0 della Romania occidentale, dove scoppi\u00f2 la Rivoluzione anticomunista del dicembre 1989, continuano gli eventi commemorativi. Studenti di 17 scuole e licei \u00a0si sono recati in pellegrinaggio ai Monumenti della Rivoluzione, mentre in serata sono deposte candele sui gradini della Cattedrale Metropolitana. Ieri a Timi\u015foara \u00e8 stata giornata di lutto, in memoria degli eroi della Rivoluzione.<\/p>\n<p>&nbsp;<\/p>\n<p>Eurostat \u2013 La Romania continua ad avvicinarsi alla media dell\u2019Unione Europea in termini di consumi. Secondo i dati pubblicati da Eurostat, lo scorso anno, il consumo individuale effettivo, indicatore del benessere delle famiglie, ha raggiunto l\u201986% della media UE. A livello europeo, i valori pi\u00f9 elevati sono stati registrati a Lussemburgo, nei Paesi Bassi e in Germania, mentre i pi\u00f9 bassi in Lettonia, Ungheria e Bulgaria. I dati rilevano anche differenze significative per il PIL pro capite, espresso in parit\u00e0 di potere d\u2019acquisto. Il Lussemburgo ha registrato il livello pi\u00f9 elevato, superiore del 145% alla media UE, mentre la Bulgaria il pi\u00f9 basso, inferiore del 34%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Consiglio Europeo \u2013 Il presidente romeno, Nicu\u0219or Dan, partecipa al Consiglio Europeo di Bruxelles. I capi di stato e di governo dei Paesi membri esaminano la situazione in Ucraina, con particolare attenzione alle garanzie di sicurezza per Kiev e alle azioni diplomatiche destinate al raggiungimento di una pace giusta e duratura. Viene inoltre discusso il [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":723460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[98934],"tags":[],"coauthors":[116091],"class_list":["post-963980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-topnews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>18.12.2025 (aggiornamento) - Radio Romania Internazionale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"18.12.2025 (aggiornamento) - Radio Romania Internazionale\" \/>\n<meta property=\"og:description\" content=\"Consiglio Europeo \u2013 Il presidente romeno, Nicu\u0219or Dan, partecipa al Consiglio Europeo di Bruxelles. I capi di stato e di governo dei Paesi membri esaminano la situazione in Ucraina, con particolare attenzione alle garanzie di sicurezza per Kiev e alle azioni diplomatiche destinate al raggiungimento di una pace giusta e duratura. Viene inoltre discusso il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Romania Internazionale\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-18T17:21:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T19:39:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Newsroom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsroom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/18-12-2025-aggiornamento-id963980.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/18-12-2025-aggiornamento-id963980.html\"},\"author\":{\"name\":\"Newsroom\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"headline\":\"18.12.2025 (aggiornamento)\",\"datePublished\":\"2025-12-18T17:21:49+00:00\",\"dateModified\":\"2025-12-18T19:39:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/18-12-2025-aggiornamento-id963980.html\"},\"wordCount\":631,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/18-12-2025-aggiornamento-id963980.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"articleSection\":[\"Topnews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/18-12-2025-aggiornamento-id963980.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/18-12-2025-aggiornamento-id963980.html\",\"name\":\"18.12.2025 (aggiornamento) - Radio Romania Internazionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/18-12-2025-aggiornamento-id963980.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/18-12-2025-aggiornamento-id963980.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"datePublished\":\"2025-12-18T17:21:49+00:00\",\"dateModified\":\"2025-12-18T19:39:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/18-12-2025-aggiornamento-id963980.html#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/18-12-2025-aggiornamento-id963980.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/18-12-2025-aggiornamento-id963980.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/RRI-960x540-Topnews-2-NOU.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/18-12-2025-aggiornamento-id963980.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Topnews\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"18.12.2025 (aggiornamento)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Romania Internazionale\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\",\"name\":\"Newsroom\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/author\\\/newsroom\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"18.12.2025 (aggiornamento) - Radio Romania Internazionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html","og_locale":"it_IT","og_type":"article","og_title":"18.12.2025 (aggiornamento) - Radio Romania Internazionale","og_description":"Consiglio Europeo \u2013 Il presidente romeno, Nicu\u0219or Dan, partecipa al Consiglio Europeo di Bruxelles. I capi di stato e di governo dei Paesi membri esaminano la situazione in Ucraina, con particolare attenzione alle garanzie di sicurezza per Kiev e alle azioni diplomatiche destinate al raggiungimento di una pace giusta e duratura. Viene inoltre discusso il [&hellip;]","og_url":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html","og_site_name":"Radio Romania Internazionale","article_published_time":"2025-12-18T17:21:49+00:00","article_modified_time":"2025-12-18T19:39:12+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","type":"image\/jpeg"}],"author":"Newsroom","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Newsroom","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html"},"author":{"name":"Newsroom","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"headline":"18.12.2025 (aggiornamento)","datePublished":"2025-12-18T17:21:49+00:00","dateModified":"2025-12-18T19:39:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html"},"wordCount":631,"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","articleSection":["Topnews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html","url":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html","name":"18.12.2025 (aggiornamento) - Radio Romania Internazionale","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","datePublished":"2025-12-18T17:21:49+00:00","dateModified":"2025-12-18T19:39:12+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/03\/RRI-960x540-Topnews-2-NOU.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/18-12-2025-aggiornamento-id963980.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/www.rri.ro\/it"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.rri.ro\/it\/news"},{"@type":"ListItem","position":3,"name":"Topnews","item":"https:\/\/www.rri.ro\/it\/news\/topnews"},{"@type":"ListItem","position":4,"name":"18.12.2025 (aggiornamento)"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Romania Internazionale","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88","name":"Newsroom","url":"https:\/\/www.rri.ro\/it\/author\/newsroom"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/963980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/comments?post=963980"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/963980\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media\/723460"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media?parent=963980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/categories?post=963980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/tags?post=963980"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/coauthors?post=963980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}