{"id":965916,"date":"2025-12-25T17:22:46","date_gmt":"2025-12-25T15:22:46","guid":{"rendered":"https:\/\/www.rri.ro\/?p=965916"},"modified":"2025-12-25T17:22:46","modified_gmt":"2025-12-25T15:22:46","slug":"25-12-2025","status":"publish","type":"post","link":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html","title":{"rendered":"25.12.2025"},"content":{"rendered":"<p>Natale &#8211; I cristiani di tutto il mondo, compresa la Romania, a maggioranza ortodossa, hanno celebrato oggi il Natale, la festa della nascita di Ges\u00f9 Cristo, una delle pi\u00f9 grandi della cristianit\u00e0, scelta per questa data nel IV secolo. I credenti hanno partecipato alla liturgia e i bambini sono andati di casa in casa a cantare canti natalizi e annunciare la nascita di Ges\u00f9 Cristo. Oltre 2.000 anni fa, la Vergine Maria e il suo promesso sposo, Giuseppe, si recarono da Nazareth a Betlemme per registrarsi per il censimento ordinato dall&#8217;imperatore romano Augusto. Maria era rimasta incinta dopo l&#8217;apparizione miracolosa dell&#8217;angelo Gabriele, che le aveva annunciato che avrebbe dato alla luce il Messia. A Betlemme, i due alloggiarono in una grotta usata come rifugio per gli animali e l\u00ec Maria diede alla luce il Redentore Ges\u00f9 Cristo. Tre Re Magi giunsero dall&#8217;Oriente, guidati da una stella, al luogo della nascita di Cristo e portarono doni al bambino, riconoscendo che era nato un re. Il Patriarca Daniele della Chiesa Ortodossa Romena ha celebrato la Santa Liturgia della Nativit\u00e0 del Signore presso la Cattedrale Patriarcale di Bucarest. Il Patriarca ha parlato di fede, buone azioni e vita pura, doni preziosi che i cristiani possono offrire a Cristo, simili ai doni che Egli ha ricevuto dai tre Magi d&#8217;Oriente. Nel suo tradizionale messaggio natalizio, Urbi et Orbi, in Vaticano, Papa Leone XIV ha lamentato la situazione dei senzatetto in tutto il mondo e le distruzioni causate dalle guerre in generale.<\/p>\n<p>Messaggio del Presidente \u2013 Il Presidente della Romania, Nicu\u015for Dan, ha trasmesso un messaggio di Natale, affermando che questa festa &#8220;ci ricorda la casa, la magia dell&#8217;infanzia e ci avvicina all&#8217;essenza dei valori che danno senso alla nostra vita&#8221;. Il capo dello Stato ha sottolineato che &#8220;i momenti trascorsi in famiglia e la gioia di avere vicino i propri cari sono i doni pi\u00f9 preziosi, che, nel tumulto della vita quotidiana, a volte rischiamo di non apprezzare quanto dovremmo&#8221;. Il presidente ha trasmesso ai romeni &#8220;Un Natale benedetto!&#8221;. &#8220;In questi giorni speciali, troviamo la nostra serenit\u00e0, la forza di essere migliori, pi\u00f9 saggi e pi\u00f9 comprensivi, affinch\u00e9, insieme, possiamo ritrovare la forza di una nazione consapevole della propria identit\u00e0 e determinata a costruire con fiducia il proprio futuro. Auguro a tutti voi un Buon Natale!&#8221;, ha concluso il Presidente.<\/p>\n<p>Vigilanza &#8211;\u00a0 Durante le mini-vacanze natalizie, 23.000 agenti di polizia, gendarmi, vigili del fuoco, soccorritori SMURD e guardie di frontiera saranno presenti nelle aree affollate e in prossimit\u00e0 dei luoghi di culto per mantenere l&#8217;ordine pubblico e intervenire rapidamente in situazioni di emergenza. Si prevede che quasi un milione di persone parteciper\u00e0 ai circa 10.000 eventi pubblici previsti nei prossimi giorni, ha dichiarato la portavoce del Ministero degli Interni, Monica Dajbog. Ogni giorno, una media di 2.000 agenti della polizia stradale sar\u00e0 presente sulle strade solitamente affollate in questi periodi, per snellire il traffico e fornire supporto agli automobilisti. Opereranno con circa 400 dispositivi radar per individuare i conducenti che rappresentano un pericolo per i partecipanti al traffico. Dajbog ha affermato che gli agenti di polizia continueranno le loro azioni in questi giorni per prevenire e contrastare il commercio illegale di articoli pirotecnici pericolosi. A supporto dei cittadini che trascorrono la loro mini-vacanza in montagna, circa 170 gendarmi di montagna saranno pronti a intervenire quotidianamente. Inoltre, durante le mini-vacanze natalizie, circa 3.300 agenti della polizia di frontiera saranno mobilitati per proteggere i confini, prevenire la criminalit\u00e0 transfrontaliera e garantire un controllo costante alla frontiera esterna.<\/p>\n<p>Rivoluzione &#8211; Il 25 dicembre rimane, nella storia recente della Romania, il giorno in cui, 36 anni fa, la coppia dittatoriale Nicolae ed Elena Ceau\u015fescu fu giustiziata in una caserma nella citt\u00e0 di Targovi\u015fte (sud). Dopo un processo sommario, i due furono trovati colpevoli di genocidio e di attentato all&#8217;economia nazionale. La Romania fu l&#8217;unico Paese dell&#8217;Europa orientale in cui il rovesciamento del regime comunista avvenne con versamento di sangue, scatenato con lo scoppio della Rivoluzione, il 16 dicembre 1989, a Timi\u0219oara (ovest) e proseguito a Bucarest dal 21 dicembre, ma anche in altre citt\u00e0 del Paese. Le violenze provocarono la morte di oltre mille persone, vittime dei cosiddetti terroristi, molti dei quali rimasero impuniti, perch\u00e9 la loro identit\u00e0 non fu mai accertata.<\/p>\n<p>Memorandum tutela dei testimoni &#8211; L&#8217;Ispettorato Generale di Polizia della Romania e l&#8217;Ispettorato Generale di Polizia della Repubblica di Moldova (ex sovietica, a maggioranza romenofona) hanno firmato a Chi\u015finau un Memorandum sul rafforzamento della cooperazione istituzionale nel campo della protezione dei testimoni. Il Memorandum riflette l&#8217;impegno congiunto delle due istituzioni a sviluppare e rafforzare i meccanismi di protezione dei testimoni, in conformit\u00e0 agli standard e alle buone pratiche internazionali, al fine di contrastare efficacemente la criminalit\u00e0 organizzata. In tale contesto, le parti hanno sottolineato la necessit\u00e0 di un continuo adattamento delle politiche e delle strategie di protezione dei testimoni all&#8217;evoluzione del contesto delinquenziale, nonch\u00e9 l&#8217;importanza dell&#8217;allineamento della Repubblica di Moldova agli standard europei in questo settore.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Natale &#8211; I cristiani di tutto il mondo, compresa la Romania, a maggioranza ortodossa, hanno celebrato oggi il Natale, la festa della nascita di Ges\u00f9 Cristo, una delle pi\u00f9 grandi della cristianit\u00e0, scelta per questa data nel IV secolo. I credenti hanno partecipato alla liturgia e i bambini sono andati di casa in casa a [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":745145,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[98934],"tags":[],"coauthors":[116091],"class_list":["post-965916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-topnews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>25.12.2025 - Radio Romania Internazionale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"25.12.2025 - Radio Romania Internazionale\" \/>\n<meta property=\"og:description\" content=\"Natale &#8211; I cristiani di tutto il mondo, compresa la Romania, a maggioranza ortodossa, hanno celebrato oggi il Natale, la festa della nascita di Ges\u00f9 Cristo, una delle pi\u00f9 grandi della cristianit\u00e0, scelta per questa data nel IV secolo. I credenti hanno partecipato alla liturgia e i bambini sono andati di casa in casa a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html\" \/>\n<meta property=\"og:site_name\" content=\"Radio Romania Internazionale\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-25T15:22:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1269\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Newsroom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Newsroom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-12-2025-id965916.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-12-2025-id965916.html\"},\"author\":{\"name\":\"Newsroom\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"headline\":\"25.12.2025\",\"datePublished\":\"2025-12-25T15:22:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-12-2025-id965916.html\"},\"wordCount\":829,\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-12-2025-id965916.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stiri-italiana-bleu-site-1269.jpg\",\"articleSection\":[\"Topnews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-12-2025-id965916.html\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-12-2025-id965916.html\",\"name\":\"25.12.2025 - Radio Romania Internazionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-12-2025-id965916.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-12-2025-id965916.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stiri-italiana-bleu-site-1269.jpg\",\"datePublished\":\"2025-12-25T15:22:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-12-2025-id965916.html#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-12-2025-id965916.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-12-2025-id965916.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stiri-italiana-bleu-site-1269.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rri.ro\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/stiri-italiana-bleu-site-1269.jpg\",\"width\":1269,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\\\/25-12-2025-id965916.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Topnews\",\"item\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/news\\\/topnews\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"25.12.2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/\",\"name\":\"Radio Romania Internazionale\",\"description\":\"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\\\/dialecte!\",\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rri.ro\\\/#\\\/schema\\\/person\\\/4a479940371b9fdefd194f561e8a7f88\",\"name\":\"Newsroom\",\"url\":\"https:\\\/\\\/www.rri.ro\\\/it\\\/author\\\/newsroom\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"25.12.2025 - Radio Romania Internazionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html","og_locale":"it_IT","og_type":"article","og_title":"25.12.2025 - Radio Romania Internazionale","og_description":"Natale &#8211; I cristiani di tutto il mondo, compresa la Romania, a maggioranza ortodossa, hanno celebrato oggi il Natale, la festa della nascita di Ges\u00f9 Cristo, una delle pi\u00f9 grandi della cristianit\u00e0, scelta per questa data nel IV secolo. I credenti hanno partecipato alla liturgia e i bambini sono andati di casa in casa a [&hellip;]","og_url":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html","og_site_name":"Radio Romania Internazionale","article_published_time":"2025-12-25T15:22:46+00:00","og_image":[{"width":1269,"height":720,"url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","type":"image\/jpeg"}],"author":"Newsroom","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Newsroom","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html#article","isPartOf":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html"},"author":{"name":"Newsroom","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"headline":"25.12.2025","datePublished":"2025-12-25T15:22:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html"},"wordCount":829,"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","articleSection":["Topnews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html","url":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html","name":"25.12.2025 - Radio Romania Internazionale","isPartOf":{"@id":"https:\/\/www.rri.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html#primaryimage"},"image":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","datePublished":"2025-12-25T15:22:46+00:00","author":{"@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88"},"breadcrumb":{"@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html#primaryimage","url":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","contentUrl":"https:\/\/www.rri.ro\/wp-content\/uploads\/2024\/04\/stiri-italiana-bleu-site-1269.jpg","width":1269,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.rri.ro\/it\/news\/topnews\/25-12-2025-id965916.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/www.rri.ro\/it"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.rri.ro\/it\/news"},{"@type":"ListItem","position":3,"name":"Topnews","item":"https:\/\/www.rri.ro\/it\/news\/topnews"},{"@type":"ListItem","position":4,"name":"25.12.2025"}]},{"@type":"WebSite","@id":"https:\/\/www.rri.ro\/#website","url":"https:\/\/www.rri.ro\/","name":"Radio Romania Internazionale","description":"Totul despre Rom\u00e2nia \u015fi rom\u00e2ni, \u00een 13 limbi\/dialecte!","inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.rri.ro\/#\/schema\/person\/4a479940371b9fdefd194f561e8a7f88","name":"Newsroom","url":"https:\/\/www.rri.ro\/it\/author\/newsroom"}]}},"_links":{"self":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/965916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/comments?post=965916"}],"version-history":[{"count":0,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/posts\/965916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media\/745145"}],"wp:attachment":[{"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/media?parent=965916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/categories?post=965916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/tags?post=965916"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rri.ro\/it\/wp-json\/wp\/v2\/coauthors?post=965916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}